{"id":47026,"date":"2020-10-19T13:20:49","date_gmt":"2020-10-19T11:20:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=47026"},"modified":"2020-10-19T13:21:24","modified_gmt":"2020-10-19T11:21:24","slug":"nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/","title":{"rendered":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Coprifuoco alle 21, deciso dai sindaci<\/strong>, nelle zone della movida dove si verificano assembramenti, <strong>riunioni nella Pa solo a distanza<\/strong>, vietate le tavolate nei ristoranti e i convegni in presenza. Alle superiori forme flessibili nell\u2019organizzazione della didattica: incremento della didattica digitale, spinta ai turni pomeridiani e <strong>ingresso a partire dalle 9<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Palestre sotto la lente<\/strong>: resteranno aperte solo se si adegueranno in una settimana ai protocolli di sicurezza anti-Covid. <strong>No a sagre e fiere di paese<\/strong>, s\u00ec solo a manifestazioni fieristiche a carattere nazionale o internazionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sono alcune delle novit\u00e0 introdotte dal nuovo dpcm approvato nella serata del 18 ottobre dopo un lungo dibattito e un braccio di ferro su palestre e scuole.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ieri sera la conferenza stampa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Alle 21.30 di ieri sera il presidente del Consiglio Giuseppe Conte ha tenuto una conferenza stampa nel corso della quale ha illustrato le nuove misure che saranno in vigore da oggi e fino al prossimo 21 novembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ecco nel dettaglio cosa \u00e8 consentito fare e cosa no:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"423\" height=\"552\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm1.jpg\" alt=\"Schermata Dpcm 18 ottobre\" class=\"wp-image-47028\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm1.jpg 423w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm1-230x300.jpg 230w\" sizes=\"auto, (max-width: 423px) 100vw, 423px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"439\" height=\"581\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm-2.jpg\" alt=\"Schermata Dpcm 18 ottobre\" class=\"wp-image-47027\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm-2.jpg 439w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Schermata-Dpcm-2-227x300.jpg 227w\" sizes=\"auto, (max-width: 439px) 100vw, 439px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ecco le nuove misure anti-contagio contenute nel nuovo Dpcm che il presidente Conte ha illustrato ieri sera in conferenza stampa<\/p>\n","protected":false},"author":18,"featured_media":47029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[94,4149,2877,8896,8916,365,8891,93,2039,5100,82],"class_list":["post-47026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-ciociaria","tag-conferenza-stampa","tag-consiglio-dei-ministri","tag-contagi","tag-covid","tag-decreto","tag-dpcm","tag-frosinone","tag-giuseppe-conte","tag-misure","tag-presidente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo\" \/>\n<meta property=\"og:description\" content=\"Ecco le nuove misure anti-contagio contenute nel nuovo Dpcm che il presidente Conte ha illustrato ieri sera in conferenza stampa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-19T11:20:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-19T11:21:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png\" \/>\n\t<meta property=\"og:image:width\" content=\"685\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo\",\"datePublished\":\"2020-10-19T11:20:49+00:00\",\"dateModified\":\"2020-10-19T11:21:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/\"},\"wordCount\":170,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/Conte-tv.png\",\"keywords\":[\"Ciociaria\",\"conferenza stampa\",\"consiglio dei ministri\",\"contagi\",\"covid\",\"decreto\",\"dpcm\",\"Frosinone\",\"giuseppe conte\",\"misure\",\"presidente\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/\",\"name\":\"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/Conte-tv.png\",\"datePublished\":\"2020-10-19T11:20:49+00:00\",\"dateModified\":\"2020-10-19T11:21:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/Conte-tv.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/Conte-tv.png\",\"width\":685,\"height\":399,\"caption\":\"Il presidente del Consiglio Conte durante la conferenza stampa del 18 ottobre scorso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/10\\\/19\\\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo","og_description":"Ecco le nuove misure anti-contagio contenute nel nuovo Dpcm che il presidente Conte ha illustrato ieri sera in conferenza stampa","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-10-19T11:20:49+00:00","article_modified_time":"2020-10-19T11:21:24+00:00","og_image":[{"width":685,"height":399,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo","datePublished":"2020-10-19T11:20:49+00:00","dateModified":"2020-10-19T11:21:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/"},"wordCount":170,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png","keywords":["Ciociaria","conferenza stampa","consiglio dei ministri","contagi","covid","decreto","dpcm","Frosinone","giuseppe conte","misure","presidente"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/","name":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png","datePublished":"2020-10-19T11:20:49+00:00","dateModified":"2020-10-19T11:21:24+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/10\/Conte-tv.png","width":685,"height":399,"caption":"Il presidente del Consiglio Conte durante la conferenza stampa del 18 ottobre scorso"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Nuovo Dpcm anti-contagio: ecco le ultime misure varate dal Governo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/10\/19\/nuovo-dpcm-anti-contagio-ecco-tutte-le-misure-varate-dal-governo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=47026"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47026\/revisions"}],"predecessor-version":[{"id":47031,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/47026\/revisions\/47031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/47029"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=47026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=47026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=47026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}