{"id":46399,"date":"2020-09-29T11:38:15","date_gmt":"2020-09-29T09:38:15","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=46399"},"modified":"2020-09-29T11:38:22","modified_gmt":"2020-09-29T09:38:22","slug":"scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/","title":{"rendered":"Scuola: la Provincia consegna 300 banchi al Convitto &#8216;Regina Margherita&#8217; di Anagni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Provincia di Frosinone continua nell&#8217;azione di sostegno e monitoraggio alle scuole del territorio, in un momento particolarmente complesso a causa dell&#8217;emergenza Covid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Questa mattina<\/strong>, infatti, <strong>\u00e8 stata consegnata al Convitto &#8216;Regina Margherita&#8217;<\/strong> di Anagni la <strong>prima tranche della fornitura di 300 banchi monoposto<\/strong> che sono stati dislocati nelle varie aule della struttura scolastica.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"776\" height=\"746\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-1.jpg\" alt=\"banchi convitto anagni\" class=\"wp-image-46400\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-1.jpg 776w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-1-300x288.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-1-768x738.jpg 768w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un intervento fondamentale, quello della Provincia di Frosinone guidata dal presidente Antonio Pompeo, che <strong>permette all&#8217;istituto di accelerare i tempi di ripresa dell&#8217;attivit\u00e0 didattica<\/strong> che, altrimenti, avrebbe subito ulteriori rallentamenti a causa dei ritardi nella consegna dei banchi da parte del Miur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il rettore del Convitto, prof. Fabio Magliocchetti<\/strong>, ha ringraziato l&#8217;Ente di piazza Gramsci e lo stesso presidente Pompeo ha voluto sottolineare la costante attenzione da parte della Provincia verso le realt\u00e0 scolastiche del territorio che, oggi pi\u00f9 che mai, hanno continuo bisogno di sostegno e controllo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"548\" height=\"632\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-3.jpg\" alt=\"banchi convitto anagni\" class=\"wp-image-46402\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-3.jpg 548w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-3-260x300.jpg 260w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pompeo e Sardellitti: per noi la sicurezza scolastica \u00e8 sempre al primo posto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La sicurezza scolastica \u2013 hanno commentato <strong>Pompeo e la consigliera provinciale delegata alla Pubblica Istruzione e Formazione, Alessandra Sardellitti<\/strong> \u2013 \u00e8 sempre stata al centro della nostra agenda amministrativa e lo \u00e8 ancora di pi\u00f9 oggi, con tutte le difficolt\u00e0 e le incertezze causate dalla pandemia&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"701\" height=\"531\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Pompeo-Sardellitti.jpg\" alt=\"pompeo sardellitti\" class=\"wp-image-46403\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Pompeo-Sardellitti.jpg 701w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Pompeo-Sardellitti-300x227.jpg 300w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><figcaption>Il presidente Pompeo e la consigliera provinciale Sardellitti<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La Provincia di Frosinone continua con straordinario impegno e continua responsabilit\u00e0 a vigilare sulla sicurezza degli studenti, dei docenti e di tutto il personale impiegato all&#8217;interno delle strutture scolastiche per garantire le migliori condizioni e la tranquillit\u00e0 necessaria al proseguimento dell&#8217;attivit\u00e0 didattica in presenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia di Frosinone ha consegnato la prima tranche dei 300 banchi monoposto al convitto Regina Margherita di Anagni<\/p>\n","protected":false},"author":18,"featured_media":46401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,38],"tags":[4290,441,842,11432,10271,11433,93,11431,367],"class_list":["post-46399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-scuola","tag-alessandra-sardellitti","tag-anagni","tag-antonio-pompeo","tag-banchi-monoposto","tag-convitto","tag-fabio-magliocchetti","tag-frosinone","tag-regina-margherita","tag-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scuola: la Provincia consegna 300 banchi al Convitto &#039;Regina Margherita&#039; di Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scuola: la Provincia consegna 300 banchi al Convitto &#039;Regina Margherita&#039; di Anagni\" \/>\n<meta property=\"og:description\" content=\"La Provincia di Frosinone ha consegnato la prima tranche dei 300 banchi monoposto al convitto Regina Margherita di Anagni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-29T09:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-29T09:38:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"863\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Scuola: la Provincia consegna 300 banchi al Convitto &#8216;Regina Margherita&#8217; di Anagni\",\"datePublished\":\"2020-09-29T09:38:15+00:00\",\"dateModified\":\"2020-09-29T09:38:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/\"},\"wordCount\":264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Banchi-Convitto-Anagni-2.jpg\",\"keywords\":[\"alessandra sardellitti\",\"anagni\",\"antonio pompeo\",\"banchi monoposto\",\"convitto\",\"fabio magliocchetti\",\"Frosinone\",\"regina margherita\",\"scuola\"],\"articleSection\":[\"*SLIDE*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/\",\"name\":\"Scuola: la Provincia consegna 300 banchi al Convitto 'Regina Margherita' di Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Banchi-Convitto-Anagni-2.jpg\",\"datePublished\":\"2020-09-29T09:38:15+00:00\",\"dateModified\":\"2020-09-29T09:38:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Banchi-Convitto-Anagni-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Banchi-Convitto-Anagni-2.jpg\",\"width\":863,\"height\":616,\"caption\":\"Banchi convitto Anagni consegnati il 29 settembre 2020 dalla Provincia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scuola: la Provincia consegna 300 banchi al Convitto &#8216;Regina Margherita&#8217; di Anagni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/29\\\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scuola: la Provincia consegna 300 banchi al Convitto 'Regina Margherita' di Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/","og_locale":"it_IT","og_type":"article","og_title":"Scuola: la Provincia consegna 300 banchi al Convitto 'Regina Margherita' di Anagni","og_description":"La Provincia di Frosinone ha consegnato la prima tranche dei 300 banchi monoposto al convitto Regina Margherita di Anagni","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-09-29T09:38:15+00:00","article_modified_time":"2020-09-29T09:38:22+00:00","og_image":[{"width":863,"height":616,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Scuola: la Provincia consegna 300 banchi al Convitto &#8216;Regina Margherita&#8217; di Anagni","datePublished":"2020-09-29T09:38:15+00:00","dateModified":"2020-09-29T09:38:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/"},"wordCount":264,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg","keywords":["alessandra sardellitti","anagni","antonio pompeo","banchi monoposto","convitto","fabio magliocchetti","Frosinone","regina margherita","scuola"],"articleSection":["*SLIDE*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/","name":"Scuola: la Provincia consegna 300 banchi al Convitto 'Regina Margherita' di Anagni - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg","datePublished":"2020-09-29T09:38:15+00:00","dateModified":"2020-09-29T09:38:22+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Banchi-Convitto-Anagni-2.jpg","width":863,"height":616,"caption":"Banchi convitto Anagni consegnati il 29 settembre 2020 dalla Provincia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Scuola: la Provincia consegna 300 banchi al Convitto &#8216;Regina Margherita&#8217; di Anagni"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/29\/scuola-la-provincia-consegna-300-banchi-al-convitto-regina-margherita-di-anagni\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=46399"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46399\/revisions"}],"predecessor-version":[{"id":46404,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46399\/revisions\/46404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/46401"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=46399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=46399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=46399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}