{"id":46336,"date":"2020-09-28T18:16:23","date_gmt":"2020-09-28T16:16:23","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=46336"},"modified":"2020-09-29T07:43:05","modified_gmt":"2020-09-29T05:43:05","slug":"ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/","title":{"rendered":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Accolto con una grande partecipazione il nuovo sportello Ebit di Frosinone, importante opportunit\u00e0 per il mondo delle imprese e per i lavoratori<\/strong>. L&#8217;Ente Bilaterale del Terziario, in 18 anni di attivit\u00e0 ha raccolto oltre 6mila aziende iscritte, erogato oltre 12 milioni di euro in progetti formativi, proposto 7mila corsi e formato 30mila lavoratori.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"479\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/consegna-ebit.jpg\" alt=\"\" class=\"wp-image-46378\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/consegna-ebit.jpg 717w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/consegna-ebit-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/consegna-ebit-272x182.jpg 272w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una presentazione ufficiale quella odierna a Frosinone che si \u00e8 tenuta stamattina nella sede della Confcommercio del capoluogo<\/strong>. Tutti riuniti, dalle istituzioni alle imprese &#8211; nel rispetto delle normative per evitare la diffusione del Coronavirus &#8211; per parlare della nuova offerta rivolta alle imprese del territorio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fare gli onori di casa il Presidente di Confcommercio Lazio e Consigliere nazionale dott. Giovanni Acampora, il vice Presidente di Confcommercio Lazio Sud Fabio Loreto e il direttore generale di Confcommercio Lazio e Lazio sud dott. Salvatore di Cecca che ha moderato gli interventi.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A<strong> prendere la parola, per illustrare i numerosi servizi dedicati alle aziende e ai lavoratori del settore commercio e terziario, il dott. Guido Lazzarelli presidente dell\u2019EBiT Lazio<\/strong> seguito dall\u2019intervento del vicepresidente Silvana Morini. A seguire, la parola \u00e8 passata a Giovanni Gioia, segretario generale Filcams Cgil Frosinone e Latina in rappresentanza delle categorie CGIL, CISL e UIL.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"567\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/sardellitti-ebit.jpg\" alt=\"\" class=\"wp-image-46380\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/sardellitti-ebit.jpg 1008w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/sardellitti-ebit-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/sardellitti-ebit-768x432.jpg 768w\" sizes=\"auto, (max-width: 1008px) 100vw, 1008px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Apprezzatissimi gli interventi del Sindaco di Frosinone Nicola Ottaviani e della consigliera comunale provinciale Alessandra Sardellitti, in rappresentanza del Presidente della Provincia di Frosinone<\/strong>. Nel corso dell\u2019evento \u00e8 stato altres\u00ec donato un defibrillatore alla Citt\u00e0 di Frosinone, con relativi corsi di formazione per gli utilizzatori.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole di Acampora<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Le imprese stanno soffrendo e si trovano in grande difficolt\u00e0 &#8211; ha affermato Acampora<\/strong>&#8211; Questo \u00e8 un momento in cui occorre partecipazione e condivisione.<strong> L&#8217;inaugurazione dello sportello  Ebit \u00e8 l&#8217;esempio virtuso di cosa significhi fare squadra&#8221;<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un passaggio lo ha quindi riservato alla nuova Camera di Commercio Frosinone\/Latina. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Colgo l&#8217;occasione per dire &#8211; ha fatto notare &#8211; che per quanto riguarda la presidenza del nuovo ente unico territoriale,<strong> non sono ancora a conoscenza delle candidature da parte delle associazioni. Tutto ci\u00f2 \u00e8 abbastanza grave,<\/strong> anche perch\u00e9 siamo arrivati al termine di quelle che dovrebbero essere le consultazioni. Vorrei ricordare che la Camera di Commercio unificata, come \u00e8 stato evidenziato nel corso di questo incontro da autorevoli relatori, \u00e8 proprio l&#8217;insieme delle associazioni&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Rimango, quindi, esterrefatto  &#8211; ha continuato &#8211; che a pochi giorni dalla nascita del nuovo ente, <\/strong>che sar\u00e0 un propulsore eccezionale per due territori,  autorevoli associazioni ancora non scendono in campo per cercare una soluzione condivisa e un progetto comune.  <strong>Ci tengo anche a dire che non credo nelle candidature sporadiche, perch\u00e9 quel che serve sono nomi autorevoli che posssano ben rappresentare le due province.<\/strong> Il processo di accorpamento  &#8211; ha concluso &#8211; \u00e8 stato lungo e faticoso e l&#8217;occasione non va persa. Non serve l&#8217;autoreferenzialit\u00e0 o la rincorsa alle poltrone<strong> e noi di Confcommercio siamo pronti al dialogo con tutti&#8221;. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I presenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La presentazione \u00e8 avvenuta alla presenza <\/strong>del Segretario Generale  FISASCAT CISL Frosinone Romano Pasqualitto, del Segretario Generale  Uiltucs Latina Gianfranco Cartisano, del segretario generale UILTUCS  Frosinone Luigi Canali, dei dirigenti provinciali di Confcommercio Lazio  Sud (il Presidente Confcommercio Frosinone Gianmarco Gallo, il  Presidente di Confcommercio Cassino Bruno Vacca, il Presidente di  Confcommercio Sant\u2019Elia Fiumerapido Paride Gargano, il Presidente di  Confcommercio Fiuggi Maria Vittoria Necci, il Presidente Fit Frosinone  Luigi Girolamo, il responsabile del credito avv.Ernesto Schiano) e le  imprese \u201cHygenia\u201d, \u201cRomana Diesel\u201d e \u201cT&amp;M Logistica Integrata\u201d, che  hanno fornito le loro testimonianze dirette.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P<strong>resso la sede di Confcommercio Imprese per l\u2019Italia Lazio Sud,  in via Lago di Como 50\/54 sar\u00e0 dunque attivo lo sportello \u2018Ebit Lazio\u2019.<\/strong> L\u2019Ente Bilaterale del terziario del Lazio al servizio delle imprese e dei lavoratori, nasce dalla collaborazione tra Confcommercio Lazio Sud e le Organizzazioni Sindacali dei lavoratori Filcams-Cgil Latina-Frosinone, Fisascat-Cisl Frosinone e Uiltucs-Uil Frosinone, assicura uno strumento condiviso e ha come obiettivo quello di favorire una serie di servizi (formazione gratuita, apprendistato, salute e sicurezza, conciliazione e arbitrato, videosorveglianza, osservazione e ricerche, welfare territoriale) alle imprese e la crescita professionale agli addetti del settore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In particolare giova evidenziare, per quanto attiene alle politiche di welfare, un bonus economico per l\u2019emergenza covid-19 <\/strong>per lavoratori e aziende (per le modalit\u00e0 di fruizione del bonus si invita a consultare il sito internet \u201cebitlazio.it\u201d).<\/p>\n\n\n<p><!--EndFragment--><\/p>","protected":false},"excerpt":{"rendered":"<p>Accolto con una grande partecipazione il nuovo sportello Ebit di Frosinone, importante opportunit\u00e0 per il mondo delle imprese e per<\/p>\n","protected":false},"author":18,"featured_media":46337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,5],"tags":[4290,94,9436,11421,8826,3067,639,11422],"class_list":["post-46336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-economia","tag-alessandra-sardellitti","tag-ciociaria","tag-confocommercio","tag-ebit-lazio","tag-giovanni-acampora","tag-la-provincia-quotidiano","tag-nicola-ottaviani","tag-salvatore-di-cecca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori\" \/>\n<meta property=\"og:description\" content=\"Accolto con una grande partecipazione il nuovo sportello Ebit di Frosinone, importante opportunit\u00e0 per il mondo delle imprese e per\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T16:16:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-29T05:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori\",\"datePublished\":\"2020-09-28T16:16:23+00:00\",\"dateModified\":\"2020-09-29T05:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/\"},\"wordCount\":724,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/ebit-lazio.jpg\",\"keywords\":[\"alessandra sardellitti\",\"Ciociaria\",\"confocommercio\",\"Ebit Lazio\",\"giovanni acampora\",\"La provincia quotidiano\",\"nicola ottaviani\",\"salvatore di cecca\"],\"articleSection\":[\"*SLIDE*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/\",\"name\":\"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/ebit-lazio.jpg\",\"datePublished\":\"2020-09-28T16:16:23+00:00\",\"dateModified\":\"2020-09-29T05:43:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/ebit-lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/ebit-lazio.jpg\",\"width\":1008,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/28\\\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/","og_locale":"it_IT","og_type":"article","og_title":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori","og_description":"Accolto con una grande partecipazione il nuovo sportello Ebit di Frosinone, importante opportunit\u00e0 per il mondo delle imprese e per","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-09-28T16:16:23+00:00","article_modified_time":"2020-09-29T05:43:05+00:00","og_image":[{"width":1008,"height":567,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori","datePublished":"2020-09-28T16:16:23+00:00","dateModified":"2020-09-29T05:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/"},"wordCount":724,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg","keywords":["alessandra sardellitti","Ciociaria","confocommercio","Ebit Lazio","giovanni acampora","La provincia quotidiano","nicola ottaviani","salvatore di cecca"],"articleSection":["*SLIDE*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/","name":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg","datePublished":"2020-09-28T16:16:23+00:00","dateModified":"2020-09-29T05:43:05+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/ebit-lazio.jpg","width":1008,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ebit Lazio, presentato nella sede Frusinate della Confcommercio lo sportello al servizio di imprese e lavoratori"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/28\/ebit-lazio-presentato-nella-sede-frusinate-della-confcommercio-lo-sportello-al-servizio-di-imprese-e-lavoratori\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=46336"}],"version-history":[{"count":19,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46336\/revisions"}],"predecessor-version":[{"id":46395,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/46336\/revisions\/46395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/46337"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=46336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=46336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=46336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}