{"id":45603,"date":"2020-09-19T00:01:00","date_gmt":"2020-09-18T22:01:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=45603"},"modified":"2020-09-18T22:57:31","modified_gmt":"2020-09-18T20:57:31","slug":"come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/","title":{"rendered":"&#8220;Come godo che avete tolto di mezzo quello scimpanz\u00e8&#8221;: identificato e denunciato l&#8217;autore del post contro Willy"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pensava di farla franca nascondendosi dietro un profilo fake, <strong>il ragazzo di 23 anni, residente a Treviso <\/strong>che, subito dopo la morte del giovane Willy Monteiro Duarte, deceduto a Colleferro a seguito di percosse, aveva esultato sui social con frasi che avevano sconcertato l\u2019opinione pubblica tanto da provocare molteplici segnalazioni di protesta da parte di cittadini indignati.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Studente esperto di informatica: ecco chi \u00e8 <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Studente universitario, esperto di informatica,<\/strong> aveva postato il suo odio e la sua intolleranza razziale arrivando a definire \u201ceroi\u201d gli assassini per \u201caver ucciso una persona di colore\u201d definendolo\u201cscimpanz\u00e9\u201d.  <strong>Oltre ad aver creato un personaggio virtuale, cui aveva dato il nome di Manlio Germano<\/strong>, il sottosegretario interpretato da Claudio Amendola nel film &#8216;Caterina va in citt\u00e0&#8217; del regista Virz\u00ec, <strong>il giovane si connetteva ai social network attraverso provider esteri<\/strong>, addirittura utilizzando tecniche di anonimizzazione in grado di mascherare le tracce informatiche della navigazione, convinto che sarebbe stato impossibile rintracciarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"493\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/willy-monteiro-1.jpg\" alt=\"willy monteiro\" class=\"wp-image-44554\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/willy-monteiro-1.jpg 684w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/willy-monteiro-1-300x216.jpg 300w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><figcaption>Il giovane Willy Monteiro ucciso nella notte tra il 5 e il 6 settembre scorso a Colleferro<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo un&#8217;attenta e meticolosa indagine, espletata attraverso le pi\u00f9 moderne tecniche di analisi informatica e di ricostruzione del traffico telematico, resa ulteriormente complessa dalle connessioni sui provider esteri, la Polizia Postale di Roma e Latina con la collaborazione dei colleghi specialisti di Firenze, \u00e8 riuscita comunque a risalire all\u2019autore dello spregevole post, a rintracciarlo presso un albergo del capoluogo toscano ed a deferirlo alla Procura della Repubblica presso il Tribunale di Latina che coordina le complesse indagini informatiche.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Identificato e denunciato dalla Polizia Postale il giovane che sotto falso nome ha postato terribili frasi sulla morte di Willy Monteiro Duarte<\/p>\n","protected":false},"author":18,"featured_media":45605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[94,1421,245,510,11328,2333,4809,2874,11220],"class_list":["post-45603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-ciociaria","tag-colleferro","tag-denuncia","tag-facebook","tag-manlio-germano","tag-polizia-postale","tag-post","tag-profilo","tag-willy-monteiro-duarte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Come godo che avete tolto di mezzo quello scimpanz\u00e8&quot;: identificato e denunciato l&#039;autore del post contro Willy - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Come godo che avete tolto di mezzo quello scimpanz\u00e8&quot;: identificato e denunciato l&#039;autore del post contro Willy\" \/>\n<meta property=\"og:description\" content=\"Identificato e denunciato dalla Polizia Postale il giovane che sotto falso nome ha postato terribili frasi sulla morte di Willy Monteiro Duarte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-18T22:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"&#8220;Come godo che avete tolto di mezzo quello scimpanz\u00e8&#8221;: identificato e denunciato l&#8217;autore del post contro Willy\",\"datePublished\":\"2020-09-18T22:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/manlio-germano.jpg\",\"keywords\":[\"Ciociaria\",\"colleferro\",\"denuncia\",\"facebook\",\"manlio germano\",\"polizia postale\",\"post\",\"profilo\",\"willy monteiro duarte\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/\",\"name\":\"\\\"Come godo che avete tolto di mezzo quello scimpanz\u00e8\\\": identificato e denunciato l'autore del post contro Willy - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/manlio-germano.jpg\",\"datePublished\":\"2020-09-18T22:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/manlio-germano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/manlio-germano.jpg\",\"width\":709,\"height\":484,\"caption\":\"Il profilo Facebook di Manlio Germano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Come godo che avete tolto di mezzo quello scimpanz\u00e8&#8221;: identificato e denunciato l&#8217;autore del post contro Willy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/19\\\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Come godo che avete tolto di mezzo quello scimpanz\u00e8\": identificato e denunciato l'autore del post contro Willy - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/","og_locale":"it_IT","og_type":"article","og_title":"\"Come godo che avete tolto di mezzo quello scimpanz\u00e8\": identificato e denunciato l'autore del post contro Willy","og_description":"Identificato e denunciato dalla Polizia Postale il giovane che sotto falso nome ha postato terribili frasi sulla morte di Willy Monteiro Duarte","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-09-18T22:01:00+00:00","og_image":[{"width":709,"height":484,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"&#8220;Come godo che avete tolto di mezzo quello scimpanz\u00e8&#8221;: identificato e denunciato l&#8217;autore del post contro Willy","datePublished":"2020-09-18T22:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg","keywords":["Ciociaria","colleferro","denuncia","facebook","manlio germano","polizia postale","post","profilo","willy monteiro duarte"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/","name":"\"Come godo che avete tolto di mezzo quello scimpanz\u00e8\": identificato e denunciato l'autore del post contro Willy - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg","datePublished":"2020-09-18T22:01:00+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/manlio-germano.jpg","width":709,"height":484,"caption":"Il profilo Facebook di Manlio Germano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"&#8220;Come godo che avete tolto di mezzo quello scimpanz\u00e8&#8221;: identificato e denunciato l&#8217;autore del post contro Willy"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/19\/come-godo-che-avete-tolto-di-mezzo-quello-scimpanze-identificato-e-denunciato-lautore-del-post-contro-willy\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/45603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=45603"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/45603\/revisions"}],"predecessor-version":[{"id":45606,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/45603\/revisions\/45606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/45605"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=45603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=45603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=45603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}