{"id":44903,"date":"2020-09-16T16:00:00","date_gmt":"2020-09-16T14:00:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=44903"},"modified":"2020-09-16T16:49:52","modified_gmt":"2020-09-16T14:49:52","slug":"anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/","title":{"rendered":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L\u2019Associazione Costruttori Edili di Frosinone<\/strong> (Ance) ha incontrato <strong>Anas<\/strong>, con l\u2019obiettivo di avviare un percorso con i diversi attori del mercato, ispirato a una logica di collaborazione e trasparenza, nell\u2019ambito del <strong>piano di investimenti previsto dal gestore delle strade<\/strong> volto a rilanciare lo sviluppo infrastrutturale e la manutenzione delle strutture esistenti della nostra provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si tratta di importanti investimenti che Anas sta destinando alla provincia di Frosinone<\/strong> e che rappresentano un significativo sbocco di mercato per le imprese edili, le quali da sempre contribuiscono in maniera importante al PIL provinciale ed all\u2019occupazione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento di Massaro <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Ringrazio Anas e in particolare il Responsabile Struttura Territoriale del Lazio l\u2019ingegner Marco Moladori \u2013 dichiara il<strong> presidente di Ance Frosinone, cavalier Angelo Libero Massaro<\/strong> &#8211; per questo percorso di dialogo e confronto basato sulla concretezza, la seriet\u00e0 e la trasparenza di chi come noi imprenditori \u00e8 abituato a fare, a costruire guardando al futuro&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole di Moladori<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Con il rientro di strade in gestione all\u2019Anas \u2013 ha detto invece <strong>Marco Moladori <\/strong>&#8211; l\u2019azienda torna ad essere presente ed operativa su arterie importanti ricadenti nella provincia di Frosinone, quali la SS 6 Casilina, la SS 156 dei Monti Lepini e la SS. 214 di Casamari. <strong>In un\u2019ottica di superamento della logica dell\u2019emergenza<\/strong>, in favore di una programmazione degli interventi manutentivi, Anas \u00e8 impegnata a garantire la concorrenza nel rispetto dei principi di trasparenza e rotazione degli incarichi&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"726\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Marco-Moladori.jpg\" alt=\"marco moladori\" class=\"wp-image-44905\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Marco-Moladori.jpg 726w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Marco-Moladori-300x300.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Marco-Moladori-150x150.jpg 150w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><figcaption>Marco Moladori di Anas<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ance Frosinone e Anas insieme per un percorso di collaborazione sul piano degli investimenti previsto dal gestore delle strade<\/p>\n","protected":false},"author":18,"featured_media":44904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1541,2601,94,11222,613,93,11223,564],"class_list":["post-44903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-anas","tag-angelo-libero-massaro","tag-ciociaria","tag-costruttori-edili","tag-finanziamenti","tag-frosinone","tag-marco-moladori","tag-strade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate\" \/>\n<meta property=\"og:description\" content=\"Ance Frosinone e Anas insieme per un percorso di collaborazione sul piano degli investimenti previsto dal gestore delle strade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-16T14:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"841\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate\",\"datePublished\":\"2020-09-16T14:00:00+00:00\",\"dateModified\":\"2020-09-16T14:49:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Libero-Massaro.jpg\",\"keywords\":[\"anas\",\"angelo libero massaro\",\"Ciociaria\",\"costruttori edili\",\"finanziamenti\",\"Frosinone\",\"marco moladori\",\"strade\"],\"articleSection\":[\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/\",\"name\":\"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Libero-Massaro.jpg\",\"datePublished\":\"2020-09-16T14:00:00+00:00\",\"dateModified\":\"2020-09-16T14:49:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Libero-Massaro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Libero-Massaro.jpg\",\"width\":841,\"height\":507,\"caption\":\"angelo libero massaro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/09\\\/16\\\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/","og_locale":"it_IT","og_type":"article","og_title":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate","og_description":"Ance Frosinone e Anas insieme per un percorso di collaborazione sul piano degli investimenti previsto dal gestore delle strade","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-09-16T14:00:00+00:00","article_modified_time":"2020-09-16T14:49:52+00:00","og_image":[{"width":841,"height":507,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate","datePublished":"2020-09-16T14:00:00+00:00","dateModified":"2020-09-16T14:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg","keywords":["anas","angelo libero massaro","Ciociaria","costruttori edili","finanziamenti","Frosinone","marco moladori","strade"],"articleSection":["Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/","name":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg","datePublished":"2020-09-16T14:00:00+00:00","dateModified":"2020-09-16T14:49:52+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Libero-Massaro.jpg","width":841,"height":507,"caption":"angelo libero massaro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Anas e Ance per lo sviluppo del territorio, stilato un accordo per importanti investimenti nel Frusinate"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/09\/16\/anas-e-ance-frosinone-per-lo-sviluppo-del-territorio-stilato-un-accordo-per-importanti-investimenti-nel-frusinate\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/44903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=44903"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/44903\/revisions"}],"predecessor-version":[{"id":45389,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/44903\/revisions\/45389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/44904"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=44903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=44903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=44903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}