{"id":43595,"date":"2020-08-27T08:41:00","date_gmt":"2020-08-27T06:41:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=43595"},"modified":"2020-08-27T08:56:57","modified_gmt":"2020-08-27T06:56:57","slug":"frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/","title":{"rendered":"Frosinone, ultimo appuntamento con Teatro musica e cabaret"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Venerd\u00ec 28 agosto si chiuder\u00e0&nbsp;\u201cTeatro musica e cabaret tra le porte\u201d in piazzale Vittorio Veneto.<\/strong> <strong>La manifestazione<\/strong>, che ha suscitato una numerosa partecipazione da parte del pubblico frusinate e non, nel rispetto delle prescrizioni sanitarie vigenti, \u00e8 stata ideata dall\u2019amministrazione Ottaviani&nbsp;mediante gli assessorati al centro storico e alla cultura, coordinati rispettivamente da Rossella Testa e Valentina Sementilli, con il consigliere delegato ai grandi eventi Gianpiero Fabrizi. \u201cTeatro musica e cabaret tra le porte\u201d<strong> \u00e8 stata realizzata in collaborazione con Atcl, con il prezioso contributo della Banca Popolare dei Frusinate.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La trama<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Venerd\u00ec alle 21.30, con ingresso rigorosamente\ngratuito, sar\u00e0 di scena una gustosa anteprima: \u201cLa stranissima coppia\u201d, scritta\ne diretta da Diego Ruiz; con Patrizia Pellegrino e Manlio Dov\u00ec.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cosa c\u2019\u00e8 di pi\u00f9 romantico del primo incontro tra un uomo e una donna? Ci sono aspettative, cuori che battono all\u2019impazzata <\/strong>e quell\u2019ansia incontrollabile di fare bella figura a tutti i costi! Cos\u00ec almeno viene raccontato nei romanzi rosa o nelle commediole romantiche, ma nella vita \u00e8 veramente cos\u00ec? Se hai quindici anni e credi ancora nelle favole, forse s\u00ec!&nbsp; Se invece di anni ne hai cinquanta, hai gi\u00e0 un matrimonio alle spalle e qualche delusione che fa ancora male, allora la parola d\u2019ordine \u00e8\u2026 vendetta! I \u201csingle forzati\u201d di oggi sono uomini e donne che si ritrovano improvvisamente soli, con l\u2019assoluta necessit\u00e0 di rifarsi una vita sentimentale, ma con l\u2019inevitabile istinto di difendersi dalle frecce avvelenate di Cupido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prosegue, intanto, dal gioved\u00ec alla domenica, nel rispetto delle norme sanitarie, la Terrazza del Belvedere, <\/strong>con food e drink, arte, musica nell\u2019isola pedonale, tra Corso della Repubblica, via Maccari fino a largo Turriziani, progetto realizzato con gli assessorati al commercio (coordinato da Antonio Scaccia) e centro storico.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frosinone, teatro musica e cabaret tra le porte \u00e8,\nanche quest\u2019anno, con ingresso rigorosamente libero. Prenotazione telefonica\nobbligatoria, fino ad esaurimento posti, sempre nel rispetto delle norme\nsanitarie, allo 0775\/1893548, nei seguenti giorni e orari: dal luned\u00ec al\ngioved\u00ec, 9.30 \u201312.30; dal gioved\u00ec alla domenica, 16.30 \u2013 18.30. Il pubblico\ndovr\u00e0 presentarsi, anche all\u2019ingresso di piazzale Vittorio Veneto, munito di\nmascherina. Coloro che avranno effettuato la prenotazione saranno attesi fino a\n15 minuti prima dell&#8217;inizio degli spettacoli, dando la possibilit\u00e0\ndell&#8217;ingresso nell&#8217;area agli altri spettatori, in caso di assenza, sempre allo\nscopo di garantire il distanziamento sociale, che non potr\u00e0 essere inferiore\nalla misura di un metro.&nbsp;<a href=\"http:\/\/www.comune.frosinone.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.comune.frosinone.it<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.bpf.it\/\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"500\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/BPF20062019_1700banner300x250.jpg\" alt=\"\" class=\"wp-image-13490\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/BPF20062019_1700banner300x250.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/BPF20062019_1700banner300x250-300x250.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/BPF20062019_1700banner300x250-500x417.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 28 agosto si chiuder\u00e0&nbsp;\u201cTeatro musica e cabaret tra le porte\u201d in piazzale Vittorio Veneto. La manifestazione, che ha suscitato<\/p>\n","protected":false},"author":18,"featured_media":43596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[1322,5731,94,93,10561,639,153],"class_list":["post-43595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-banca-popolare-frusinate","tag-cabaret","tag-ciociaria","tag-frosinone","tag-la-provincia-quotidfiano","tag-nicola-ottaviani","tag-teatro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, ultimo appuntamento con Teatro musica e cabaret - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, ultimo appuntamento con Teatro musica e cabaret\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 28 agosto si chiuder\u00e0&nbsp;\u201cTeatro musica e cabaret tra le porte\u201d in piazzale Vittorio Veneto. La manifestazione, che ha suscitato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-27T06:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T06:56:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, ultimo appuntamento con Teatro musica e cabaret\",\"datePublished\":\"2020-08-27T06:41:00+00:00\",\"dateModified\":\"2020-08-27T06:56:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TEATRO-2020-WEB_Pagina_19.jpg\",\"keywords\":[\"Banca popolare frusinate\",\"cabaret\",\"Ciociaria\",\"Frosinone\",\"la provincia quotidfiano\",\"nicola ottaviani\",\"teatro\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/\",\"name\":\"Frosinone, ultimo appuntamento con Teatro musica e cabaret - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TEATRO-2020-WEB_Pagina_19.jpg\",\"datePublished\":\"2020-08-27T06:41:00+00:00\",\"dateModified\":\"2020-08-27T06:56:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TEATRO-2020-WEB_Pagina_19.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TEATRO-2020-WEB_Pagina_19.jpg\",\"width\":1241,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, ultimo appuntamento con Teatro musica e cabaret\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/27\\\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, ultimo appuntamento con Teatro musica e cabaret - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, ultimo appuntamento con Teatro musica e cabaret","og_description":"Venerd\u00ec 28 agosto si chiuder\u00e0&nbsp;\u201cTeatro musica e cabaret tra le porte\u201d in piazzale Vittorio Veneto. La manifestazione, che ha suscitato","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-27T06:41:00+00:00","article_modified_time":"2020-08-27T06:56:57+00:00","og_image":[{"width":1241,"height":650,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, ultimo appuntamento con Teatro musica e cabaret","datePublished":"2020-08-27T06:41:00+00:00","dateModified":"2020-08-27T06:56:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg","keywords":["Banca popolare frusinate","cabaret","Ciociaria","Frosinone","la provincia quotidfiano","nicola ottaviani","teatro"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/","name":"Frosinone, ultimo appuntamento con Teatro musica e cabaret - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg","datePublished":"2020-08-27T06:41:00+00:00","dateModified":"2020-08-27T06:56:57+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/TEATRO-2020-WEB_Pagina_19.jpg","width":1241,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, ultimo appuntamento con Teatro musica e cabaret"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/27\/frosinone-ultimo-appuntamento-con-teatro-musica-e-cabaret\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=43595"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43595\/revisions"}],"predecessor-version":[{"id":43677,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43595\/revisions\/43677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/43596"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=43595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=43595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=43595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}