{"id":43356,"date":"2020-08-22T10:56:24","date_gmt":"2020-08-22T08:56:24","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=43356"},"modified":"2020-08-22T10:56:27","modified_gmt":"2020-08-22T08:56:27","slug":"mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/","title":{"rendered":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Coinvolgere anche la cittadinanza <\/strong>nella redazione dei nuovi strumenti<strong> di pianificazione della mobilit\u00e0 cittadina, <\/strong>per avviare un percorso di rinnovamento che sia il pi\u00f9 partecipato e condiviso possibile. \u00c8 la proposta avanzata dal <strong>consigliere comunale di Frosinone, Daniele Riggi<\/strong>, in merito alle novit\u00e0 che interesseranno il comune capoluogo per quanto riguarda la mobilit\u00e0. Una pianificazione che oltre ai tecnici comunali, dovrebbe veder coinvolti anche le organizzazioni politiche, i comitati di quartiere e le associazioni interessate al tema della mobilit\u00e0. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le novit\u00e0 previste per la mobilit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nei prossimi anni, con molta probabilit\u00e0, ci sar\u00e0 un radicale rinnovamento della <strong>mobilit\u00e0 urbana e interurbana nella citt\u00e0 di Frosinone<\/strong>: nuovo gestore del trasporto pubblico locale; <strong>nuove isole pedonali e ZTL<\/strong>; realizzazione di nuove rotatorie e dell\u2019ultimo tratto della ex \u201cMonti Lepini\u201d; nuove piste ciclabili; progetto della metropolitana di superficie; fermata TAV \u2013 Frecciarossa. Le sopraccitate novit\u00e0, se inquadrate in un progetto organico, potenzialmente, possono trasformarsi in una nuova rete di mobilit\u00e0 urbana per il comune capoluogo, che pu\u00f2 avere riflessi importanti anche in prospettiva intercomunale e provinciale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Due strumenti per la mobilit\u00e0 cittadina<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Contestualmente a queste novit\u00e0, si \u00e8 presentata l\u2019opportunit\u00e0 di tornare a discutere di due strumenti importanti per la mobilit\u00e0 cittadina: il<strong> PUMS, piano urbano della mobilit\u00e0 sostenibile, e il PUT, piano urbano del traffico. <\/strong>Questi strumenti sono gi\u00e0 stati oggetto di discussione nel corso di una importante riunione tecnica, che si \u00e8 tenuta lo scorso febbraio, a cui ho partecipato, in qualit\u00e0 di membro della commissione consiliare &#8220;polizia locale, personale, protezione civile, sicurezza urbana e centro storico&#8221;. A quella riunione sarebbero dovute seguire altre riunioni tecniche, con lo scopo di completare e perfezionare la redazione delle <strong>linee di indirizzo del PUMS e l\u2019aggiornamento del PUT, <\/strong>prima dell\u2019approvazione di questi strumenti in Consiglio comunale. Purtroppo, l\u2019arrivo dell\u2019emergenza Coronavirus ha, inevitabilmente, interrotto questo percorso, che avrebbe potuto avere esiti positivi gi\u00e0 in estate. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ascoltare le esigenze dei cittadini<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Suggerisco all\u2019<strong>Amministrazione Ottaviani di riprendere il prima possibile il percorso interrotto<\/strong>, e di coinvolgere nella redazione di questi importanti strumenti di pianificazione della mobilit\u00e0 urbana, non solo i tecnici comunali, ma anche le organizzazioni politiche, i comitati di quartiere e le associazioni interessate al tema della mobilit\u00e0, avviando cos\u00ec un percorso di rinnovamento della mobilit\u00e0 urbana che sia il pi\u00f9 partecipato e condiviso possibile. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Coinvolgere anche i soggetti politici e la societ\u00e0 civile<\/strong> \u00e8 importante, perch\u00e9 non bisogna dimenticare che questi strumenti di pianificazione, per essere pienamente efficaci e commisurati alle esigenze dei cittadini necessitano, soprattutto, di scelte di indirizzo politico, oltre a quelle di matrice tecnica. Le conoscenze maturate nel corso degli anni dalle organizzazioni politiche, dalle associazioni e dai comitati di quartiere sulle problematiche della mobilit\u00e0 cittadina possono essere una fonte di informazioni preziosa, che amplia e completa le informazioni gi\u00e0 in possesso degli uffici tecnici comunali. Spero, dunque, che l\u2019Amministrazione Ottaviani non sottovaluti l\u2019importanza di <strong>avviare un percorso di confronto e condivisione con le forze politiche e con la cittadinanza<\/strong> su un tema cos\u00ec importante, come quello della mobilit\u00e0 urbana, in una fase storica in cui si stanno presentando nuove importanti opportunit\u00e0 per la nostra citt\u00e0&#8221;.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Coinvolgere anche la cittadinanza nella redazione dei nuovi strumenti di pianificazione della mobilit\u00e0 cittadina, per avviare un percorso di rinnovamento<\/p>\n","protected":false},"author":18,"featured_media":43367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[5288,93,5733,2115,461,529],"class_list":["post-43356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-daniele-riggi","tag-frosinone","tag-isole-pedonali","tag-tav","tag-traffico","tag-viabilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione\" \/>\n<meta property=\"og:description\" content=\"Coinvolgere anche la cittadinanza nella redazione dei nuovi strumenti di pianificazione della mobilit\u00e0 cittadina, per avviare un percorso di rinnovamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-22T08:56:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-22T08:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione\",\"datePublished\":\"2020-08-22T08:56:24+00:00\",\"dateModified\":\"2020-08-22T08:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/daniele-riggi.jpg\",\"keywords\":[\"daniele riggi\",\"Frosinone\",\"isole pedonali\",\"tav\",\"traffico\",\"viabilit\u00e0\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/\",\"name\":\"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/daniele-riggi.jpg\",\"datePublished\":\"2020-08-22T08:56:24+00:00\",\"dateModified\":\"2020-08-22T08:56:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/daniele-riggi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/daniele-riggi.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/","og_locale":"it_IT","og_type":"article","og_title":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione","og_description":"Coinvolgere anche la cittadinanza nella redazione dei nuovi strumenti di pianificazione della mobilit\u00e0 cittadina, per avviare un percorso di rinnovamento","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-22T08:56:24+00:00","article_modified_time":"2020-08-22T08:56:27+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione","datePublished":"2020-08-22T08:56:24+00:00","dateModified":"2020-08-22T08:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg","keywords":["daniele riggi","Frosinone","isole pedonali","tav","traffico","viabilit\u00e0"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/","name":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg","datePublished":"2020-08-22T08:56:24+00:00","dateModified":"2020-08-22T08:56:27+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/daniele-riggi.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e0 urbana a Frosinone, Riggi: la cittadinanza va coinvolta nella pianificazione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/mobilita-urbana-a-frosinone-riggi-la-cittadinanza-va-coinvolta-nella-pianificazione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=43356"}],"version-history":[{"count":6,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43356\/revisions"}],"predecessor-version":[{"id":43372,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43356\/revisions\/43372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/43367"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=43356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=43356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=43356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}