{"id":43347,"date":"2020-08-22T08:54:42","date_gmt":"2020-08-22T06:54:42","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=43347"},"modified":"2020-08-22T08:54:45","modified_gmt":"2020-08-22T06:54:45","slug":"isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/","title":{"rendered":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>&#8220;Il prossimo 14 settembre le scuole del primo ciclo di Isola del Liri riapriranno per accogliere i nostri bambini.<\/strong> Sappiamo che l\u2019istruzione \u00e8 strategica per la societ\u00e0, costruisce competenze per il futuro. La Scuola tuttavia \u00e8 anche altro; \u00e8 parte integrante del sistema di relazioni di una Comunit\u00e0, educa al vivere insieme e al rispetto reciproco con il lavoro instancabile che i docenti svolgono ogni giorno, nelle classi&#8221;. <strong>Inizia cos\u00ec la lettera che il sindaco Massimiliano Quadrini, la consigliera delegata  all&#8217;Istruzione Monica Mancini, la Dirigente Scolastica,  Gabriella Curato. hanno inviato alle famiglie. <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"458\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/massimiliano-quadrini.jpg\" alt=\"massimiliano quadrini isola del liri\" class=\"wp-image-42889\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/massimiliano-quadrini.jpg 769w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/massimiliano-quadrini-300x179.jpg 300w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><figcaption>Il sindaco di Isola del Liri Massimiliano Quadrini<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Le misure adottate<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Per questo <strong>abbiamo lavorato durante tutta l\u2019estate, per consentire la riapertura nel rispetto delle regole di sicurezza anti Covid19 e la ripresa in presenza<\/strong>. I lavori di messa in sicurezza del plesso Valcatoio, completati nei termini, ci hanno garantito gli spazi necessari per ospitare le classi di scuola secondaria rispettando il distanziamento dovuto ed hanno consentito, inoltre, di potere temporaneamente trasferire due classi della scuola primaria di Forli al secondo piano del Valcatoio, in ambienti grandi, nuovi e pienamente idonei&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Sono stati eseguiti inoltre, nel plesso di Montemontano, lavori di adeguamento degli spazi interni<\/strong> che consentiranno di spostare una sezione della scuola dell\u2019Infanzia di Carnello in locali spaziosi e, altrettanto, di garantire spazi adeguati ai piccini e ai docenti che resteranno nel plesso di Carnello. Il Comune ha acquistato i banchi monoposto che saranno consegnati prima dell\u2019inizio delle attivit\u00e0 didattiche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;appello<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La Scuola ha organizzato, secondo le prescrizioni, un piano della sicurezza per minimizzare i rischi da contagio. Siamo pronti, i nostri bambini faranno lezione tutti negli edifici scolastici, provvisti di palestre e laboratori adeguati. Nessuno rester\u00e0 escluso o dovr\u00e0 ripiegare su spazi improvvisati. <strong>A voi genitori chiediamo di partecipare attivamente al rispetto delle regole prescritte<\/strong> dalla Autorit\u00e0 affinch\u00e9 non vengano meno le condizioni di sicurezza, per potere proseguire nell\u2019attivit\u00e0 in presenza. Insieme non ci fermeremo, per il futuro degli adulti di domani e del nostro bellissimo territorio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il prossimo 14 settembre le scuole del primo ciclo di Isola del Liri riapriranno per accogliere i nostri bambini. Sappiamo<\/p>\n","protected":false},"author":18,"featured_media":1656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,38],"tags":[94,8916,11002,260,3067,1775,129],"class_list":["post-43347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-scuola","tag-ciociaria","tag-covid","tag-gabriella-curato","tag-isola-del-liri","tag-la-provincia-quotidiano","tag-massimiliano-quadrini","tag-scuole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie\" \/>\n<meta property=\"og:description\" content=\"&#8220;Il prossimo 14 settembre le scuole del primo ciclo di Isola del Liri riapriranno per accogliere i nostri bambini. Sappiamo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-22T06:54:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-22T06:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie\",\"datePublished\":\"2020-08-22T06:54:42+00:00\",\"dateModified\":\"2020-08-22T06:54:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/panoramica-isola_liri-e1542391595800.jpg\",\"keywords\":[\"Ciociaria\",\"covid\",\"gabriella curato\",\"isola del liri\",\"La provincia quotidiano\",\"massimiliano quadrini\",\"scuole\"],\"articleSection\":[\"*SLIDE*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/\",\"name\":\"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/panoramica-isola_liri-e1542391595800.jpg\",\"datePublished\":\"2020-08-22T06:54:42+00:00\",\"dateModified\":\"2020-08-22T06:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/panoramica-isola_liri-e1542391595800.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/panoramica-isola_liri-e1542391595800.jpg\",\"width\":632,\"height\":421,\"caption\":\"Una foto panoramica di Isola del Liri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/22\\\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie","og_description":"&#8220;Il prossimo 14 settembre le scuole del primo ciclo di Isola del Liri riapriranno per accogliere i nostri bambini. Sappiamo","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-22T06:54:42+00:00","article_modified_time":"2020-08-22T06:54:45+00:00","og_image":[{"width":632,"height":421,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie","datePublished":"2020-08-22T06:54:42+00:00","dateModified":"2020-08-22T06:54:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg","keywords":["Ciociaria","covid","gabriella curato","isola del liri","La provincia quotidiano","massimiliano quadrini","scuole"],"articleSection":["*SLIDE*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/","name":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg","datePublished":"2020-08-22T06:54:42+00:00","dateModified":"2020-08-22T06:54:45+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/panoramica-isola_liri-e1542391595800.jpg","width":632,"height":421,"caption":"Una foto panoramica di Isola del Liri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri, riapertura delle scuole: Comune e dirigente scolastico scrivono alle famiglie"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/22\/isola-del-liri-riapertura-delle-scuole-comune-e-dirigente-scolastico-scrivono-alle-famiglie\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=43347"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43347\/revisions"}],"predecessor-version":[{"id":43348,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/43347\/revisions\/43348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=43347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=43347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=43347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}