{"id":42573,"date":"2020-08-11T14:51:35","date_gmt":"2020-08-11T12:51:35","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=42573"},"modified":"2020-08-11T15:13:10","modified_gmt":"2020-08-11T13:13:10","slug":"santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/","title":{"rendered":"Cassino, problemi al &#8216;Santa Scolastica&#8217;. Ciacciarelli vuole chiarezza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cDopo la mancanza di anestesisti ed il conseguente stop agli interventi ordinari, spunta un\u2019altra grana all\u2019ospedale <strong>Santa Scolastica di Cassino<\/strong>&#8220;.   Ad intervenite ancora una volta sulle criticit\u00e0 del nosocomio cassinate \u00e8 il consigliere regionale del Lazio <strong>Pasquale Ciacciarelli<\/strong> (Lega) che sofferma la sua attenzione sul reparto di <strong>Gastroenterologia<\/strong>. &#8220;Sembrerebbe &#8211; evidenzia Ciacciarelli &#8211; che il reparto sia a <strong>corto di personale<\/strong>; ci sarebbero soltanto <strong>quattro medici<\/strong>&nbsp;a garantire tutti i servizi. Secondo qualche indiscrezione presto potrebbe venire smantellato&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;attacco al Pd<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La direzione dell\u2019ospedale &#8211; tuona Ciacciarelli &#8211; chiarisca subito l\u2019effettivo status delle cose. Se fosse vero sarebbe gravissimo. \u00c8 necessario un potenziamento dell\u2019ospedale, pi\u00f9 assunzioni. Il PD non pu\u00f2 andare avanti con la politica dei nastri tagliati che poi si rivelano scatole vuote! La situazione sta assumendo tratti davvero drammatici ed a pagarne le spese sono, come sempre, i cittadini che vengono depauperati dei servizi essenziali. Andr\u00f2 a fondo alla vicenda.\u201d <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consigliere regionale della Lega parla delle criticit\u00e0 del reparto di Gastroenterologia<\/p>\n","protected":false},"author":22,"featured_media":28027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[216,10898,1336,1334],"class_list":["post-42573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cassino","tag-gastroenterologia","tag-pasquale-ciacciarelli","tag-santa-scolastica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, problemi al &#039;Santa Scolastica&#039;. Ciacciarelli vuole chiarezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, problemi al &#039;Santa Scolastica&#039;. Ciacciarelli vuole chiarezza\" \/>\n<meta property=\"og:description\" content=\"Il consigliere regionale della Lega parla delle criticit\u00e0 del reparto di Gastroenterologia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-11T12:51:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-11T13:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stefania Vitti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stefania Vitti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/\"},\"author\":{\"name\":\"Stefania Vitti\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/4b2a77accd24ffeaef25ab2bb65dafbf\"},\"headline\":\"Cassino, problemi al &#8216;Santa Scolastica&#8217;. Ciacciarelli vuole chiarezza\",\"datePublished\":\"2020-08-11T12:51:35+00:00\",\"dateModified\":\"2020-08-11T13:13:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/\"},\"wordCount\":165,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ciacciarelli.jpg\",\"keywords\":[\"Cassino\",\"gastroenterologia\",\"pasquale ciacciarelli\",\"santa scolastica\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/\",\"name\":\"Cassino, problemi al 'Santa Scolastica'. Ciacciarelli vuole chiarezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ciacciarelli.jpg\",\"datePublished\":\"2020-08-11T12:51:35+00:00\",\"dateModified\":\"2020-08-11T13:13:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ciacciarelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ciacciarelli.jpg\",\"width\":740,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, problemi al &#8216;Santa Scolastica&#8217;. Ciacciarelli vuole chiarezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/4b2a77accd24ffeaef25ab2bb65dafbf\",\"name\":\"Stefania Vitti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g\",\"caption\":\"Stefania Vitti\"},\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/vitti\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/11\\\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, problemi al 'Santa Scolastica'. Ciacciarelli vuole chiarezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, problemi al 'Santa Scolastica'. Ciacciarelli vuole chiarezza","og_description":"Il consigliere regionale della Lega parla delle criticit\u00e0 del reparto di Gastroenterologia","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2020-08-11T12:51:35+00:00","article_modified_time":"2020-08-11T13:13:10+00:00","og_image":[{"width":740,"height":607,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg","type":"image\/jpeg"}],"author":"Stefania Vitti","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Stefania Vitti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/"},"author":{"name":"Stefania Vitti","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/4b2a77accd24ffeaef25ab2bb65dafbf"},"headline":"Cassino, problemi al &#8216;Santa Scolastica&#8217;. Ciacciarelli vuole chiarezza","datePublished":"2020-08-11T12:51:35+00:00","dateModified":"2020-08-11T13:13:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/"},"wordCount":165,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg","keywords":["Cassino","gastroenterologia","pasquale ciacciarelli","santa scolastica"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/","name":"Cassino, problemi al 'Santa Scolastica'. Ciacciarelli vuole chiarezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg","datePublished":"2020-08-11T12:51:35+00:00","dateModified":"2020-08-11T13:13:10+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ciacciarelli.jpg","width":740,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, problemi al &#8216;Santa Scolastica&#8217;. Ciacciarelli vuole chiarezza"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/4b2a77accd24ffeaef25ab2bb65dafbf","name":"Stefania Vitti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c35716bb6116d7ef16dc3aae005800b801cc92f822e317e712e663fa99d3f6e6?s=96&d=mm&r=g","caption":"Stefania Vitti"},"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/vitti\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/11\/santa-scolastica-cassino-gastroenterologia-ciacciarelli-andro-a-fondo-alla-vicenda\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=42573"}],"version-history":[{"count":11,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42573\/revisions"}],"predecessor-version":[{"id":42599,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42573\/revisions\/42599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/28027"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=42573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=42573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=42573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}