{"id":42453,"date":"2020-08-10T16:01:47","date_gmt":"2020-08-10T14:01:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=42453"},"modified":"2020-08-10T16:01:50","modified_gmt":"2020-08-10T14:01:50","slug":"cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/","title":{"rendered":"Cassino: i detenuti saranno impiegati per la manutenzione stradale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Prima\nsaranno formati attraverso corsi specifici tenuti da Societ\u00e0\nAustostrad e poi, una volta adeguatamente preparati, potranno essere\nimpiegati per lavori di pubblica utilit\u00e0 inerente la manutenzione\nstradale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta dei <strong>detenuti della casa circondariale San Domenico<\/strong> che questa mattina, attraverso il suo direttore,<strong> Francesco Cocco<\/strong>, ha sottoscritto una <strong>lettera di intenti <\/strong>con il sindaco del Comune di Cassino, <strong>Enzo Salera<\/strong> e il direttore del VI Tronco di Cassino della Societ\u00e0 Autostrade, <strong>Costantino Ivoi.<\/strong>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presente all\u2019incontro anche <strong>l\u2019assessore al Personale, Barbara Alifuoco<\/strong>, che sta seguendo con particolare impegno l\u2019iter del progetto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">In\ncosa consiste il progetto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le parti hanno convenuto di avviare<strong> una collaborazione della durata di 12 mesi, estensibile per un altro anno ancora, <\/strong>volta a sviluppare percorsi di reintegrazione sociale e lavorativa in favore di soggetti destinatari di condanna penale definitiva, attraverso interventi di manutenzione stradale.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tali interventi potranno riguardare il rifacimento della segnaletica orizzontale, la pulizia di caditoie, la sistemazione di sedi stradali a basso scorrimento, la manutenzione del verde urbano, ed attivit\u00e0 finalizzate a ripristinare il decoro di spazi pubblici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019iniziativa,\nfacendo proprio lo spirito dell\u2019art. 27 della Costituzione, secondo\ncui il trattamento rieducativo dei soggetti ridotti in \u201cvinculis\u201d\ndeve tendere \u201cal reinserimento sociale degli stessi\u201d, mira  al\nreintegro sociale del personale detenuto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Successivamente,\ncon protocolli d\u2019intesa verranno definiti  gli impegni di dettaglio\nche le Parti andranno ad assumere. \n<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le\nparole di Salera<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Si\ntratta di una iniziativa \u2013 ha commentato il primo cittadino di\nCassino \u2013 di rilevante funzione sociale e molto utile sia alla\ncollettivit\u00e0 che ai detenuti, i quali, a titolo volontaristico e\ngratuito, intenderanno essere coinvolti nella iniziativa&#8221;. \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infatti\nessi potranno giovarsi dell\u2019assistenza della Societ\u00e0 Autostradale\nper corsi di formazione professionale per poter poi essere impiegati\nin interventi puntuali a favore del nostro territorio comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Cassino, il carcere San Domenico e la Societ\u00e0 Autostrade hanno sottoscritto una lettera d&#8217;intenti per l&#8217;impiego dei detenuti nei lavori di manutenzione stradale<\/p>\n","protected":false},"author":18,"featured_media":42455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[10880,216,94,10193,3273,10878,464,5074,10879,564],"class_list":["post-42453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-casa-circondariale","tag-cassino","tag-ciociaria","tag-detenuti","tag-enzo-salera","tag-lavori-di-pubblica-utilita","tag-manutenzione","tag-san-domenico","tag-societa-autostrade","tag-strade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino: i detenuti saranno impiegati per la manutenzione stradale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino: i detenuti saranno impiegati per la manutenzione stradale\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Cassino, il carcere San Domenico e la Societ\u00e0 Autostrade hanno sottoscritto una lettera d&#039;intenti per l&#039;impiego dei detenuti nei lavori di manutenzione stradale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-10T14:01:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T14:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino: i detenuti saranno impiegati per la manutenzione stradale\",\"datePublished\":\"2020-08-10T14:01:47+00:00\",\"dateModified\":\"2020-08-10T14:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/detenuti-rebibbia.jpg\",\"keywords\":[\"casa circondariale\",\"Cassino\",\"Ciociaria\",\"detenuti\",\"enzo salera\",\"lavori di pubblica utilit\u00e0\",\"manutenzione\",\"san domenico\",\"societ\u00e0 autostrade\",\"strade\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/\",\"name\":\"Cassino: i detenuti saranno impiegati per la manutenzione stradale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/detenuti-rebibbia.jpg\",\"datePublished\":\"2020-08-10T14:01:47+00:00\",\"dateModified\":\"2020-08-10T14:01:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/detenuti-rebibbia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/detenuti-rebibbia.jpg\",\"width\":800,\"height\":577,\"caption\":\"Detenuti al lavoro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino: i detenuti saranno impiegati per la manutenzione stradale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/10\\\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino: i detenuti saranno impiegati per la manutenzione stradale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino: i detenuti saranno impiegati per la manutenzione stradale","og_description":"Il Comune di Cassino, il carcere San Domenico e la Societ\u00e0 Autostrade hanno sottoscritto una lettera d'intenti per l'impiego dei detenuti nei lavori di manutenzione stradale","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-10T14:01:47+00:00","article_modified_time":"2020-08-10T14:01:50+00:00","og_image":[{"width":800,"height":577,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino: i detenuti saranno impiegati per la manutenzione stradale","datePublished":"2020-08-10T14:01:47+00:00","dateModified":"2020-08-10T14:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg","keywords":["casa circondariale","Cassino","Ciociaria","detenuti","enzo salera","lavori di pubblica utilit\u00e0","manutenzione","san domenico","societ\u00e0 autostrade","strade"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/","name":"Cassino: i detenuti saranno impiegati per la manutenzione stradale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg","datePublished":"2020-08-10T14:01:47+00:00","dateModified":"2020-08-10T14:01:50+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/detenuti-rebibbia.jpg","width":800,"height":577,"caption":"Detenuti al lavoro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino: i detenuti saranno impiegati per la manutenzione stradale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/10\/cassino-i-detenuti-saranno-impiegati-per-la-manutenzione-stradale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=42453"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42453\/revisions"}],"predecessor-version":[{"id":42456,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42453\/revisions\/42456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/42455"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=42453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=42453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=42453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}