{"id":42400,"date":"2020-08-09T15:08:57","date_gmt":"2020-08-09T13:08:57","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=42400"},"modified":"2020-08-09T15:08:59","modified_gmt":"2020-08-09T13:08:59","slug":"risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/","title":{"rendered":"&#8216;Risate e dintorni&#8217;: tre serate di cabaret al Castello dei Conti di Aquino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tre serate di cabaret nella splendida cornice del <strong>Castello Medievale dei Conti di Aquino<\/strong> di <strong>Piedimonte San Germano<\/strong>. La rassegna <strong>&#8216;Risate e Dintorni&#8217;,<\/strong> giunta alla sua XVIII edizione, andr\u00e0 in scena domani 10 agosto, marted\u00ec 11 e mercoled\u00ec 12.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Un\u2019iniziativa volta alla <strong>promozione e alla diffusione del turismo e del folklore regionale<\/strong>, con particolare riferimento alla valorizzazione della tradizione del nostro territorio &#8211; commenta <strong>Gioacchino Ferdinandi, sindaco di Piedimonte San Germano<\/strong>. Tre serate all\u2019insegna del cabaret, con l\u2019obiettivo di sensibilizzare e coinvolgere la comunit\u00e0 cittadina&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"501\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/alessandro-bolide.jpg\" alt=\"alessandro bolide \" class=\"wp-image-42402\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/alessandro-bolide.jpg 750w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/alessandro-bolide-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/alessandro-bolide-272x182.jpg 272w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Il comico Alessandro Bolide direttamente da &#8216;Made in Sud&#8217;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anche il <strong>vicesindaco e assessore alla Cultura, Leonardo Capuano,<\/strong> si dice molto soddisfatto: &#8220;Nonostante un periodo complicato e delicato siamo riusciti a dare seguito a questa manifestazione. Era importante, proprio in un momento come questo, dare un segnale di vita e di continuit\u00e0 a tutta la comunit\u00e0&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rispetto\ndelle regole anti-Covid<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ospiti di questa edizione saranno i comici Roberto Ciufoli, \u2018Nduccio e Alessandro Bolide.<strong> Il presidente della Pro Loco, Alfonso Testa, assicura che ci sar\u00e0 il rispetto di tutte le regole anti-Covid<\/strong> e del distanziamento sociale. La partecipazione alla manifestazione sar\u00e0 a porte chiuse, su prenotazione su numero comunale 333.9485433 e con posti limitati nel rispetto del distanziamento con obbligo di indossare la mascherina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da domani a mercoled\u00ec 12 agosto tre serate di cabaret al Castello medievale dei Conti di Aquino con la rassegna &#8216;Risate e dintorni&#8217;<\/p>\n","protected":false},"author":18,"featured_media":42401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[10869,5731,10870,94,93,4725,194,10868,5689],"class_list":["post-42400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-alessandro-bolide","tag-cabaret","tag-castello-medievale-dei-conti-di-aquino","tag-ciociaria","tag-frosinone","tag-gioacchino-ferdinandi","tag-piedimonte-san-germano","tag-risate-e-dintorni","tag-roberto-ciufoli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&#039;Risate e dintorni&#039;: tre serate di cabaret al Castello dei Conti di Aquino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Risate e dintorni&#039;: tre serate di cabaret al Castello dei Conti di Aquino\" \/>\n<meta property=\"og:description\" content=\"Da domani a mercoled\u00ec 12 agosto tre serate di cabaret al Castello medievale dei Conti di Aquino con la rassegna &#039;Risate e dintorni&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-09T13:08:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T13:08:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"&#8216;Risate e dintorni&#8217;: tre serate di cabaret al Castello dei Conti di Aquino\",\"datePublished\":\"2020-08-09T13:08:57+00:00\",\"dateModified\":\"2020-08-09T13:08:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/roberto-ciufoli.jpg\",\"keywords\":[\"alessandro bolide\",\"cabaret\",\"castello medievale dei conti di aquino\",\"Ciociaria\",\"Frosinone\",\"Gioacchino Ferdinandi\",\"piedimonte san germano\",\"risate e dintorni\",\"Roberto Ciufoli\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/\",\"name\":\"'Risate e dintorni': tre serate di cabaret al Castello dei Conti di Aquino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/roberto-ciufoli.jpg\",\"datePublished\":\"2020-08-09T13:08:57+00:00\",\"dateModified\":\"2020-08-09T13:08:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/roberto-ciufoli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/roberto-ciufoli.jpg\",\"width\":640,\"height\":439,\"caption\":\"Roberto Ciufoli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Risate e dintorni&#8217;: tre serate di cabaret al Castello dei Conti di Aquino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"'Risate e dintorni': tre serate di cabaret al Castello dei Conti di Aquino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/","og_locale":"it_IT","og_type":"article","og_title":"'Risate e dintorni': tre serate di cabaret al Castello dei Conti di Aquino","og_description":"Da domani a mercoled\u00ec 12 agosto tre serate di cabaret al Castello medievale dei Conti di Aquino con la rassegna 'Risate e dintorni'","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-09T13:08:57+00:00","article_modified_time":"2020-08-09T13:08:59+00:00","og_image":[{"width":640,"height":439,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"&#8216;Risate e dintorni&#8217;: tre serate di cabaret al Castello dei Conti di Aquino","datePublished":"2020-08-09T13:08:57+00:00","dateModified":"2020-08-09T13:08:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg","keywords":["alessandro bolide","cabaret","castello medievale dei conti di aquino","Ciociaria","Frosinone","Gioacchino Ferdinandi","piedimonte san germano","risate e dintorni","Roberto Ciufoli"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/","name":"'Risate e dintorni': tre serate di cabaret al Castello dei Conti di Aquino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg","datePublished":"2020-08-09T13:08:57+00:00","dateModified":"2020-08-09T13:08:59+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/roberto-ciufoli.jpg","width":640,"height":439,"caption":"Roberto Ciufoli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"&#8216;Risate e dintorni&#8217;: tre serate di cabaret al Castello dei Conti di Aquino"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/risate-e-dintorni-tre-serate-di-cabaret-al-castello-dei-conti-di-aquino\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=42400"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42400\/revisions"}],"predecessor-version":[{"id":42403,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42400\/revisions\/42403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/42401"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=42400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=42400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=42400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}