{"id":42360,"date":"2020-08-09T12:09:57","date_gmt":"2020-08-09T10:09:57","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=42360"},"modified":"2020-08-09T12:21:04","modified_gmt":"2020-08-09T10:21:04","slug":"cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/","title":{"rendered":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una bravata che ha a dir poco del surreale quella messa a segno da un uomo che a bordo della sua auto, una <strong>Mercedes Classe A<\/strong>, ha percorso il tragitto dei portici della centrale <strong>piazza Labriola a Cassino<\/strong>. Incurante delle persone presenti e degli arredi esterni dei locali, il giovane ha guidato lungo tutto il colonnato per poi sfrecciare sulla piazza fino schiantarsi contro una vetrina di un bar.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fitvids-video\"><iframe loading=\"lazy\" title=\"Cassino, con l&#039;auto semina il panico in centro. Sdegno e preoccupazione per il folle gesto\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/d95yTcxnL74?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Nessuna traccia dell&#8217;automobilista<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;autore del gesto \u00e8 riuscito a dileguarsi facendo perdere le proprie tracce, ma i carabinieri stanno lavorando per risalire alle sue generalit\u00e0 grazie alle testimonianze dei presenti che hanno ripreso la scena pubblicandola sui social. Il video, che in queste ore sta circolando in rete, ha generato sdegno e preoccupazione per la sicurezza dei ragazzi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il commento di Abbruzzese contro il sindaco Salera<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A commentare l&#8217;insana azione anche il consigliere comunale di opposizione,<strong> Mario Abbruzzese<\/strong>, che non ha mancato di sferrare un attacco contro il sindaco di Cassino <strong>Enzo Salera<\/strong>: &#8220;Sta creando il video sconvolgente che mostra un\u2019automobile andare indisturbata in piazza Labriola e sotto i portici, danneggiando i locali e mettendo in pericolo la vita dei giovani che erano l\u00ec pone un serio problema di sicurezza in questa citt\u00e0. Lo dico da padre, prima che da politico, non \u00e8 possibile che i nostri ragazzi non possano divertirsi in sicurezza in questa citt\u00e0. Non \u00e8 possibile che una macchina giri indisturbata in una zona dove non dovrebbe mai transitare.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Chiesto un tavolo sulla sicurezza<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il sindaco Salera \u00e8 stato preso in giro: voleva pedonalizzare Corso della Repubblica e invece si e trovato le macchine in piazza Labriola! Caro sindaco \u00e8 venuto il momento di smetterla di girare per fare inaugurazioni e di iniziare a lavorare, portiamo urgentemente questo tema in consiglio comunale. Non c\u2019\u00e8 nulla di pi\u00f9 importante della sicurezza dei nostri figli di cui parlare. Chiederemo come gruppo di minoranza un consiglio comunale su questo tema e anticipo una richiesta di convocare subito un tavolo sulla sicurezza con le forze dell\u2019ordine, la questura e il Prefetto per garantire ai nostri giovani la sicurezza che meritano&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.<\/p>\n","protected":false},"author":18,"featured_media":42367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[216,10859,1226,266,2020,3860,10860],"class_list":["post-42360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-cassino","tag-corsa-auto","tag-mario-abbruzzese","tag-movida","tag-pericolo","tag-piazza-labriola","tag-portici"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto\" \/>\n<meta property=\"og:description\" content=\"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-09T10:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T10:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto\",\"datePublished\":\"2020-08-09T10:09:57+00:00\",\"dateModified\":\"2020-08-09T10:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/auto-portici-Cassino.png\",\"keywords\":[\"Cassino\",\"corsa auto\",\"mario abbruzzese\",\"movida\",\"pericolo\",\"piazza labriola\",\"portici\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/\",\"name\":\"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/auto-portici-Cassino.png\",\"datePublished\":\"2020-08-09T10:09:57+00:00\",\"dateModified\":\"2020-08-09T10:21:04+00:00\",\"description\":\"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/auto-portici-Cassino.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/auto-portici-Cassino.png\",\"width\":560,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/09\\\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto","og_description":"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-09T10:09:57+00:00","article_modified_time":"2020-08-09T10:21:04+00:00","og_image":[{"width":560,"height":330,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto","datePublished":"2020-08-09T10:09:57+00:00","dateModified":"2020-08-09T10:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png","keywords":["Cassino","corsa auto","mario abbruzzese","movida","pericolo","piazza labriola","portici"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/","name":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png","datePublished":"2020-08-09T10:09:57+00:00","dateModified":"2020-08-09T10:21:04+00:00","description":"Un ragazzo a bordo della sua auto ha guidato lungo il colonnato di piazza Labriola a Cassino seminando il panico.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/auto-portici-Cassino.png","width":560,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, semina il panico in centro. Sdegno e preoccupazione per il folle gesto"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/09\/cassino-con-lauto-semina-il-panico-in-centro-sdegno-e-preoccupazione-per-il-folle-gesto\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=42360"}],"version-history":[{"count":8,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42360\/revisions"}],"predecessor-version":[{"id":42391,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/42360\/revisions\/42391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/42367"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=42360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=42360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=42360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}