{"id":41933,"date":"2020-08-04T11:01:31","date_gmt":"2020-08-04T09:01:31","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=41933"},"modified":"2020-08-04T11:18:13","modified_gmt":"2020-08-04T09:18:13","slug":"si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/","title":{"rendered":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u00c8 morto attorno alle 22.20 di ieri sera monsignor Lorenzo Chiarinelli. <\/strong>Nell&#8217;ultimo periodo le sue condizioni si erano aggravate. <strong>Nato a Pratoianni il 16 marzo 1935<\/strong>, monsignor Chiarinelli \u00e8 stato vice assistente ecclesiastico centrale della Fuci e un insegnante tra i pi\u00f9 apprezzati del liceo Classico \u201cVarrone\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A livello nazionale \u00e8 stato dal 1967 vice assistente della Fuci e, successivamente, del \u201cMovimento dei laureati\u201d e del rinnovato \u201cMovimento Ecclesiale di Impegno Culturale\u201d (Meic). <strong>Consacrato vescovo nel 1983, ha retto la diocesi di Sora- Aquino-Pontecorvo fino al 1993<\/strong>, quando \u00e8 stato trasferito alla diocesi di Aversa (1994-1997). Nel 1997 fu nominato vescovo di Viterbo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un episcopato illuminato<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Durante il suo episcopato, nella\nConferenza episcopale italiana ha ricoperto l\u2019incarico di presidente della\ncommissione episcopale per la Dottrina della fede e la Catechesi conducendo la\nverifica e la redazione definitiva del \u201ccatechismi\u201d della Cei. \u00c8 stato membro\ndella commissione episcopale per l\u2019Ecumenismo e il Dialogo e presidente del\ncomitato scientifico organizzatore delle Settimane dei Cattolici Italiani. In\nquesta veste ha condotto nell\u2019ottobre 2004 la 44\u00b0 Settimana Sociale dei\nCattolici Italiani sul tema \u201cDemocrazia: nuovi scenari \u2013 nuovi poteri\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il messaggio del vescovo\nAntonazzo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dalla segreteria del vescovo di Sora-Cassino-Aquino-Pontecorvo, monsignor Gerardo Antonazzo, nella serata di ieri \u00e8 arrivata la comunicazione della morte di monsignor Chiarinelli. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Consapevoli che i pensieri e le vie del Signore non sono sempre per noi pienamente comprensibili, &#8211; si legge nel messaggio diffuso ieri sera &#8211; lo affidiamo con la nostra preghiera al Padre delle misericordie: \u2018Benedetto sei tu, Signore, Pastore eterno del tuo popolo, tu hai chiamato questo nostro fratello Lorenzo al ministero episcopale e lo hai sorretto con la tua grazia per essere segno della presenza del tuo Figlio, accogli ora le sue fatiche e introduci questo tuo servo fedele nella pienezza della tua gioia infinita&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le esequie<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La camera ardente sar\u00e0 allestita nella Cattedrale di Rieti dalle 16 alle 22 di oggi, 4 agosto 2020 mentre<strong> i funerali si svolgeranno il 5 agosto 2020<\/strong>, presso la <strong>Cattedrale di Rieti alle 11.00<\/strong> e presso la <strong>Basilica della Quercia a Viterbo alle 17.00.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 spento ieri sera monsignor Lorenzo Chiarinelli: \u00e8 stato vescovo di Sora fino al 1993<\/p>\n","protected":false},"author":18,"featured_media":41935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,5568,608,93,10800,1728,3777,1333],"class_list":["post-41933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-cordoglio","tag-diocesi","tag-frosinone","tag-lorenzo-chiarinelli","tag-monsignor-antonazzo","tag-morte","tag-vescovo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 spento ieri sera monsignor Lorenzo Chiarinelli: \u00e8 stato vescovo di Sora fino al 1993\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T09:01:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-04T09:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale\",\"datePublished\":\"2020-08-04T09:01:31+00:00\",\"dateModified\":\"2020-08-04T09:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/monsignor-chiarinelli.jpg\",\"keywords\":[\"Ciociaria\",\"Cordoglio\",\"diocesi\",\"Frosinone\",\"lorenzo chiarinelli\",\"monsignor antonazzo\",\"morte\",\"vescovo\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/\",\"name\":\"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/monsignor-chiarinelli.jpg\",\"datePublished\":\"2020-08-04T09:01:31+00:00\",\"dateModified\":\"2020-08-04T09:18:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/monsignor-chiarinelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/monsignor-chiarinelli.jpg\",\"width\":512,\"height\":341,\"caption\":\"Monsignor Lorenzo Chiarinelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/08\\\/04\\\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/","og_locale":"it_IT","og_type":"article","og_title":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale","og_description":"Si \u00e8 spento ieri sera monsignor Lorenzo Chiarinelli: \u00e8 stato vescovo di Sora fino al 1993","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-08-04T09:01:31+00:00","article_modified_time":"2020-08-04T09:18:13+00:00","og_image":[{"width":512,"height":341,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale","datePublished":"2020-08-04T09:01:31+00:00","dateModified":"2020-08-04T09:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg","keywords":["Ciociaria","Cordoglio","diocesi","Frosinone","lorenzo chiarinelli","monsignor antonazzo","morte","vescovo"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/","name":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg","datePublished":"2020-08-04T09:01:31+00:00","dateModified":"2020-08-04T09:18:13+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/08\/monsignor-chiarinelli.jpg","width":512,"height":341,"caption":"Monsignor Lorenzo Chiarinelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Si \u00e8 spento monsignor Lorenzo Chiarinelli: domani doppio funerale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/08\/04\/si-e-spento-monsignor-lorenzo-chiarinelli-gia-vescovo-di-sora\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=41933"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41933\/revisions"}],"predecessor-version":[{"id":41938,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41933\/revisions\/41938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/41935"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=41933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=41933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=41933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}