{"id":41263,"date":"2020-07-25T08:49:09","date_gmt":"2020-07-25T06:49:09","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=41263"},"modified":"2020-07-25T08:50:02","modified_gmt":"2020-07-25T06:50:02","slug":"schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/","title":{"rendered":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>I campionamenti effettuati per conto del Consorzio sono proseguiti anche in questi giorni<\/strong> e proseguiranno fin quando l\u2019attuale stato di allerta non sar\u00e0 definitivamente superato&#8221;.  <strong>Cos\u00ec Stefania Ruffo, Commissario Consorzi di Bonifica della Provincia di Frosinone.\u00a0 <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Le analisi eseguite su nostra espressa, diretta volont\u00e0 hanno confermato la assoluta utilizzabilit\u00e0 a fini irrigui <\/strong>d<strong>ell\u2019acqua del fiume Liri.<\/strong> Solo a seguito degli esiti dei campionamenti tutti pubblicati in tempo reale sul sito internet istituzionale del Conca di Sora \u2013 che hanno escluso qualunque alterazione dei parametri di sicurezza e qualit\u00e0 della risorsa idrica &#8211;\u00a0abbiamo ripristinato il servizio di irrigazione. Il problema, come noto alle autorit\u00e0 locali e all\u2019opinione pubblica, nasce altrove&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Non a caso io stessa, nelle more dell\u2019emergenza, avevo provveduto a contattare i responsabili del Consorzio di Bonifica del Fucin<\/strong>o per concordare un momento di confronto utile ad individuare le soluzioni pi\u00f9 opportune per superare la criticit\u00e0. L\u2019incontro che doveva esserci, \u00e8 stato rimandato dai dirigenti del Fucino per via della concomitante seduta della Commissione Ambiente della Regione Abruzzo con all\u2019ordine del giorno anche la questione della schiuma che, ciclicamente, compare sulle acque del fiume Liri generando, ovviamente, apprensione e preoccupazione tra i cittadini, non solo tra gli imprenditori agricoli consorziati del Conca&#8221;. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"378\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/schiuma-bianca-fiume.jpg\" alt=\"schiuma bianca fiume Liri il corriere della provincia\" class=\"wp-image-33290\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/schiuma-bianca-fiume.jpg 591w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/schiuma-bianca-fiume-300x192.jpg 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><figcaption>La schiuma bianca nel fiume Liri<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;impegno<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La riunione  \u00e8 stata rimandata. Marted\u00ec prossimo, accompagnata dal direttore del Consorzio di Sora, sar\u00f2 in Abruzzo<\/strong> per partecipare ad un tavolo che, nei miei auspici, sar\u00e0 la sede dalla quale scaturir\u00e0 la soluzione definitiva al decisamente sgradevole e preoccupante fenomeno, peraltro ciclico, della schiuma bianca sulle acque del Liri&#8221;.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;I campionamenti effettuati per conto del Consorzio sono proseguiti anche in questi giorni e proseguiranno fin quando l\u2019attuale stato di<\/p>\n","protected":false},"author":18,"featured_media":39150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[4511,537,6342,4547,313,6280],"class_list":["post-41263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-anbi-lazio","tag-bonifica","tag-conca-di-sora","tag-fiume-liri","tag-schiuma","tag-stefania-ruffo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino\" \/>\n<meta property=\"og:description\" content=\"&#8220;I campionamenti effettuati per conto del Consorzio sono proseguiti anche in questi giorni e proseguiranno fin quando l\u2019attuale stato di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-25T06:49:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-25T06:50:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino\",\"datePublished\":\"2020-07-25T06:49:09+00:00\",\"dateModified\":\"2020-07-25T06:50:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ruffo-bonifica.jpg\",\"keywords\":[\"Anbi Lazio.\",\"bonifica\",\"conca di sora\",\"fiume liri\",\"Schiuma\",\"Stefania Ruffo\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/\",\"name\":\"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ruffo-bonifica.jpg\",\"datePublished\":\"2020-07-25T06:49:09+00:00\",\"dateModified\":\"2020-07-25T06:50:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ruffo-bonifica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ruffo-bonifica.jpg\",\"width\":745,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/25\\\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/","og_locale":"it_IT","og_type":"article","og_title":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino","og_description":"&#8220;I campionamenti effettuati per conto del Consorzio sono proseguiti anche in questi giorni e proseguiranno fin quando l\u2019attuale stato di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-25T06:49:09+00:00","article_modified_time":"2020-07-25T06:50:02+00:00","og_image":[{"width":745,"height":507,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino","datePublished":"2020-07-25T06:49:09+00:00","dateModified":"2020-07-25T06:50:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg","keywords":["Anbi Lazio.","bonifica","conca di sora","fiume liri","Schiuma","Stefania Ruffo"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/","name":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg","datePublished":"2020-07-25T06:49:09+00:00","dateModified":"2020-07-25T06:50:02+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ruffo-bonifica.jpg","width":745,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Schiuma nel Liri, Stefania Ruffo incontra i dirigenti della Bonifica del Fucino"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/25\/schiuma-nel-liri-stefania-ruffo-incontra-i-dirigenti-della-bonifica-del-fucino\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=41263"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41263\/revisions"}],"predecessor-version":[{"id":41265,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41263\/revisions\/41265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/39150"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=41263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=41263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=41263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}