{"id":41183,"date":"2020-07-24T12:58:02","date_gmt":"2020-07-24T10:58:02","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=41183"},"modified":"2020-07-24T19:10:45","modified_gmt":"2020-07-24T17:10:45","slug":"federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/","title":{"rendered":"Federlazio, Polito traccia la rotta e invita a un cambio di passo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Carmine Polito<\/strong>, iscritto alla Federlazio fin dalla sua fondazione, ricoprendo nel tempo diversi incarichi,<strong> da ieri \u00e8 il nuovo presidente dell&#8217;associazione datoriale<\/strong>.  Da sempre membro del Consiglio Direttivo di Frosinone, \u00e8 stato  anche Presidente regionale del Settore Legno. Ha poi  retto la Presidenza della Federlazio di Frosinone per alcuni mesi nel  2014 ed \u00e8 stato infine Presidente del Confidi Lazio da gennaio 2017 a  maggio 2020.  Neanche il tempo di festeggiare, che gi\u00e0 \u00e8 al lavoro. Ringrazia per gli auguri e si dice pronto ad incontarere i presidenti degli enti territoriali e regionali.  <strong>Sollecita rapidit\u00e0 nell&#8217;erogazione delle risorse, nella realizzazione delle infrastrutture, anche telematiche, e nella sburocratizzazione. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervista<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Presidente, lei ha ricevuto, tra i tanti, anche gli auguri di Buschini, Pompeo, Pigliacelli e De Angelis. Ovvero i rappresentati di enti ed istituzioni che recitano un ruolo fondamentale per il rilancio territoriale.<\/strong>  <strong>Bastano gli auguri?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Intanto li ringrazio per gli auguri. Ci tengo a dire che una delle prime cose che intendo fare, sar\u00e0 quella di instaurarare un rapporto diretto con loro. Lo far\u00f2, coinvolgendo anche Federlazio regionale, perch\u00e9 ritengo si tratti di uomini di grande spessore, in grado di permettere il cambio di passo di questa terra. Colgo l&#8217;occasione per dire che \u00e8 interesse di tutti trovare persone che abbiamo voglia di collaborare allo sviluppo della Ciociaria. Da parte nostra  siamo pronti ad instaurare rapporti sempre pi\u00f9 stetti con i rappresentati di enti ed istituzioni,  anche sulla scia di quanto fatto dai miei predecessori. Tutto ci\u00f2 per far s\u00ec che i nostri associati, ma anche coloro che ancora non ci hanno onorato di far parte della Federlazio, possano trarre i giusti vantaggi nel fare impresa. Non solo a livello personale ma soprattutto per la crecita del Pil locale e, quindi, per una redistribuzione della ricchezza ai cittadini della provincia di Frosinone&#8221;.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Stagnazione,  immobilita&#8217;, recessione. Termini contenuti  nell&#8217;ultima indagine   congiunturale  stilata dalla Federlazio. Poi il Covid. Presidente, come se ne esce? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Se ne esce prima di tutto con un cambio di mentalit\u00e0. Occorre rimettere l&#8217;impresa  produttiva al centro dello sviluppo e cessare di considerare l&#8217;imprenditore uno che sfrutta il lavoro, non paga le  tasse e viola le leggi. Lo sviluppo viene fatto dalle impresa e non dalla pubblica amministrazione. Quest&#8217;ultima deve  predisporre le condizioni affinch\u00e9 il sistema nel suo insieme operi in modo  pi\u00f9  efficiente e possa produrre ricchezza. Gi\u00e0 questo cambio  di cultura dello sviluppo sarebbe un  primo  passo importante&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gi\u00e0 prima dell&#8217;emergenza  sanitaria la strada da  voi indicata era quella di una sorta di shock  economico.  Le azioni del governo  stanno andando    nella giusta direzione? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dalla nostra ultima indagine congiunturale  ad oggi \u00e8 intervenuto un  evento assolutamente  inedito e imprevedibile, il Covid, che ha cambiato completamente  lo scenario. Le risorse  finanziarie ingenti sono quelle che arriveranno dall&#8217;Europa. Alle nostre classi dirigenti spetta ora il  compito di impiegarle in programmi   credibili, seri, utili, che mettano al centro non obiettivi di  mero assistenzialismo ma  azioni volte all&#8217;aumento della produttivit\u00e0 e dell&#8217;efficienza del nostro  sistema produttivo e del  sistema-paese pi\u00f9  in generale.  Gli interventi messi in campo dal Governo e dalla Regione  subito dopo l&#8217;avvento del Covid sono  stati  indubbiamente lodevoli sotto il profilo delle intenzioni. Ci sono state, per\u00f2, alcune disfunzioni sul  piano  dell&#8217;applicazione, come i ritardi nell&#8217;erogazione della cassa integrazione e qualche problema con le banche  nella concessione di quelle risorse stanziate. Ma nell&#8217;insieme, considerando la  portata straordinaria dell&#8217;evento, non  possiamo dire che non sia stato fatto nulla&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Burocrazia e pressione fiscale elevata sono i veri nemici delle aziende. Lo ripetete come  un  mantra. A  suo avviso lo snellimento delle  autorizzazioni e la riduzione delle tasse sono interventi  fondamentali,  oppure,  visto l&#8217;attuale quadro  economico,  non bastano  pi\u00f9? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Non c&#8217;\u00e8 solo una leva da azionare per rilanciare questo paese. Un burocrazia pi\u00f9 produttiva, pi\u00f9  snella e pi\u00f9 efficiente, cos\u00ec come una tassazione pi\u00f9 sostenibile sono naturalmente due prerequisiti fondamentali. Poi ci vogliono infrastrutture che funzionino, un sistema formativo  che  consenta di creare professionalit\u00e0 che servono al mercato   e un meccanismo  di allocazione del  lavoro che consenta  un rapido e tempestivo  incontro tra domanda  e offerta, per evitare che una <br> parte del sistema produttivo ricerchi professionalit\u00e0 che non trova e una parte dell&#8217;offerta di  lavoro sia priva di quelle competenze  necessarie per rispondere  a quella richiesta&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C&#8217;\u00e8 chi, come voi, sollecita che la rotta giusta da seguire sia anche quella di un piano che  preveda grandi investimenti  pubblici. In quali campi bisognerebbe   intervenire in maniera  rapida  e decisa? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Certamente un piano di investimenti pubblici sulle grandi questioni del Paese: infrastrutture  materiali e immateriali, economia  green, digitalizzazione dei processi produttivi, sistema scolastico  e formativo, riforma della giustizia. L&#8217;elenco sarebbe lungo. Certo, se facciamo riferimento al  nostro territorio, possiamo dire che i ritardi della burocrazia ad esempio nel rilascio delle Autorizzazioni  ambientali,  oppure lo stato fatiscente delle infrastrutture stradali in questi anni o  anche   un sistema  di collegamenti ferroviari    assolutamente inadeguato  hanno   avuto la loro parte  nel determinare   la sofferenza di questa  provincia dal punto  di vista economico.   Ora alcuni  interventi sull&#8217;assetto viario che dovrebbe   mettere in campo   l&#8217;Asi e l&#8217;arrivo dell&#8217;alta velocit\u00e0 a  Frosinone  potrebbero   dare  un buon  contributo  ad un percorso   di rilancio del territorio. Oggi la parola d&#8217;ordine \u00e8: rapidit\u00e0&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Carmine Polito, iscritto alla Federlazio fin dalla sua fondazione, ricoprendo nel tempo diversi incarichi, da ieri \u00e8 il nuovo presidente<\/p>\n","protected":false},"author":3,"featured_media":41142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[3121,94,2231,1015,3067],"class_list":["post-41183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-carmine-polito","tag-ciociaria","tag-economia","tag-federlazio","tag-la-provincia-quotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Federlazio, Polito traccia la rotta e invita a un cambio di passo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federlazio, Polito traccia la rotta e invita a un cambio di passo\" \/>\n<meta property=\"og:description\" content=\"Carmine Polito, iscritto alla Federlazio fin dalla sua fondazione, ricoprendo nel tempo diversi incarichi, da ieri \u00e8 il nuovo presidente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-24T10:58:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-24T17:10:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"593\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Federlazio, Polito traccia la rotta e invita a un cambio di passo\",\"datePublished\":\"2020-07-24T10:58:02+00:00\",\"dateModified\":\"2020-07-24T17:10:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/\"},\"wordCount\":886,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/polito.jpg\",\"keywords\":[\"Carmine Polito\",\"Ciociaria\",\"economia\",\"Federlazio\",\"La provincia quotidiano\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/\",\"name\":\"Federlazio, Polito traccia la rotta e invita a un cambio di passo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/polito.jpg\",\"datePublished\":\"2020-07-24T10:58:02+00:00\",\"dateModified\":\"2020-07-24T17:10:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/polito.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/polito.jpg\",\"width\":593,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federlazio, Polito traccia la rotta e invita a un cambio di passo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/24\\\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Federlazio, Polito traccia la rotta e invita a un cambio di passo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/","og_locale":"it_IT","og_type":"article","og_title":"Federlazio, Polito traccia la rotta e invita a un cambio di passo","og_description":"Carmine Polito, iscritto alla Federlazio fin dalla sua fondazione, ricoprendo nel tempo diversi incarichi, da ieri \u00e8 il nuovo presidente","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2020-07-24T10:58:02+00:00","article_modified_time":"2020-07-24T17:10:45+00:00","og_image":[{"width":593,"height":458,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Federlazio, Polito traccia la rotta e invita a un cambio di passo","datePublished":"2020-07-24T10:58:02+00:00","dateModified":"2020-07-24T17:10:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/"},"wordCount":886,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg","keywords":["Carmine Polito","Ciociaria","economia","Federlazio","La provincia quotidiano"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/","name":"Federlazio, Polito traccia la rotta e invita a un cambio di passo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg","datePublished":"2020-07-24T10:58:02+00:00","dateModified":"2020-07-24T17:10:45+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/polito.jpg","width":593,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Federlazio, Polito traccia la rotta e invita a un cambio di passo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/24\/federlazio-polito-traccia-la-rotta-e-invita-a-un-cambio-di-passo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=41183"}],"version-history":[{"count":7,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41183\/revisions"}],"predecessor-version":[{"id":41190,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41183\/revisions\/41190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/41142"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=41183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=41183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=41183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}