{"id":41020,"date":"2020-07-22T10:50:09","date_gmt":"2020-07-22T08:50:09","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=41020"},"modified":"2020-07-22T15:37:15","modified_gmt":"2020-07-22T13:37:15","slug":"sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/","title":{"rendered":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019incontro del sindaco della citt\u00e0 martire con il ministro della Salute, Roberto Speranza,<\/strong> ha suscitato numerose reazioni a Cassino dove il problema dell\u2019ospedale Santa Scolastica \u2013 a cominciare dalla carenza di anestesisti con il blocco degli interventi chirurgici \u2013 mette a dura prova il diritto alla salute dei cittadini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una questione sulla quale, nelle scorse settimane, non sono mancati interventi, anche accesi, da parte dell&#8217;opposizione che ha sollecitato al sindaco azioni decise e risolutive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"352\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/ospedale-santa-scolastica-cassino.jpg\" alt=\"ospedale santa scolastica cassino il corriere della provincia\" class=\"wp-image-21044\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/ospedale-santa-scolastica-cassino.jpg 632w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/ospedale-santa-scolastica-cassino-300x167.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/ospedale-santa-scolastica-cassino-500x278.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno di questi \u00e8 il <strong>consigliere comunale Salvatore Fontana<\/strong> che, in una brevissima dichiarazione, attacca l&#8217;amministrazione Salera, definendo l&#8217;incontro con il ministro Speranza &#8220;inutile&#8221;, dal momento che le competenze in materia di sanit\u00e0 sono in capo alla Regione. Piuttosto, invece,  avrebbe dovuto incontrare l&#8217;assessore regionale alla Sanit\u00e0, Alessio D&#8217;Amato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La notizia che il sindaco sia andato dal ministro della salute \u2013 dice &#8211; \u00e8 una buona notizia, non perch\u00e9 il ministro possa fare qualcosa, la sanit\u00e0 \u00e8 di competenza regionale, ma perch\u00e9, <strong>sembra, che Salera abbia finalmente capito che c\u2019\u00e8 un problema enorme all\u2019ospedale di Cassino<\/strong>&#8230;deve solo, adesso, capire di chi sono competenze e responsabilit\u00e0&#8230;\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consigliere comunale di opposizione di Cassino, Salvatore Fontana, interviene sull&#8217;incontro del sindaco Salera con il ministro della Salute Roberto Speranza<\/p>\n","protected":false},"author":18,"featured_media":10567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,28,11],"tags":[9124,216,94,3273,93,405,2059,345,9127,219,3843,1334],"class_list":["post-41020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-politica","category-salute","tag-anestesisti","tag-cassino","tag-ciociaria","tag-enzo-salera","tag-frosinone","tag-incontro","tag-opposizione","tag-ospedale","tag-roberto-speranza","tag-salute","tag-salvatore-fontana","tag-santa-scolastica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale\" \/>\n<meta property=\"og:description\" content=\"Il consigliere comunale di opposizione di Cassino, Salvatore Fontana, interviene sull&#039;incontro del sindaco Salera con il ministro della Salute Roberto Speranza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-22T08:50:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-22T13:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale\",\"datePublished\":\"2020-07-22T08:50:09+00:00\",\"dateModified\":\"2020-07-22T13:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/\"},\"wordCount\":194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/salvatore-fontana-1.jpg\",\"keywords\":[\"anestesisti\",\"Cassino\",\"Ciociaria\",\"enzo salera\",\"Frosinone\",\"incontro\",\"opposizione\",\"ospedale\",\"roberto speranza\",\"salute\",\"Salvatore Fontana\",\"santa scolastica\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Evidenza\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/\",\"name\":\"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/salvatore-fontana-1.jpg\",\"datePublished\":\"2020-07-22T08:50:09+00:00\",\"dateModified\":\"2020-07-22T13:37:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/salvatore-fontana-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/salvatore-fontana-1.jpg\",\"width\":719,\"height\":379,\"caption\":\"Salvatore Fontana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/22\\\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/","og_locale":"it_IT","og_type":"article","og_title":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale","og_description":"Il consigliere comunale di opposizione di Cassino, Salvatore Fontana, interviene sull'incontro del sindaco Salera con il ministro della Salute Roberto Speranza","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-22T08:50:09+00:00","article_modified_time":"2020-07-22T13:37:15+00:00","og_image":[{"width":719,"height":379,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale","datePublished":"2020-07-22T08:50:09+00:00","dateModified":"2020-07-22T13:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/"},"wordCount":194,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg","keywords":["anestesisti","Cassino","Ciociaria","enzo salera","Frosinone","incontro","opposizione","ospedale","roberto speranza","salute","Salvatore Fontana","santa scolastica"],"articleSection":["*PRIMO PIANO*","Evidenza","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/","name":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg","datePublished":"2020-07-22T08:50:09+00:00","dateModified":"2020-07-22T13:37:15+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/salvatore-fontana-1.jpg","width":719,"height":379,"caption":"Salvatore Fontana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Sanit\u00e0 a Cassino, Fontana: il sindaco faccia incontri utili. La competenza \u00e8 regionale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/22\/sanita-a-cassino-fontana-bene-incontro-con-ministro-ma-capire-responsabilita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=41020"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41020\/revisions"}],"predecessor-version":[{"id":41024,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/41020\/revisions\/41024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10567"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=41020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=41020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=41020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}