{"id":40584,"date":"2020-07-15T11:51:51","date_gmt":"2020-07-15T09:51:51","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=40584"},"modified":"2020-07-15T11:53:33","modified_gmt":"2020-07-15T09:53:33","slug":"frosinone-teatro-in-piazza-in-sicurezza-come-prenotare","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/","title":{"rendered":"Frosinone, teatro in piazza in sicurezza: come prenotare"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L\u2019amministrazione Ottaviani ha confermato, nel programma dell\u2019estate frusinate, il tradizionale appuntamento con il teatro, arricchendolo di performance musicali e momenti di pura comicit\u00e0<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quest\u2019anno, il calendario degli spettacoli, realizzato in collaborazione con Atcl, si terr\u00e0 infatti in piazzale Vittorio Veneto fino al 28 agosto, con inizio alle 21.30 sempre con ingresso rigorosamente gratuito, nel rispetto delle regole di distanziamento sociale.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"374\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/nicola-ottaviani-e1578679573680.jpg\" alt=\"nicola ottaviani sindaco frosinone il corriere della provincia\" class=\"wp-image-26048\" \/><figcaption>Il sindaco di Frosinone Nicola Ottaviani<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento del sindaco<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0&#8220;Per tornare alla normalit\u00e0 &#8211; <strong>ha dichiarato il sindaco di Frosinone Nicola Ottaviani<\/strong> &#8211; non ha senso cancellare completamente la cultura e gli eventi artistici e musicali ormai consolidati, mentre \u00e8 importante abituarsi a vivere e socializzare in condizioni di sicurezza, che devono mutare le nostre abitudini, senza far arretrare il livello della nostra civilt\u00e0&#8221;.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gli appuntamenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Teatro, musica e cabaret tra le porte, organizzato tramite gli assessorati alla cultura e centro storico (coordinati da Valentina Sementilli e Rossella Testa), con il consigliere delegato ai grandi eventi (Gianpiero Fabrizi), <strong>partir\u00e0 gioved\u00ec 16 luglio con Corrado Tedeschi e Antonio Friello <\/strong>nello spettacolo teatrale \u201cLezioni semiserie pirandelliane. L\u2019uomo dal fiore in bocca\u201d. Un classico del grande scrittore siciliano, riletto in chiave inedita: proprio nella coesistenza di due \u201ccorde\u201d contrastanti, comica e tragica, risiede forse uno dei motivi del successo di questo spettacolo,\u00a0in cui Tedeschi offre\u00a0un\u2019interpretazione antiretorica, miscelando dramma, genere grottesco e umoristico. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Venerd\u00ec 17 sar\u00e0 invece di scena Sebastiano Somma<\/strong> con lo spettacolo teatrale \u201cIl vecchio e il mare\u201d tratto dal capolavoro immortale di Ernest Hemingway. Sabato 18 luglio le note invaderanno la piazza con il duo pianoforte e chitarra di Stefano Spallotta e Marco Attura e con le sonorit\u00e0 cantautoriali di Matteo Panetta (direzione artistica Katia Sacchetti). La prima settimana di programmazione si concluder\u00e0<strong> domenica 19 luglio, con lo spettacolo teatrale di e con Fabrizio Giannini <\/strong>dal titolo \u201cSotto casa di Alberto\u201d, un appassionante ed emozionante viaggio nella vita di Alberto Sordi. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ingresso libero con prenotazione telefonica\nobbligatoria, fino ad esaurimento posti, nel rispetto delle norme sanitarie,\nallo 0775\/1893548, nei seguenti giorni e orari: dal luned\u00ec al gioved\u00ec, 9.30 \u2013\n12.30; dal gioved\u00ec alla domenica, 16.30 \u2013 18.30.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il pubblico che avr\u00e0 effettuato la prenotazione sar\u00e0\natteso fino a 15 minuti prima dell&#8217;inizio degli spettacoli, dando la\npossibilit\u00e0 dell&#8217;ingresso nell&#8217;area agli altri spettatori, in caso di assenza,\nsempre allo scopo di garantire il distanziamento sociale, che non potr\u00e0 essere\ninferiore alla misura di un metro.&nbsp;<a href=\"http:\/\/www.comune.frosinone.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.comune.frosinone.it<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019amministrazione Ottaviani ha confermato, nel programma dell\u2019estate frusinate, il tradizionale appuntamento con il teatro, arricchendolo di performance musicali e momenti<\/p>\n","protected":false},"author":18,"featured_media":40585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[94,93,3067,639],"class_list":["post-40584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-ciociaria","tag-frosinone","tag-la-provincia-quotidiano","tag-nicola-ottaviani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, teatro in piazza in sicurezza: come prenotare - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, teatro in piazza in sicurezza: come prenotare\" \/>\n<meta property=\"og:description\" content=\"L\u2019amministrazione Ottaviani ha confermato, nel programma dell\u2019estate frusinate, il tradizionale appuntamento con il teatro, arricchendolo di performance musicali e momenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T09:51:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-15T09:53:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, teatro in piazza in sicurezza: come prenotare\",\"datePublished\":\"2020-07-15T09:51:51+00:00\",\"dateModified\":\"2020-07-15T09:53:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/\"},\"wordCount\":403,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/teatro-300x250-1.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"La provincia quotidiano\",\"nicola ottaviani\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/\",\"name\":\"Frosinone, teatro in piazza in sicurezza: come prenotare - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/teatro-300x250-1.jpg\",\"datePublished\":\"2020-07-15T09:51:51+00:00\",\"dateModified\":\"2020-07-15T09:53:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/teatro-300x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/teatro-300x250-1.jpg\",\"width\":709,\"height\":591},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, teatro in piazza in sicurezza: come prenotare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/15\\\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, teatro in piazza in sicurezza: come prenotare - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, teatro in piazza in sicurezza: come prenotare","og_description":"L\u2019amministrazione Ottaviani ha confermato, nel programma dell\u2019estate frusinate, il tradizionale appuntamento con il teatro, arricchendolo di performance musicali e momenti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-15T09:51:51+00:00","article_modified_time":"2020-07-15T09:53:33+00:00","og_image":[{"width":709,"height":591,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, teatro in piazza in sicurezza: come prenotare","datePublished":"2020-07-15T09:51:51+00:00","dateModified":"2020-07-15T09:53:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/"},"wordCount":403,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg","keywords":["Ciociaria","Frosinone","La provincia quotidiano","nicola ottaviani"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/","name":"Frosinone, teatro in piazza in sicurezza: come prenotare - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg","datePublished":"2020-07-15T09:51:51+00:00","dateModified":"2020-07-15T09:53:33+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/teatro-300x250-1.jpg","width":709,"height":591},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, teatro in piazza in sicurezza: come prenotare"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/15\/frosinone-teatro-in-piazza-in-sicurezza-come-prenotare\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=40584"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40584\/revisions"}],"predecessor-version":[{"id":40588,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40584\/revisions\/40588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/40585"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=40584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=40584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=40584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}