{"id":40412,"date":"2020-07-12T12:46:48","date_gmt":"2020-07-12T10:46:48","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=40412"},"modified":"2020-07-12T12:48:26","modified_gmt":"2020-07-12T10:48:26","slug":"assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/","title":{"rendered":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sette Consorzi, quasi 11.000 km. di canali, 97 impianti irrigui, 90.000 ettari irrigati, 59 impianti idrovori, <\/strong>400 dipendenti, 1.666.000 di ettari come perimetro consortile con 604.00 ettari per quello di bonifica, oltre 307.000 consorziati. I numeri sono forniti da Anbi Lazio, l\u2019associazione che raggruppa i consorzi di bonifica nel Lazio. I Consorzi, anche in piena pandemia, essendo classificati come servizi essenziali, non si sono mai fermati per garantire irrigazione e prevenzione in termini di sicurezza ambientale ed idraulica .<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In molte occasioni vengono criticati. Arrivano i ruoli di pagare, immancabilmente con coda di polemiche e critiche.<\/strong> Ma queste strutture, comunque, sono utili e definite essenziali. In altre Regioni l\u2019appeal con l\u2019utenza,&nbsp; che sono i cittadini e imprese, soprattutto, per essere chiari, \u00e8 stato costruito mattone dopo mattone. Hanno impiegato tempo ma oggi \u00e8 solido. Nel Lazio si fa fatica. Colpa di un passato dove emergevano solo fatti negativi. Invertire il trend si pu\u00f2 e si deve ma insieme . Lo ha capito bene il neo presidente di Anbi Lazio, Sonia Ricci che insieme al direttore Andrea Renna sta lavorando anche su questi temi. Senza proclami, polemiche o annunci.Come \u00e8 giusto che sia.&nbsp;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nei giorni scorsi,&nbsp; in streming,&nbsp; tutte le strutture laziali hanno preso parte, come le altre che operano nel Paese,&nbsp; all\u2019assemblea nazionale di Anbi<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento di Sonia Ricci<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un appuntamento atteso ed importante. Un\u2019assemblea che ha fatto emergere gli scenari dove per il futuro ci si dovr\u00e0 confrontare . \u201cC\u2019\u00e8 bisogno \u2013 <strong>ha detto Sonia Ricci, presidente di Anbi Lazio<\/strong> &#8211; di un nuovo modello di sviluppo, importante per fare l\u2019indispensabile passo avanti, trasformando gli attuali problemi in opportunit\u00e0. Lo sviluppo del territorio dovr\u00e0 essere perno centrale per il rilancio economico del Paese. Nel Lazio, grazie alla sensibilit\u00e0 della Regione e di diversi altri Enti,&nbsp; siamo in sintonia. Stiamo cercando di migliorare lo scenario delle possibilit\u00e0 con un lavoro di squadra con tutti i direttori in sinergia. Grazie al lavoro del direttore di Anbi Lazio, Andrea Renna, il clima di collaborazione e concertazione sta dando le prime risposte d\u2019insieme attese. La sinergia con la sede nazionale aiuta, relazioni e indicazioni del Presidente Nazionale di Anbi, Francesco Vincenzi, e del direttore nazionale, Massimo Gargano, permettono di avere ben chiaro la direzione. Si apre una stagione di fondamentale programmazione per rinnovare il Paese, grazie ad una mole di finanziamenti europei come mai abbiamo visto, ma anche per le opportunit\u00e0 offerte dalla Politica Agricola Comune e dal Green New Deal. Arriveranno fondi importanti per la progettazione come ha sottolineato la Ministra Bellanova Nel Lazio \u2013 conclude Ricci \u2013 dobbiamo farci trovare pronti e , proprio per questo stiamo lavorando.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/Renna-Sacchetti-Gargano.jpg\" alt=\"\" class=\"wp-image-29766\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/Renna-Sacchetti-Gargano.jpg 800w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/Renna-Sacchetti-Gargano-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/Renna-Sacchetti-Gargano-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/Renna-Sacchetti-Gargano-500x375.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A moderare i lavori il direttore <strong>Gargano. A portare il proprio contributo<\/strong>&nbsp;<strong>Teresa Bellanova<\/strong>&nbsp;, Ministra Politiche Agricole Alimentari Forestali;&nbsp;<strong>Giuseppe L\u2019Abbate,<\/strong>&nbsp;Sottosegretario Mi.P.A.A.F.;&nbsp;<strong>Roberto Morassut<\/strong>&nbsp;, Sottosegretario M.A.T.T.M.;&nbsp;<strong>Salvatore Margiotta<\/strong>&nbsp;, Sottosegretario M.I.T.;&nbsp;<strong>Pier Paolo Baretta<\/strong>&nbsp;, Sottosegretario M.E.F.;&nbsp;<strong>Gianpaolo Vallardi<\/strong>&nbsp;, Presidente ComAgri Senato<strong>; Filippo Gallinella<\/strong>&nbsp;, Presidente ComAgri Camera;&nbsp;<strong>Susanna Cenni<\/strong>&nbsp;&nbsp; e&nbsp;<strong>Raffaele Nevi<\/strong>&nbsp;, componenti Commissione Agricoltura Camera;&nbsp;<strong>Paolo Trancassini<\/strong>&nbsp;, componente Commissione Bilancio Camera;&nbsp;<strong>Ettore Prandini<\/strong>&nbsp;, Presidente Coldiretti;&nbsp;<strong>Massimiliano Giansanti<\/strong>&nbsp;, Presidente Confagricoltura;&nbsp;<strong>Giovanni Daghetta<\/strong>&nbsp;, Consigliere Nazionale CIA;&nbsp;<strong>Fabrizio Curcio<\/strong>&nbsp;, Capo Dipartimento Casa Italia;&nbsp;<strong>Giuseppe&nbsp; Blasi<\/strong>&nbsp;, Capo Dipartimento Mi.P.A.A.F.;&nbsp;<strong>Angelica Catalano<\/strong>&nbsp;, Direttore Generale Ufficio Dighe;&nbsp;<strong>Luca Bianchi<\/strong>&nbsp;, Direttore Generale SVIMEZ;&nbsp;<strong>Raffaele Borriello<\/strong>&nbsp;, Direttore Generale ISMEA;&nbsp;<strong>Massimiliano Atelli<\/strong>&nbsp;, Consigliere Presidenza Corte dei Conti;&nbsp;<strong>Erasmo D\u2019Angelis<\/strong>&nbsp;, Segretario Generale Autorit\u00e0 Bacino Appenino Centrale.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole di Renna<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cNel Lazio \u2013 aggiunge Renna \u2013 abbiamo&nbsp; 69 progetti esecutivi e definitivi per la riduzione del rischio idrogeologico<\/strong>. Si guarda con interesse a nuovi progetti per bacini adatti ad impianti fotovoltaici sull\u2019acqua, senza trascurare nuove attivit\u00e0 di manutenzioni senza spezzettare competenze oppure attendere frontisti che non si muovono, da decenni ormai. L\u2019ambito digitale e la semplificazione nella gestione dei dati e il controllo delle situazioni di rischio idraulico restano tra i punti focali. Le disponibilit\u00e0 idriche nel nostro Paese e&nbsp; nel Lazio sono ferme agli anni \u201970. Su questi dobbiamo creare progetti validi. Siccit\u00e0 ed eventi che il clima impazzito propongono vanno contrastati con la prevenzione e non con l\u2019emergenza. New Green Deal ed economia circolare insieme alle buone pratiche da esportare nel Lazio rappresentano le nostre priorit\u00e0&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Solo cos\u00ec \u2013 concludono Ricci e Renna \u2013 daremo risposte a cittadini ed imprese che reclamano attenzione<\/strong> per la sicurezza ambientale ed idrogeologica ma anche la certezza di poter continuare a produrre dando occupazione e provenienza certa delle produzioni&nbsp; che da sempre caratterizzano un Made in Lazio da difendere oggi pi\u00f9 di prima. Insieme.\u201d<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sette Consorzi, quasi 11.000 km. di canali, 97 impianti irrigui, 90.000 ettari irrigati, 59 impianti idrovori, 400 dipendenti, 1.666.000 di<\/p>\n","protected":false},"author":18,"featured_media":38550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,5],"tags":[4511,5234,94,7407,10579,10155],"class_list":["post-40412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-economia","tag-anbi-lazio","tag-andrea-renna","tag-ciociaria","tag-gargano","tag-massimo","tag-sonia-ricci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro\" \/>\n<meta property=\"og:description\" content=\"Sette Consorzi, quasi 11.000 km. di canali, 97 impianti irrigui, 90.000 ettari irrigati, 59 impianti idrovori, 400 dipendenti, 1.666.000 di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-12T10:46:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-12T10:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro\",\"datePublished\":\"2020-07-12T10:46:48+00:00\",\"dateModified\":\"2020-07-12T10:48:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/\"},\"wordCount\":811,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ricci-renna.jpg\",\"keywords\":[\"Anbi Lazio.\",\"andrea renna\",\"Ciociaria\",\"gargano\",\"massimo\",\"sonia ricci\"],\"articleSection\":[\"*SLIDE*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/\",\"name\":\"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ricci-renna.jpg\",\"datePublished\":\"2020-07-12T10:46:48+00:00\",\"dateModified\":\"2020-07-12T10:48:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ricci-renna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/ricci-renna.jpg\",\"width\":758,\"height\":495,\"caption\":\"Sonia Ricci e Andrea Renna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/12\\\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/","og_locale":"it_IT","og_type":"article","og_title":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro","og_description":"Sette Consorzi, quasi 11.000 km. di canali, 97 impianti irrigui, 90.000 ettari irrigati, 59 impianti idrovori, 400 dipendenti, 1.666.000 di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-12T10:46:48+00:00","article_modified_time":"2020-07-12T10:48:26+00:00","og_image":[{"width":758,"height":495,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro","datePublished":"2020-07-12T10:46:48+00:00","dateModified":"2020-07-12T10:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/"},"wordCount":811,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg","keywords":["Anbi Lazio.","andrea renna","Ciociaria","gargano","massimo","sonia ricci"],"articleSection":["*SLIDE*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/","name":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg","datePublished":"2020-07-12T10:46:48+00:00","dateModified":"2020-07-12T10:48:26+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/ricci-renna.jpg","width":758,"height":495,"caption":"Sonia Ricci e Andrea Renna"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Assemblea nazionale Anbi, Lazio presente al webinar che getta le basi per il futuro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/12\/assemblea-nazionale-anbi-lazio-presente-al-webinar-che-getta-le-basi-per-il-futuro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=40412"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40412\/revisions"}],"predecessor-version":[{"id":40414,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/40412\/revisions\/40414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/38550"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=40412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=40412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=40412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}