{"id":4004,"date":"2018-12-29T17:55:46","date_gmt":"2018-12-29T16:55:46","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=4004"},"modified":"2018-12-29T17:57:10","modified_gmt":"2018-12-29T16:57:10","slug":"elezioni-comunali-a-isola-tomaselli-appoggia-mancini","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/","title":{"rendered":"Elezioni comunali a Isola: Tomaselli appoggia Mancini"},"content":{"rendered":"<p>In vista dell&#8217;imminente tornata amministrativa nella citt\u00e0 delle cascate, che porter\u00e0 al rinnovo del consiglio comunale nella prossima primavera, iniziano a delinearsi gli <strong>schieramenti politici<\/strong> che sosterranno i candidati alla carica di sindaco.<\/p>\n<p>Oggi a confermare il suo appoggio all&#8217;avvocato <strong>Diego Mancini<\/strong> \u00e8 il consigliere comunale <strong>Mauro Tomaselli<\/strong> che ne parla con toni assolutamente positivi.<\/p>\n<figure id=\"attachment_4005\" aria-describedby=\"caption-attachment-4005\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4005 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/isola-diego-mancini.jpg\" alt=\"candidato sindaco isola del liri diego mancini frosinone ciociaria\" width=\"600\" height=\"903\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/isola-diego-mancini.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/isola-diego-mancini-199x300.jpg 199w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/isola-diego-mancini-500x753.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-4005\" class=\"wp-caption-text\">Il candidato sindaco di Isola del Liri Diego Mancini<\/figcaption><\/figure>\n<h2>Il sostegno di Tomaselli<\/h2>\n<p>&#8220;Nel corso della sua conferenza stampa \u2013 dice Tomaselli &#8211; ho avuto modo di testare ancora una volta le sue doti morali e professionali nonch\u00e8 le linee programmatiche per lo sviluppo socio-culturale ed economico di Isola del Liri. In particolare \u2013 continua il consigliere &#8211; ho apprezzato la sua signorilit\u00e0 e l&#8217;apertura nei confronti di tutti i cittadini, a prescindere dall&#8217;appartenenza politica e unicamente per il bene superiore della nostra citt\u00e0. Questo rappresenta una garanzia di successo che porter\u00e0 al superamento dei velenosi scontri che hanno caratterizzato gli ultimi anni dell&#8217;amministrazione locale e alla risoluzione di numerosi problemi rimasti incancreniti e irrisolti in tanti, troppi anni&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In vista dell&#8217;imminente tornata amministrativa nella citt\u00e0 delle cascate, che porter\u00e0 al rinnovo del consiglio comunale nella prossima primavera, iniziano<\/p>\n","protected":false},"author":18,"featured_media":4006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1430,1124,1429,581,260,1428,253],"class_list":["post-4004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-amministrative","tag-candidatura","tag-diego-mancini","tag-elezioni-comunali","tag-isola-del-liri","tag-mauro-tomaselli","tag-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elezioni comunali a Isola: Tomaselli appoggia Mancini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni comunali a Isola: Tomaselli appoggia Mancini\" \/>\n<meta property=\"og:description\" content=\"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-29T16:55:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-29T16:57:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Elezioni comunali a Isola: Tomaselli appoggia Mancini\",\"datePublished\":\"2018-12-29T16:55:46+00:00\",\"dateModified\":\"2018-12-29T16:57:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/mauro-tomaselli-isola.jpg\",\"keywords\":[\"amministrative\",\"Candidatura\",\"diego mancini\",\"elezioni comunali\",\"isola del liri\",\"mauro tomaselli\",\"politica\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/\",\"name\":\"Elezioni comunali a Isola: Tomaselli appoggia Mancini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/mauro-tomaselli-isola.jpg\",\"datePublished\":\"2018-12-29T16:55:46+00:00\",\"dateModified\":\"2018-12-29T16:57:10+00:00\",\"description\":\"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/mauro-tomaselli-isola.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/mauro-tomaselli-isola.jpg\",\"width\":620,\"height\":352,\"caption\":\"Mauro Tomaselli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni comunali a Isola: Tomaselli appoggia Mancini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/29\\\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elezioni comunali a Isola: Tomaselli appoggia Mancini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni comunali a Isola: Tomaselli appoggia Mancini","og_description":"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2018-12-29T16:55:46+00:00","article_modified_time":"2018-12-29T16:57:10+00:00","og_image":[{"width":620,"height":352,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Elezioni comunali a Isola: Tomaselli appoggia Mancini","datePublished":"2018-12-29T16:55:46+00:00","dateModified":"2018-12-29T16:57:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg","keywords":["amministrative","Candidatura","diego mancini","elezioni comunali","isola del liri","mauro tomaselli","politica"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/","name":"Elezioni comunali a Isola: Tomaselli appoggia Mancini - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg","datePublished":"2018-12-29T16:55:46+00:00","dateModified":"2018-12-29T16:57:10+00:00","description":"In vista delle imminenti elezioni comunali a Isola del Liri il consigliere Mauro Tomaselli annuncia il proprio appoggio alla candidatura di Diego Mancini.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/mauro-tomaselli-isola.jpg","width":620,"height":352,"caption":"Mauro Tomaselli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Elezioni comunali a Isola: Tomaselli appoggia Mancini"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/29\/elezioni-comunali-a-isola-tomaselli-appoggia-mancini\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/4004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=4004"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/4004\/revisions"}],"predecessor-version":[{"id":4007,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/4004\/revisions\/4007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/4006"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=4004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=4004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=4004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}