{"id":39918,"date":"2020-07-06T14:39:11","date_gmt":"2020-07-06T12:39:11","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=39918"},"modified":"2020-07-06T14:39:14","modified_gmt":"2020-07-06T12:39:14","slug":"ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/","title":{"rendered":"Ferentino Estate 2020: l&#8217;emergenza non ferma la voglia di cultura e divertimento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si terr\u00e0 <strong>domani pomeriggio<\/strong>, alle <strong>ore 17<\/strong>, nella Sala Consiliare del Comune di Ferentino, la conferenza stampa di presentazione degli eventi estivi. Nonostante l&#8217;emergenza Covid-19, per la quale la macchina amministrativa, il sindaco Antonio Pompeo e la sua squadra hanno attivato una poderosa azione di sostegno e supporto alle necessit\u00e0 della popolazione, con particolare riguardo ai nuclei familiari in maggiori difficolt\u00e0, lo sforzo dell&#8217;Amministrazione per offrire serate di svago e di alto valore culturale e artistico non \u00e8 venuto meno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"606\" height=\"300\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/pompeo-schietroma-sonni.jpg\" alt=\"\" class=\"wp-image-39920\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/pompeo-schietroma-sonni.jpg 606w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/pompeo-schietroma-sonni-300x149.jpg 300w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La\nprogrammazione, in forma ridotta rispetto agli anni precedenti\nproprio a causa della situazione legata al virus e in ottemperanza\nalle regole del distanziamento sociale imposte dal Governo, \u00e8 stata\npensata nell&#8217;ottica di coniugare leggerezza e divertimento con la\nsicurezza e il rispetto delle norme anti-Covid. Prenotazione\nobbligatoria, biglietto digitale e nuove modalit\u00e0 per la fruizione\ndegli eventi sono alcune delle misure che l&#8217;Amministrazione Pompeo\nmette in campo per rendere spazi e iniziative il pi\u00f9 agevoli\npossibili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alla\nconferenza stampa, insieme al <strong>sindaco Antonio Pompeo<\/strong>,\nparteciperanno <strong>l&#8217;assessore alla Cultura <\/strong>del Comune di\nFerentino,<strong> Angelica Schietroma<\/strong>; il <strong>presidente della Pro\nLoco, Luigi Sonni<\/strong> e i rappresentanti delle associazione\ncoinvolte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per\nmeglio osservare le misure di sicurezza, la conferenza sar\u00e0\nriservata alla presenza degli organi di stampa, con la possibilit\u00e0\nper tutti di seguire la diretta streaming sul sito istituzionale\ndell&#8217;Ente all&#8217;indirizzo <a href=\"http:\/\/www.comune.ferentino.fr.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.comune.ferentino.fr.it<\/a>\ncliccando sul canale You Tube del Comune di Ferentino e sui canali\nsocial. \n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 domani pomeriggio, alle ore 17, nella Sala Consiliare del Comune di Ferentino, la conferenza stampa di presentazione degli<\/p>\n","protected":false},"author":18,"featured_media":39919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[842,94,5517,92,3067,4434],"class_list":["post-39918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-antonio-pompeo","tag-ciociaria","tag-estate","tag-ferentino","tag-la-provincia-quotidiano","tag-luigi-sonni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ferentino Estate 2020: l&#039;emergenza non ferma la voglia di cultura e divertimento - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferentino Estate 2020: l&#039;emergenza non ferma la voglia di cultura e divertimento\" \/>\n<meta property=\"og:description\" content=\"Si terr\u00e0 domani pomeriggio, alle ore 17, nella Sala Consiliare del Comune di Ferentino, la conferenza stampa di presentazione degli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-06T12:39:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-06T12:39:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"569\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ferentino Estate 2020: l&#8217;emergenza non ferma la voglia di cultura e divertimento\",\"datePublished\":\"2020-07-06T12:39:11+00:00\",\"dateModified\":\"2020-07-06T12:39:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Locandina-conferenza-stampa.jpg\",\"keywords\":[\"antonio pompeo\",\"Ciociaria\",\"estate\",\"ferentino\",\"La provincia quotidiano\",\"Luigi Sonni\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/\",\"name\":\"Ferentino Estate 2020: l'emergenza non ferma la voglia di cultura e divertimento - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Locandina-conferenza-stampa.jpg\",\"datePublished\":\"2020-07-06T12:39:11+00:00\",\"dateModified\":\"2020-07-06T12:39:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Locandina-conferenza-stampa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Locandina-conferenza-stampa.jpg\",\"width\":569,\"height\":272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ferentino Estate 2020: l&#8217;emergenza non ferma la voglia di cultura e divertimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/06\\\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ferentino Estate 2020: l'emergenza non ferma la voglia di cultura e divertimento - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/","og_locale":"it_IT","og_type":"article","og_title":"Ferentino Estate 2020: l'emergenza non ferma la voglia di cultura e divertimento","og_description":"Si terr\u00e0 domani pomeriggio, alle ore 17, nella Sala Consiliare del Comune di Ferentino, la conferenza stampa di presentazione degli","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-06T12:39:11+00:00","article_modified_time":"2020-07-06T12:39:14+00:00","og_image":[{"width":569,"height":272,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ferentino Estate 2020: l&#8217;emergenza non ferma la voglia di cultura e divertimento","datePublished":"2020-07-06T12:39:11+00:00","dateModified":"2020-07-06T12:39:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg","keywords":["antonio pompeo","Ciociaria","estate","ferentino","La provincia quotidiano","Luigi Sonni"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/","name":"Ferentino Estate 2020: l'emergenza non ferma la voglia di cultura e divertimento - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg","datePublished":"2020-07-06T12:39:11+00:00","dateModified":"2020-07-06T12:39:14+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/07\/Locandina-conferenza-stampa.jpg","width":569,"height":272},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ferentino Estate 2020: l&#8217;emergenza non ferma la voglia di cultura e divertimento"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/06\/ferentino-estate-2020-lemergenza-non-ferma-la-voglia-di-cultura-e-divertimento\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=39918"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39918\/revisions"}],"predecessor-version":[{"id":39921,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39918\/revisions\/39921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/39919"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=39918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=39918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=39918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}