{"id":39692,"date":"2020-07-03T10:50:32","date_gmt":"2020-07-03T08:50:32","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=39692"},"modified":"2020-07-03T10:50:36","modified_gmt":"2020-07-03T08:50:36","slug":"frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/","title":{"rendered":"Frosinone, espropri per la riqualificazione urbana dello Scalo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong> La giunta comunale, nell\u2019ultima seduta settimanale, ha approvato la  delibera relativa all\u2019anticipazione di cassa per il pagamento in acconto  (dell&#8217;80%) dell&#8217;indennit\u00e0 ai proprietari <\/strong>delle aree oggetto di  esproprio, ricadenti all\u2019interno del progetto per la riqualificazione  Urbana e la Sicurezza delle Periferie della Citt\u00e0 di Frosinone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T<strong>ra  le opere previste all\u2019interno del Programma (per il quale  l\u2019amministrazione Ottaviani ha ottenuto un finanziamento ministeriale  <\/strong>per un importo complessivo pari ad  17.995.818,81 euro), sono stati  inseriti, infatti, sia i lavori relativi al miglioramento della  sicurezza stradale e piste ciclabili per un importo complessivo di 2.148.351,88 euro, sia i lavori di completamento del verde Pubblico, per un  importo complessivo di \u20ac 1.500.000,00. In quest\u2019ultimo caso, nel quadro  economico \u00e8 prevista, per l&#8217;acquisizione di aree o immobili, la somma  complessiva pari ad \u20ac 382.822,00, mentre per i lavori di miglioramento  della sicurezza stradale e piste ciclabili la somma per l&#8217;acquisizione  di aree o immobili \u00e8 pari ad \u20ac 200.000,00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A tal fine,  l\u2019Amministrazione Comunale ha sottoscritto, lo scorso mese di giugno,  alcuni atti di cessione volontaria<\/strong>. Per il Verde Pubblico, per una  estensione pari a mq 229, con importo di \u20ac 5.725,00; per mq 426, con  importo pari ad \u20ac 10.650,00. Per il Verde Pubblico e Viabilit\u00e0, con mq  3.905 e mq 1.377, l\u2019importo \u00e8 pari ad \u20ac 97.625,00 e ad \u20ac 34.425,00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il  bando per la riqualificazione urbana e la sicurezza, come specificato  nella convenzione, prevede il rimborso delle spese sostenute a fronte  della attestazione dell\u2019avvenuto pagamento degli importi previsti nel  programma dell\u2019Amministrazione;<\/strong> non disponendo della necessaria  liquidit\u00e0 per provvedere ai pagamenti sopra riportati a valere sul  finanziamento disposto dal Programma richiamato in oggetto, si proceder\u00e0  quindi mediante anticipazione di cassa a carico dell\u2019Amministrazione  comunale, provvedendo successivamente al riequilibrio delle somme ad  avvenuto rimborso del contributo concesso, previsto nel secondo semestre  dell\u2019anno. La giunta ha quindi autorizzato l\u2019anticipazione di cassa per  un importo complessivo di \u20ac 118.740,00 di cui \u20ac 91.200,00 per la  realizzazione dei lavori di completamento del verde pubblico ed \u20ac  27.540,00<br>per i lavori per la sicurezza stradale e le piste ciclabili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I<strong>l  primo step del Programma \u00e8 avvenuto nel 2017 con l&#8217;ottenimento, da  parte dell\u2019amministrazione Ottaviani, del finanziamento ministeriale in  risposta al bando per la riqualificazione urbana e la sicurezza delle  periferie delle citt\u00e0 metropolitane e dei comuni capoluogo di Provincia<\/strong>,  nel quale risulta inserito come progetto cardine quello inerente alla  riqualificazione di piazzale Kambo con il concomitante investimento di  Rete Ferroviaria Italiana, per la riqualificazione degli edifici di  propriet\u00e0 e la realizzazione di un sovrappasso pedonale al fine di  incentivare l\u2019utilizzo dei mezzi su ferro.\u00a0 Il Comune, cos\u00ec, ha di fatto  concretizzato la possibilit\u00e0 di operare la ricucitura di due aree  strategiche del Capoluogo attualmente separate dall&#8217;infrastruttura  ferroviaria (la zona edificata in prossimit\u00e0 della chiesa \u201cSacra  Famiglia\u201d risalente al dopoguerra e il nuovo quartiere di Edilizia  Residenziale Pubblica sviluppatosi lungo \u201cCorso Lazio\u201d negli anni \u201980).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In\n riferimento agli interventi finanziati per il Quartiere Scalo, con \ndelibera di giunta \u00e8 stato quindi approvato il progetto definitivo dei \nlavori di riqualificazione e messa in sicurezza dell&#8217;area Stazione, con \nprevisione di pedonalizzazione dell&#8217;intera superficie antistante \nl&#8217;edificio viaggiatori mediante l&#8217;eliminazione della viabilit\u00e0 di \ntransito che attualmente separa lo stesso dalla piazza, e la \nrivisitazione dell&#8217;intero sistema di viabilit\u00e0 dell&#8217;area.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"445\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/battisti-ottaviani.jpg\" alt=\"\" class=\"wp-image-33940\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/battisti-ottaviani.jpg 796w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/battisti-ottaviani-300x168.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/battisti-ottaviani-768x429.jpg 768w\" sizes=\"auto, (max-width: 796px) 100vw, 796px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo  scorso 28 giugno 2019, alla Villa comunale, \u00e8 stato poi firmato il  protocollo d&#8217;intesa alla presenza del sindaco, Nicola Ottaviani,  dell&#8217;amministratore di Ferrovie, Gianfranco Battisti, e del Direttore  Stazioni di RFI, Sara Venturoni,<\/strong> inerente all\u2019iniziativa di  riqualificazione dell&#8217;intero ambito urbano in cui la stazione si  inserisce. Ed \u00e8 anche grazie a quell&#8217;investimento complessivo di circa  30 milioni di euro per il nuovo assetto della stazione e del quartiere,  che le Ferrovie dello Stato hanno deciso di utilizzare la nuova  rivisitazione urbanistica dello Scalo e della stazione, per far fermare i  treni superveloci nel capoluogo, con il Frecciarossa che ha inaugurato  il nuovo corso del trasporto il 14 giugno. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La giunta comunale, nell\u2019ultima seduta settimanale, ha approvato la delibera relativa all\u2019anticipazione di cassa per il pagamento in acconto (dell&#8217;80%)<\/p>\n","protected":false},"author":18,"featured_media":13993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[94,93,639,10464],"class_list":["post-39692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-ciociaria","tag-frosinone","tag-nicola-ottaviani","tag-riqualificazione-scalo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, espropri per la riqualificazione urbana dello Scalo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, espropri per la riqualificazione urbana dello Scalo\" \/>\n<meta property=\"og:description\" content=\"La giunta comunale, nell\u2019ultima seduta settimanale, ha approvato la delibera relativa all\u2019anticipazione di cassa per il pagamento in acconto (dell&#8217;80%)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-03T08:50:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-03T08:50:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, espropri per la riqualificazione urbana dello Scalo\",\"datePublished\":\"2020-07-03T08:50:32+00:00\",\"dateModified\":\"2020-07-03T08:50:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/progetto-stazione-frosinone-e1561739065269.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"nicola ottaviani\",\"riqualificazione scalo\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/\",\"name\":\"Frosinone, espropri per la riqualificazione urbana dello Scalo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/progetto-stazione-frosinone-e1561739065269.jpg\",\"datePublished\":\"2020-07-03T08:50:32+00:00\",\"dateModified\":\"2020-07-03T08:50:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/progetto-stazione-frosinone-e1561739065269.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/06\\\/progetto-stazione-frosinone-e1561739065269.jpg\",\"width\":632,\"height\":355,\"caption\":\"L'area della nuova stazione ferroviaria di Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, espropri per la riqualificazione urbana dello Scalo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/07\\\/03\\\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, espropri per la riqualificazione urbana dello Scalo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, espropri per la riqualificazione urbana dello Scalo","og_description":"La giunta comunale, nell\u2019ultima seduta settimanale, ha approvato la delibera relativa all\u2019anticipazione di cassa per il pagamento in acconto (dell&#8217;80%)","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-07-03T08:50:32+00:00","article_modified_time":"2020-07-03T08:50:36+00:00","og_image":[{"width":632,"height":355,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, espropri per la riqualificazione urbana dello Scalo","datePublished":"2020-07-03T08:50:32+00:00","dateModified":"2020-07-03T08:50:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg","keywords":["Ciociaria","Frosinone","nicola ottaviani","riqualificazione scalo"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/","name":"Frosinone, espropri per la riqualificazione urbana dello Scalo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg","datePublished":"2020-07-03T08:50:32+00:00","dateModified":"2020-07-03T08:50:36+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/06\/progetto-stazione-frosinone-e1561739065269.jpg","width":632,"height":355,"caption":"L'area della nuova stazione ferroviaria di Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, espropri per la riqualificazione urbana dello Scalo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/07\/03\/frosinone-espropri-per-la-riqualificazione-urbana-dello-scalo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=39692"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39692\/revisions"}],"predecessor-version":[{"id":39693,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39692\/revisions\/39693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/13993"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=39692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=39692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=39692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}