{"id":39412,"date":"2020-06-29T18:01:52","date_gmt":"2020-06-29T16:01:52","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=39412"},"modified":"2020-06-29T19:20:16","modified_gmt":"2020-06-29T17:20:16","slug":"lucio-migliorelli-confermato-alla-guida-della-saf","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/","title":{"rendered":"Lucio Migliorelli confermato alla guida della Saf"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Far\u00e0 il bis. <strong>Il presidente della Saf Lucio Migliorelli ha ottenuto il favore dell&#8217;assemblea dei sindaci per il rinnovo.<\/strong> La riunione \u00e8 appena terminata nella sala del Fornaci Village dove, nel rispetto di tutte le misure di sicurezza, i primi cittadini hanno votato affinch\u00e9 il numero uno della Societ\u00e0 Ambiente Frosinone restasse al timone, insieme ai componenti del Cda Marco Di Torrice e Daniela Mancinelli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"447\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/lucio-migliorelli-1.jpg\" alt=\"\" class=\"wp-image-39221\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/lucio-migliorelli-1.jpg 601w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/lucio-migliorelli-1-300x223.jpg 300w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><figcaption>Lucio Migliorelli \u00e8 presidente della Saf dal 2017<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unico voto contrario quello del sindaco di Aquino, Libero Mazzaroppi mentre si sono astenuti Settefrati, Filettino e Casalvieri. La maggioranza ha votato s\u00ec anche al bilancio, che ha registrato solo 5 voti contrari.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il plauso dai Consorzi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Immediate sono arrivate le congratulazioni dei presidenti dei due Consorzi, <strong>a cominciare dal presidente dell&#8217;Asi Francesco De Angelis:<\/strong> &#8220;Congratulazioni  e buon lavoro a Lucio Migliorelli, confermato presidente Saf, e al  nuovo consiglio di amministrazione dell&#8217;Ente. L&#8217;Assemblea  dei sindaci &#8211; spiega &#8211; ha fatto la scelta giusta visto il lavoro svolto da Migliorelli in questi anni. Sono certo che si potr\u00e0 proseguire, di  concerto con i primi cittadini del territorio, nel garantire un servizio  di gestione dei rifiuti innovativo, che punti sull&#8217;economia circolare e  che tuteli l&#8217;ambiente e la salute dei cittadini&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auguri anche <strong>dal presidente del Cosilam, Marco Delle Cese<\/strong>: &#8220;La strada dell\u2019innovazione viene premiata &#8211; ha detto Delle Cese &#8211; Ho appreso con favore la decisione dell\u2019Assemblea dei Soci della Saf di confermare alla presidenza della societ\u00e0 Lucio Migliorelli. In questi anni ha dimostrato grande impegno e massima attenzione puntando all\u2019efficientamento del servizio e all\u2019innovazione dello stesso. Ed \u00e8 giusto proseguire su questa strada che \u00e8 risultata vincente&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gli auguri del presidente del Consiglio regionale Buschini e della consigliera Battisti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A Lucio Migliorelli, rieletto alla presidenza Saf e al nuovo C.d.a. i miei migliori auguri di buon lavoro&#8221; ha detto<strong> il presidente del Consiglio regionale del Lazio, Mauro Buschini.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lucio  &#8211; spiega &#8211; sta lavorando per trasformare il ciclo dei rifiuti in una  visione moderna e green. Tutela dell&#8217;ambiente e nuovo sviluppo in una  ottica di economia circolare sono obiettivi concreti da raggiungere in  un lavoro di raccordo con i sindaci del territorio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La continuit\u00e0 nell&#8217;amministrazione di una societ\u00e0 di cos\u00ec grande rilevanza per la nostra provincia &#8211; commenta<strong> la consigliera regionale del Pd, Sara Battisti<\/strong> &#8211; \u00e8 un plusvalore che permetter\u00e0 di proseguire nell&#8217;importante lavoro iniziato. Ora continuiamo sulla strada dell&#8217;economia circolare dei rifiuti, di un territorio a misura d&#8217;uomo e di ambiente che Lucio aveva iniziato nel precedente mandato, contro i facili populismi e alcune prese di posizione poco responsabili. Buon lavoro!&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il presidente della Provincia Pompeo e l&#8217;auspicio per il futuro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Auguri\nal presidente Lucio Migliorelli e ai componenti del Cda, Daniela\nMancinelli e Marco Di Torrice, confermati alla guida della Saf. Con\nl&#8217;auspicio di poter coniugare sempre il ciclo virtuoso della\nlavorazione dei rifiuti con il rispetto e la salvaguardia di ambiente\ne territorio&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queste le dichiarazioni del<strong> presidente della Provincia, Antonio Pompeo,<\/strong> a margine dell&#8217;assemblea dei sindaci Saf che ha confermato Migliorelli alla presidenza e i due membri del Cda, Mancinelli e Di Torrice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;assemblea dei sindaci della Saf ha votato per il rinnovo di Lucio Migliorelli alla guida della Saf<\/p>\n","protected":false},"author":18,"featured_media":39413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236],"tags":[5494,1904,94,93,3196,82,1601],"class_list":["post-39412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-assemblea-sindaci","tag-cda","tag-ciociaria","tag-frosinone","tag-lucio-migliorelli","tag-presidente","tag-saf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lucio Migliorelli confermato alla guida della Saf - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lucio Migliorelli confermato alla guida della Saf\" \/>\n<meta property=\"og:description\" content=\"L&#039;assemblea dei sindaci della Saf ha votato per il rinnovo di Lucio Migliorelli alla guida della Saf\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-29T16:01:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T17:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"711\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Lucio Migliorelli confermato alla guida della Saf\",\"datePublished\":\"2020-06-29T16:01:52+00:00\",\"dateModified\":\"2020-06-29T17:20:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/saf-fornaci.jpg\",\"keywords\":[\"assemblea sindaci\",\"cda\",\"Ciociaria\",\"Frosinone\",\"Lucio Migliorelli\",\"presidente\",\"Saf\"],\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/\",\"name\":\"Lucio Migliorelli confermato alla guida della Saf - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/saf-fornaci.jpg\",\"datePublished\":\"2020-06-29T16:01:52+00:00\",\"dateModified\":\"2020-06-29T17:20:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/saf-fornaci.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/saf-fornaci.jpg\",\"width\":711,\"height\":469,\"caption\":\"Assemblea sindaci Saf 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lucio Migliorelli confermato alla guida della Saf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/29\\\/lucio-migliorelli-confermato-alla-guida-della-saf\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lucio Migliorelli confermato alla guida della Saf - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/","og_locale":"it_IT","og_type":"article","og_title":"Lucio Migliorelli confermato alla guida della Saf","og_description":"L'assemblea dei sindaci della Saf ha votato per il rinnovo di Lucio Migliorelli alla guida della Saf","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-06-29T16:01:52+00:00","article_modified_time":"2020-06-29T17:20:16+00:00","og_image":[{"width":711,"height":469,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Lucio Migliorelli confermato alla guida della Saf","datePublished":"2020-06-29T16:01:52+00:00","dateModified":"2020-06-29T17:20:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg","keywords":["assemblea sindaci","cda","Ciociaria","Frosinone","Lucio Migliorelli","presidente","Saf"],"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/","name":"Lucio Migliorelli confermato alla guida della Saf - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg","datePublished":"2020-06-29T16:01:52+00:00","dateModified":"2020-06-29T17:20:16+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/saf-fornaci.jpg","width":711,"height":469,"caption":"Assemblea sindaci Saf 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Lucio Migliorelli confermato alla guida della Saf"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/29\/lucio-migliorelli-confermato-alla-guida-della-saf\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=39412"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39412\/revisions"}],"predecessor-version":[{"id":39436,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/39412\/revisions\/39436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/39413"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=39412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=39412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=39412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}