{"id":38599,"date":"2020-06-22T14:22:37","date_gmt":"2020-06-22T12:22:37","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=38599"},"modified":"2020-06-22T14:22:40","modified_gmt":"2020-06-22T12:22:40","slug":"inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/","title":{"rendered":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In tempo di Covid-19 la notizia \u00e8 ancora pi\u00f9 lieta: l&#8217;inaugurazione di una nuova realt\u00e0 imprenditoriale, <strong>nella splendida cornice dell&#8217;Abbazia di Montecassino<\/strong>, \u00e8 certamente un segnale della vivacit\u00e0 e dell&#8217;entusiasmo che i giovani, come <strong>Daniele Miri<\/strong>, sanno ancora esprimere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec questa mattina<strong> \u00e8 stato inaugurato il birrificio dell&#8217;Abbazia di Montecassino<\/strong>, alla presenza di numerose autorit\u00e0 tra cui il numero due di Confindustria, <strong>Maurizio Stirpe<\/strong>; il presidente del Consiglio regionale del Lazio, <strong>Mauro Buschini<\/strong>; il consigliere regionale <strong>Pasquale Ciacciarelli<\/strong>; il presidente di Confimprese Italia, <strong>Guido D&#8217;Amico<\/strong> e il presidente del Cosilam, <strong>Marco Delle Cese<\/strong>, tanto per citarne alcuni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"501\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-taglio-nastro.jpg\" alt=\"\" class=\"wp-image-38600\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-taglio-nastro.jpg 764w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-taglio-nastro-300x197.jpg 300w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><figcaption>Il momento del taglio del nastro<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le dichiarazioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una sfida per l&#8217;intero territorio che ha guadagnato un servizio anche nel tg di Rai Uno andato in onda ieri. &#8220;Un brindisi davvero speciale \u2013 ha detto <strong>il presidente del Consiglio regionale del Lazio, Mauro Buschini<\/strong> \u2013 con questa birra dal sapore antico si guarda alla ripartenza di un territorio e delle sue eccellenze&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"464\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/daniele-miri.jpg\" alt=\"daniele miri cassino il corriere della provincia\" class=\"wp-image-38601\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/daniele-miri.jpg 757w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/daniele-miri-300x184.jpg 300w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><figcaption>L&#8217;imprenditore Daniele Miri<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;In un momento come quello che tutto il Paese sta affrontando \u2013 ha commentato<strong> il presidente del Cosilam, Marco Delle Cese<\/strong> &#8211; l&#8217;apertura di una nuova realt\u00e0 imprenditoriale non pu\u00f2 che essere accolta con entusiasmo. Daniele Miri con impegno, passione e dedizione \u00e8 riuscito a creare una azienda unica che fonde la storia con la tradizione insieme all&#8217;innovazione. \u00c8 da questo connubio che nasce la Birra Montecassino. A lui e a tutta la sua azienda i nostri migliori auguri di un grande successo. Il Consorzio \u00e8 e sar\u00e0 sempre al fianco degli imprenditori per lo sviluppo e la crescita del territori&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"432\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-cassino-delle-cese.jpg\" alt=\"birrificio marco delle cese il corriere della provincia\" class=\"wp-image-38603\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-cassino-delle-cese.jpg 597w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-cassino-delle-cese-300x217.jpg 300w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><figcaption>Daniele Miri con Marco Delle Cese<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugurato questa mattina il birrificio dell&#8217;Abbazia di Montecassino dell&#8217;imprenditore Daniele Miri<\/p>\n","protected":false},"author":18,"featured_media":38602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,5],"tags":[2296,9846,10327,216,94,10328,93,959],"class_list":["post-38599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-economia","tag-abbazia","tag-birra","tag-birrificio","tag-cassino","tag-ciociaria","tag-daniele-miri","tag-frosinone","tag-montecassino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid\" \/>\n<meta property=\"og:description\" content=\"Inaugurato questa mattina il birrificio dell&#039;Abbazia di Montecassino dell&#039;imprenditore Daniele Miri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T12:22:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-22T12:22:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"822\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid\",\"datePublished\":\"2020-06-22T12:22:37+00:00\",\"dateModified\":\"2020-06-22T12:22:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/birrificio-montecassino.jpg\",\"keywords\":[\"abbazia\",\"birra\",\"birrificio\",\"Cassino\",\"Ciociaria\",\"daniele miri\",\"Frosinone\",\"Montecassino\"],\"articleSection\":[\"*SLIDE*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/\",\"name\":\"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/birrificio-montecassino.jpg\",\"datePublished\":\"2020-06-22T12:22:37+00:00\",\"dateModified\":\"2020-06-22T12:22:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/birrificio-montecassino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/birrificio-montecassino.jpg\",\"width\":822,\"height\":482,\"caption\":\"Birrificio di Montecassino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/22\\\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/","og_locale":"it_IT","og_type":"article","og_title":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid","og_description":"Inaugurato questa mattina il birrificio dell'Abbazia di Montecassino dell'imprenditore Daniele Miri","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-06-22T12:22:37+00:00","article_modified_time":"2020-06-22T12:22:40+00:00","og_image":[{"width":822,"height":482,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid","datePublished":"2020-06-22T12:22:37+00:00","dateModified":"2020-06-22T12:22:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg","keywords":["abbazia","birra","birrificio","Cassino","Ciociaria","daniele miri","Frosinone","Montecassino"],"articleSection":["*SLIDE*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/","name":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg","datePublished":"2020-06-22T12:22:37+00:00","dateModified":"2020-06-22T12:22:40+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/birrificio-montecassino.jpg","width":822,"height":482,"caption":"Birrificio di Montecassino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Inaugurato il birrificio di Montecassino: la sfida di Daniele Miri in tempo di Covid"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/22\/inaugurato-il-birrificio-di-montecassino-la-sfida-di-daniele-miri-in-tempo-di-covid\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=38599"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38599\/revisions"}],"predecessor-version":[{"id":38604,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38599\/revisions\/38604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/38602"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=38599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=38599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=38599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}