{"id":38257,"date":"2020-06-17T18:28:06","date_gmt":"2020-06-17T16:28:06","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=38257"},"modified":"2020-06-17T18:28:14","modified_gmt":"2020-06-17T16:28:14","slug":"buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/","title":{"rendered":"Buschini: oltre 62 milioni di euro per far ripartire il cinema"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;Con l\u2019approvazione della legge di riordino su cinema e audiovisivo nel Lazio, <strong>si interviene in modo sistemico riconoscendo lo straordinario valore dell\u2019industria cinematografica <\/strong>che nella nostra Regione rappresenta, oltre ad uno strumento di formazione culturale, un importante veicolo di promozione delle nostre bellezze in Italia e all\u2019estero&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec il <strong>presidente del Consiglio regionale del Lazio, Mauro Buschini<\/strong> in merito all\u2019approvazione nella seduta di Consiglio regionale di oggi della legge n.174 relativa alle &#8216;Disposizioni in materia di cinema e audiovisivo&#8217;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;Tra fondi regionali ed europei \u2013 spiega Buschini \u2013<strong> investiamo oltre 62 milioni nel triennio<\/strong>, risorse ancor pi\u00f9 necessarie in questo momento visto lo stop forzato del settore a causa dell\u2019emergenza sanitaria. Soldi \u2013 conclude &#8211; che contribuiranno alla ripartenza dell&#8217;industria cinematografica che, oltre come spiegato alla grande valenza culturale, genera economia e posti di lavoro nel nostro territorio&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bonafoni: una risposta necessaria al settore<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Obiettivo della proposta regionale approvata oggi \u2013 ha commentato la consigliera <strong>Marta Bonafoni, capogruppo della Lista Civica Zingaretti<\/strong> &#8211; \u00e8 quello di riconoscere e promuovere le attivit\u00e0 cinematografiche e audiovisive come manifestazione dell\u2019espressione artistica a sostegno e a fondamento della cultura, dell\u2019economia e della socialit\u00e0&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"409\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/marta-bonafoni.jpg\" alt=\"marta bonafoni il corriere della provincia\" class=\"wp-image-38259\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/marta-bonafoni.jpg 569w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/marta-bonafoni-300x216.jpg 300w\" sizes=\"auto, (max-width: 569px) 100vw, 569px\" \/><figcaption>La consigliera Marta Bonafoni<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;L&#8217;emergenza sanitaria ed economica scatenata da Covid-19 &#8211; ha concluso &#8211; ha colpito duramente il settore cinematografico e della cultura in generale e fin da subito abbiamo risposto attraverso interventi per supportare il comparto e soprattutto i circa dodicimila lavoratori occupati nel cinema e nell&#8217;audiovisivo nel nostro territorio&#8221;.<br><br> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente del Consiglio regionale del lazio Mauro Buschini annuncia l&#8217;approvazione in Consiglio della legge per finanziare il cinema<\/p>\n","protected":false},"author":18,"featured_media":38258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[94,613,93,10286,1946,7535,1388,918,562],"class_list":["post-38257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-ciociaria","tag-finanziamenti","tag-frosinone","tag-industria-cinematografica","tag-legge","tag-marta-bonafoni","tag-mauro-buschini","tag-nicola-zingaretti","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Buschini: oltre 62 milioni di euro per far ripartire il cinema - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buschini: oltre 62 milioni di euro per far ripartire il cinema\" \/>\n<meta property=\"og:description\" content=\"Il presidente del Consiglio regionale del lazio Mauro Buschini annuncia l&#039;approvazione in Consiglio della legge per finanziare il cinema\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-17T16:28:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-17T16:28:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"471\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Buschini: oltre 62 milioni di euro per far ripartire il cinema\",\"datePublished\":\"2020-06-17T16:28:06+00:00\",\"dateModified\":\"2020-06-17T16:28:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/\"},\"wordCount\":255,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/mauro-buschini.jpg\",\"keywords\":[\"Ciociaria\",\"finanziamenti\",\"Frosinone\",\"industria cinematografica\",\"legge\",\"marta bonafoni\",\"mauro buschini\",\"nicola zingaretti\",\"regione lazio\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/\",\"name\":\"Buschini: oltre 62 milioni di euro per far ripartire il cinema - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/mauro-buschini.jpg\",\"datePublished\":\"2020-06-17T16:28:06+00:00\",\"dateModified\":\"2020-06-17T16:28:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/mauro-buschini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/mauro-buschini.jpg\",\"width\":738,\"height\":471,\"caption\":\"Il presidente del Consiglio regionale del Lazio Mauro Buschini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buschini: oltre 62 milioni di euro per far ripartire il cinema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/17\\\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Buschini: oltre 62 milioni di euro per far ripartire il cinema - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/","og_locale":"it_IT","og_type":"article","og_title":"Buschini: oltre 62 milioni di euro per far ripartire il cinema","og_description":"Il presidente del Consiglio regionale del lazio Mauro Buschini annuncia l'approvazione in Consiglio della legge per finanziare il cinema","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-06-17T16:28:06+00:00","article_modified_time":"2020-06-17T16:28:14+00:00","og_image":[{"width":738,"height":471,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Buschini: oltre 62 milioni di euro per far ripartire il cinema","datePublished":"2020-06-17T16:28:06+00:00","dateModified":"2020-06-17T16:28:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/"},"wordCount":255,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg","keywords":["Ciociaria","finanziamenti","Frosinone","industria cinematografica","legge","marta bonafoni","mauro buschini","nicola zingaretti","regione lazio"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/","name":"Buschini: oltre 62 milioni di euro per far ripartire il cinema - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg","datePublished":"2020-06-17T16:28:06+00:00","dateModified":"2020-06-17T16:28:14+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/mauro-buschini.jpg","width":738,"height":471,"caption":"Il presidente del Consiglio regionale del Lazio Mauro Buschini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Buschini: oltre 62 milioni di euro per far ripartire il cinema"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/17\/buschini-oltre-62-milioni-di-euro-per-far-ripartire-il-cinema\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=38257"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38257\/revisions"}],"predecessor-version":[{"id":38260,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/38257\/revisions\/38260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/38258"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=38257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=38257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=38257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}