{"id":37864,"date":"2020-06-13T07:32:50","date_gmt":"2020-06-13T05:32:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=37864"},"modified":"2020-06-13T07:32:53","modified_gmt":"2020-06-13T05:32:53","slug":"frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/","title":{"rendered":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Nell\u2019ambito delle attivit\u00e0 programmate dall\u2019amministrazione Ottaviani volte alla ottimizzazione dell\u2019attuale servizio di raccolta rifiuti,<\/strong> l\u2019ufficio ambiente, mediante il funzionario, dott. Giuseppe Sarracino, e la polizia locale, coordinata da comandante Donato Mauro, stanno conducendo una serie di verifiche su tutto il territorio comunale per individuare i responsabili dell\u2019abbandono indiscriminato di rifiuti. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La scoperta<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>I dipendenti del Comune, unitamente ai militari dell\u2019Arma e al comando della Polizia municipale, sono intervenuti in via Bellini<\/strong>, <strong>in cui era stata depositata una ingente quantit\u00e0 di rifiuti<\/strong> solidi urbani, senza le modalit\u00e0 della raccolta differenziata, violando le regole sul corretto smaltimento della differenziata e creando intralcio anche alla circolazione stradale. Dopo il rilievo di alcune violazioni che saranno perseguite attraverso l&#8217;elevazione dei relativi verbali, sono state stabilite nuove modalit\u00e0 per disciplinare, in modo ancora pi\u00f9 puntuale, la raccolta differenziata, promuovendo i comportamenti virtuosi e sanzionando coloro che, ancora oggi, continuano a disattendere le disposizioni che permettono il trattamento differenziato, con il metodo del ritiro porta a porta.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"400\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/Massimiliano-Tagliaferri.jpg\" alt=\"\" class=\"wp-image-35823\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/Massimiliano-Tagliaferri.jpg 670w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/Massimiliano-Tagliaferri-300x179.jpg 300w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><figcaption>Massimiliano Tagliaferri<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole dell&#8217;assessore<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cDopo aver superato il 70% con la raccolta\u00a0differenziata,\u00a0con il metodo del porta a porta <\/strong>su tutto il territorio comunale,\u00a0grazie alla grande collaborazione da parte delle famiglie e dei singoli cittadini\u00a0\u2013 <strong>ha dichiarato l\u2019assessore all\u2019ambiente, Massimiliano Tagliaferri \u2013 intendiamo\u00a0proseguire su questa strada,<\/strong> <strong>potenziando ogni attivit\u00e0 volta alla valorizzazione ambientale<\/strong> e alla salvaguardia e alla tutela dell\u2019ecosistema. Senza dimenticare, inoltre, che\u00a0con l\u2019aumentare della percentuale di differenziata, aumenta il risparmio per i cittadini: la\u00a0Tari, nel 2019,\u00a0ha registrato la diminuzione pi\u00f9 sensibile di tutta la Regione Lazio (dati: Cittadinanzattiva), segnando un costo, per i frusinati, inferiore del 13,7\u00a0%. La tariffa media, infatti, \u00e8 scesa da 369 euro a 319 euro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In questi giorni, inoltre, sono in corso le installazioni di fototrappole, in vari punti della citt\u00e0 <\/strong>(compreso il quartiere di via Bellini), in cui si siano verificati episodi di abbandono incontrollato dei rifiuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito delle attivit\u00e0 programmate dall\u2019amministrazione Ottaviani volte alla ottimizzazione dell\u2019attuale servizio di raccolta rifiuti, l\u2019ufficio ambiente, mediante il funzionario, dott.<\/p>\n","protected":false},"author":18,"featured_media":37865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[94,2938,93,2312,639,437,10231],"class_list":["post-37864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-ciociaria","tag-fototrappole","tag-frosinone","tag-massimiliano-tagliaferri","tag-nicola-ottaviani","tag-rifiuti","tag-via-bellini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole\" \/>\n<meta property=\"og:description\" content=\"Nell\u2019ambito delle attivit\u00e0 programmate dall\u2019amministrazione Ottaviani volte alla ottimizzazione dell\u2019attuale servizio di raccolta rifiuti, l\u2019ufficio ambiente, mediante il funzionario, dott.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-13T05:32:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-13T05:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole\",\"datePublished\":\"2020-06-13T05:32:50+00:00\",\"dateModified\":\"2020-06-13T05:32:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/fototrappole.jpg\",\"keywords\":[\"Ciociaria\",\"Fototrappole\",\"Frosinone\",\"massimiliano tagliaferri\",\"nicola ottaviani\",\"rifiuti\",\"via bellini\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/\",\"name\":\"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/fototrappole.jpg\",\"datePublished\":\"2020-06-13T05:32:50+00:00\",\"dateModified\":\"2020-06-13T05:32:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/fototrappole.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/06\\\/fototrappole.jpg\",\"width\":1040,\"height\":546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/13\\\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole","og_description":"Nell\u2019ambito delle attivit\u00e0 programmate dall\u2019amministrazione Ottaviani volte alla ottimizzazione dell\u2019attuale servizio di raccolta rifiuti, l\u2019ufficio ambiente, mediante il funzionario, dott.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-06-13T05:32:50+00:00","article_modified_time":"2020-06-13T05:32:53+00:00","og_image":[{"width":1040,"height":546,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole","datePublished":"2020-06-13T05:32:50+00:00","dateModified":"2020-06-13T05:32:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg","keywords":["Ciociaria","Fototrappole","Frosinone","massimiliano tagliaferri","nicola ottaviani","rifiuti","via bellini"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/","name":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg","datePublished":"2020-06-13T05:32:50+00:00","dateModified":"2020-06-13T05:32:53+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/06\/fototrappole.jpg","width":1040,"height":546},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, rifiuti in via Bellini: interviene il Comune con multe e fototrappole"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/13\/frosinone-rifiuti-in-via-bellini-interviene-il-comune-con-multe-e-fototrappole\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=37864"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37864\/revisions"}],"predecessor-version":[{"id":37866,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37864\/revisions\/37866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/37865"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=37864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=37864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=37864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}