{"id":37477,"date":"2020-06-09T07:42:07","date_gmt":"2020-06-09T05:42:07","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=37477"},"modified":"2020-06-09T15:20:25","modified_gmt":"2020-06-09T13:20:25","slug":"mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/","title":{"rendered":"Mancanza di camici, guanti e divise al &#8216;Santa Scolastica&#8217;, la Uil-Fpl  sollecita la Asl"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>Importanti criticit\u00e0 relative alla fornitura al personale dei DPI per il COVID-19<\/strong>. Mancano camici ordinari, guanti e divise per medici e infermieri dell&#8217;ospedale S. Scolastica di Cassino&#8221;.  <strong>\u00c8  quanto evidenzia Guido Compagnone, delegato Uil Fpl,  in una lettera inviata alla dg facente funzioni della Asl di Frosinone. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;L&#8217;organizzazione sindacale &#8211; fa notare Compagnone  &#8211;  ha gi\u00e0 evidenziato tali problematiche e ritiene doveroso che la Asl risponda a una serie di quesiti . <\/strong>Per prima cosa se \u00e8 a conoscenza dell&#8217;amministrazione ogni specifica tecnica dei DPI e se essa sia in atti riscontrabile con le relazioni del fornitore o del produttore, o di qualunque altro soggetto ad esso deputato dalla legge. Inoltre per quale motivo spesso i DPI camici siano addirittura mancanti presso ospedale, come anche i camici ordinari, guanti e divise. Tanto \u00e8 che da circa quindici giorni il personale non riceve il cambio divise, e il dipendente \u00e8 costretto a riutilizzare sempre la stessa, lavandola in proprio. La condizione, oltre che vergognosa, contraddice le norme in materia di sicurezza sul lavoro (rischio biologico e diffusione contagio) come da DLgs 81-08&#8243;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Uil Fpl, in una precedente lettera, aveva espressamente sottolineato che <\/strong>&#8220;la particolarit\u00e0 e la delicatezza della questione esige risposte precise e puntuali, evitando circonlocuzioni e reticenze, attenendosi strettamente ai fatti tecnico giuridici esposti e fornendo risposte nette ed esaustive sui quesiti esattamente come formulati. E che per le medesime ragioni il riscontro ai quesiti deve essere tempestivo, e in ogni caso entro i sette giorni dall&#8217;ultima nota del 25.5.2020. In caso di incongrua o peggio ancora omessa risposta la UIL FPL, nel poter cos\u00ec presumere ragionevolmente la non idoneit\u00e0 dei DPI, come la incongruit\u00e0 della causa della mancanza per medici e infermieri di camici ordinari, guanti e divise,  andr\u00e0 a segnalare i fatti presso le sedi di competenza&#8221;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Tale  materia &#8211; conclude Compagnone &#8211;  rientra, tra le altre cose ma non solo, nelle norme sulla sicurezza sul lavoro <\/strong>del Decreto Legislativo 81-09, e questo dimostra la gravit\u00e0 e l&#8217;impellenza della questione.&nbsp; Dato che l&#8217;amministrazione, decorso il termine ha omesso di rispondere, la Uil Fplprima prima di segnalare i fatti presso le sedi di competenza,  sollecita l&#8217;ASL a chiarire i quesiti posti, concedendo ulteriori cinque giorni&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Importanti criticit\u00e0 relative alla fornitura al personale dei DPI per il COVID-19. Mancano camici ordinari, guanti e divise per medici<\/p>\n","protected":false},"author":18,"featured_media":3709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,11],"tags":[216,94,9024,10154,868,10174,4896,940,10153],"class_list":["post-37477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-salute","tag-cassino","tag-ciociaria","tag-guanti","tag-guido-compagnone","tag-infermieri","tag-mancanza-di-dpi","tag-mascherine","tag-medici","tag-uil-fpl"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mancanza di camici, guanti e divise al &#039;Santa Scolastica&#039;, la Uil-Fpl sollecita la Asl - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mancanza di camici, guanti e divise al &#039;Santa Scolastica&#039;, la Uil-Fpl sollecita la Asl\" \/>\n<meta property=\"og:description\" content=\"&#8220;Importanti criticit\u00e0 relative alla fornitura al personale dei DPI per il COVID-19. Mancano camici ordinari, guanti e divise per medici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-09T05:42:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T13:20:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Mancanza di camici, guanti e divise al &#8216;Santa Scolastica&#8217;, la Uil-Fpl sollecita la Asl\",\"datePublished\":\"2020-06-09T05:42:07+00:00\",\"dateModified\":\"2020-06-09T13:20:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"guanti\",\"guido compagnone\",\"Infermieri\",\"mancanza di dpi\",\"mascherine\",\"Medici\",\"uil fpl\"],\"articleSection\":[\"Attualit\u00e0\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/\",\"name\":\"Mancanza di camici, guanti e divise al 'Santa Scolastica', la Uil-Fpl sollecita la Asl - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"datePublished\":\"2020-06-09T05:42:07+00:00\",\"dateModified\":\"2020-06-09T13:20:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"width\":632,\"height\":352,\"caption\":\"L'ospedale Santa Scolastica di Cassino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mancanza di camici, guanti e divise al &#8216;Santa Scolastica&#8217;, la Uil-Fpl sollecita la Asl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/06\\\/09\\\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mancanza di camici, guanti e divise al 'Santa Scolastica', la Uil-Fpl sollecita la Asl - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/","og_locale":"it_IT","og_type":"article","og_title":"Mancanza di camici, guanti e divise al 'Santa Scolastica', la Uil-Fpl sollecita la Asl","og_description":"&#8220;Importanti criticit\u00e0 relative alla fornitura al personale dei DPI per il COVID-19. Mancano camici ordinari, guanti e divise per medici","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-06-09T05:42:07+00:00","article_modified_time":"2020-06-09T13:20:25+00:00","og_image":[{"width":632,"height":352,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Mancanza di camici, guanti e divise al &#8216;Santa Scolastica&#8217;, la Uil-Fpl sollecita la Asl","datePublished":"2020-06-09T05:42:07+00:00","dateModified":"2020-06-09T13:20:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","keywords":["Cassino","Ciociaria","guanti","guido compagnone","Infermieri","mancanza di dpi","mascherine","Medici","uil fpl"],"articleSection":["Attualit\u00e0","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/","name":"Mancanza di camici, guanti e divise al 'Santa Scolastica', la Uil-Fpl sollecita la Asl - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","datePublished":"2020-06-09T05:42:07+00:00","dateModified":"2020-06-09T13:20:25+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","width":632,"height":352,"caption":"L'ospedale Santa Scolastica di Cassino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Mancanza di camici, guanti e divise al &#8216;Santa Scolastica&#8217;, la Uil-Fpl sollecita la Asl"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/06\/09\/mancanza-di-camici-guanti-e-divise-al-santa-scolastica-la-uil-fpl-sollecita-la-asl\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=37477"}],"version-history":[{"count":8,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37477\/revisions"}],"predecessor-version":[{"id":37531,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/37477\/revisions\/37531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3709"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=37477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=37477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=37477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}