{"id":36118,"date":"2020-05-23T08:02:30","date_gmt":"2020-05-23T06:02:30","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=36118"},"modified":"2020-05-23T08:18:41","modified_gmt":"2020-05-23T06:18:41","slug":"cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/","title":{"rendered":"Cassino, spostamento del mercato dell&#8217;abbigliamento: 5 consiglieri a sostegno degli ambulanti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> &#8220;<strong>Lo spostamento del mercato dell&#8217;abbigliamento dall&#8217;area di piazza Miranda al centro di Cassino, sta creando non pochi disagi agli ambulanti <\/strong>che, ormai da tempo, avevano sperimentato in maniera positiva gli spazi che la stessa piazza offre&#8221;.  Lo evidenziano i consiglieri comunali Giuseppe Golini Petrarcone, Michelina Bevilacqua, Salvatore Fontana, Massimiliano Mignanelli  e Mario Abbruzzese. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La decisione del sindaco di trasferire banchi e bancerelle nella vecchia e caotica posizione,<\/strong> tra vie e palazzi e soprattutto assegnando posti non secondo l&#8217;anzianit\u00e0 della licenza, come regola vuole, ma con altri metodi, ha indispettito i tanti commercianti che ogni sabato arrivano a Cassino. La presenza di una delegazione di ambulanti,  sotto al Comune, \u00e8 la prova provata di quanto la decisione sia stata presa in maniera avventata e priva di consenso. Nei giorni scorsi il malumore era scaturito in un&#8217;aggressione verbale a danno di un sindacalista&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;I rappresentanti della categoria  riuniti seppur distanziati sotto le finestre del palazzo comunale, hanno lamentato &#8216;incontri face to face&#8217;<\/strong> tra alcuni consiglieri comunali di maggioranza e ambulanti, senza una motivazione logica e senza che nessuno fosse stato ufficialmente convocato. Quello che noi della minoranza intendiamo capire \u00e8 il motivo per cui l&#8217;area di piazza Miranda (tra l&#8217;altro approvata anche dall&#8217;attuale sindaco quando l&#8217;assessore al commercio era il professor Costa nella giunta Petrarcone) improvvisamente \u00e8 divenuta inadeguata. E soprattutto inadeguata in un momento storico dove gli spazi sono cosa essenziale. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Perch\u00e9 accalcare nuovamente banchi e furgoni?<\/strong> La citt\u00e0 e gli ambulanti che sono l&#8217;anima dell&#8217;economia nel fine settimana aspettano una risposta chiara e soprattutto a stretto giro. Basta che questo modo di fare prepotente e anti democratico come se il Comune non fosse un bene comune ma semplicemente casa propria&#8221;.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lo spostamento del mercato dell&#8217;abbigliamento dall&#8217;area di piazza Miranda al centro di Cassino, sta creando non pochi disagi agli ambulanti<\/p>\n","protected":false},"author":18,"featured_media":6765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[216,94,3273,8508,3843],"class_list":["post-36118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-cassino","tag-ciociaria","tag-enzo-salera","tag-mercato","tag-salvatore-fontana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cassino, spostamento del mercato dell&#039;abbigliamento: 5 consiglieri a sostegno degli ambulanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassino, spostamento del mercato dell&#039;abbigliamento: 5 consiglieri a sostegno degli ambulanti\" \/>\n<meta property=\"og:description\" content=\"&#8220;Lo spostamento del mercato dell&#8217;abbigliamento dall&#8217;area di piazza Miranda al centro di Cassino, sta creando non pochi disagi agli ambulanti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-23T06:02:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-23T06:18:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Cassino, spostamento del mercato dell&#8217;abbigliamento: 5 consiglieri a sostegno degli ambulanti\",\"datePublished\":\"2020-05-23T06:02:30+00:00\",\"dateModified\":\"2020-05-23T06:18:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/comune-cassino-e1550496669833.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"enzo salera\",\"mercato\",\"Salvatore Fontana\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/\",\"name\":\"Cassino, spostamento del mercato dell'abbigliamento: 5 consiglieri a sostegno degli ambulanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/comune-cassino-e1550496669833.jpg\",\"datePublished\":\"2020-05-23T06:02:30+00:00\",\"dateModified\":\"2020-05-23T06:18:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/comune-cassino-e1550496669833.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/comune-cassino-e1550496669833.jpg\",\"width\":632,\"height\":434,\"caption\":\"Municipio di Cassino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassino, spostamento del mercato dell&#8217;abbigliamento: 5 consiglieri a sostegno degli ambulanti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/23\\\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cassino, spostamento del mercato dell'abbigliamento: 5 consiglieri a sostegno degli ambulanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/","og_locale":"it_IT","og_type":"article","og_title":"Cassino, spostamento del mercato dell'abbigliamento: 5 consiglieri a sostegno degli ambulanti","og_description":"&#8220;Lo spostamento del mercato dell&#8217;abbigliamento dall&#8217;area di piazza Miranda al centro di Cassino, sta creando non pochi disagi agli ambulanti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-05-23T06:02:30+00:00","article_modified_time":"2020-05-23T06:18:41+00:00","og_image":[{"width":632,"height":434,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Cassino, spostamento del mercato dell&#8217;abbigliamento: 5 consiglieri a sostegno degli ambulanti","datePublished":"2020-05-23T06:02:30+00:00","dateModified":"2020-05-23T06:18:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg","keywords":["Cassino","Ciociaria","enzo salera","mercato","Salvatore Fontana"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/","name":"Cassino, spostamento del mercato dell'abbigliamento: 5 consiglieri a sostegno degli ambulanti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg","datePublished":"2020-05-23T06:02:30+00:00","dateModified":"2020-05-23T06:18:41+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/comune-cassino-e1550496669833.jpg","width":632,"height":434,"caption":"Municipio di Cassino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Cassino, spostamento del mercato dell&#8217;abbigliamento: 5 consiglieri a sostegno degli ambulanti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/23\/cassino-spostamento-del-mercato-dellabbigliamento-5-consiglieri-a-sostegno-degli-ambulanti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/36118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=36118"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/36118\/revisions"}],"predecessor-version":[{"id":36119,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/36118\/revisions\/36119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/6765"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=36118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=36118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=36118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}