{"id":35805,"date":"2020-05-19T11:07:44","date_gmt":"2020-05-19T09:07:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=35805"},"modified":"2020-05-19T11:14:49","modified_gmt":"2020-05-19T09:14:49","slug":"percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/","title":{"rendered":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di  9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>I Finanzieri del Comando Provinciale di Frosinone, <\/strong>nell\u2019ambito di specifiche attivit\u00e0 finalizzate al contrasto degli illeciti in materia di spesa pubblica e alle prestazioni sociali agevolate, <strong>hanno denunciato un cittadino italiano \u2013 un settantenne residente nell\u2019hinterland di Anagn<\/strong>i -, il quale beneficiava della pensione integrativa di cittadinanza senza averne diritto.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni-1024x768.jpg\" alt=\"\" class=\"wp-image-35808\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni-1024x768.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni-1536x1152.jpg 1536w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/finanza-anagni.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;indagine<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In particolare, l\u2019attivit\u00e0 investigativa condotta dalla Fiamme Gialle della citt\u00e0 dei Papi, <\/strong>scaturita dal monitoraggio di tutti coloro che beneficiano della prestazione assistenziale, ha consentito di rilevare che il soggetto individuato, percettore della pensione integrativa di cittadinanza per circa 200 euro al mese per il periodo a far data da maggio 2019, era legale rappresentante di ben 9 societ\u00e0 e titolare delle quote di maggioranza, del valore di circa 90.000 euro, di altre 7 societ\u00e0, tutte ubicate in Roma.\u00a0 L\u2019illecita percezione della pensione integrativa di cittadinanza, da parte del settantenne ciociaro, \u00e8 stata <strong>ottenuta mediante la falsa dichiarazione,<\/strong> nell\u2019istanza presentata all\u2019Inps, dei valori e delle possidenze mobiliari, in maniera da aggirare i divieti imposti della norma.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il provvedimento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il percettore della pensione integrativa \u00e8 stato denunciato all\u2019Autorit\u00e0 Giudiziaria <\/strong>del capoluogo per aver fornito in sede di presentazione dell\u2019istanza per l\u2019ottenimento del contributo dichiarazioni false o attestanti cose non vere, con contestuale proposta di sequestro preventivo dell\u2019importo illecitamente percepito.\u00a0 In ultimo, la rilevata situazione illecita \u00e8 stata segnalata all\u2019INPS di Frosinone per la decadenza del beneficio e la successiva attivit\u00e0 di recupero delle somme di denaro indebitamente percepite dal reo.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La pensione integrativa di cittadinanza rappresenta una forma di sostegno per quanti concretamente hanno bisogno di assistenz<\/strong>a, motivo per cui la Guardia di Finanza \u00e8 impegnata in prima linea a contrastare fenomeni di indebito accesso al beneficio, affinch\u00e9 le risorse economiche pubbliche possano essere spese correttamente ed indirizzate ai cittadini onesti, in questo caso bisognosi di aiuto da parte dello Stato.\u00a0<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Finanzieri del Comando Provinciale di Frosinone, nell\u2019ambito di specifiche attivit\u00e0 finalizzate al contrasto degli illeciti in materia di spesa<\/p>\n","protected":false},"author":18,"featured_media":6076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[2849,94,93,1380,2530],"class_list":["post-35805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-amministratore","tag-ciociaria","tag-frosinone","tag-guardia-di-finanza","tag-reddito-cittadinanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9\" \/>\n<meta property=\"og:description\" content=\"I Finanzieri del Comando Provinciale di Frosinone, nell\u2019ambito di specifiche attivit\u00e0 finalizzate al contrasto degli illeciti in materia di spesa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T09:07:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-19T09:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"598\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9\",\"datePublished\":\"2020-05-19T09:07:44+00:00\",\"dateModified\":\"2020-05-19T09:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/finanza-frosinone.jpg\",\"keywords\":[\"amministratore\",\"Ciociaria\",\"Frosinone\",\"guardia di finanza\",\"reddito cittadinanza\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/\",\"name\":\"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/finanza-frosinone.jpg\",\"datePublished\":\"2020-05-19T09:07:44+00:00\",\"dateModified\":\"2020-05-19T09:14:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/finanza-frosinone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/finanza-frosinone.jpg\",\"width\":598,\"height\":456,\"caption\":\"La sede del Comando provinciale di Frosinone in piazza Risorgimento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/19\\\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/","og_locale":"it_IT","og_type":"article","og_title":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9","og_description":"I Finanzieri del Comando Provinciale di Frosinone, nell\u2019ambito di specifiche attivit\u00e0 finalizzate al contrasto degli illeciti in materia di spesa","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-05-19T09:07:44+00:00","article_modified_time":"2020-05-19T09:14:49+00:00","og_image":[{"width":598,"height":456,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9","datePublished":"2020-05-19T09:07:44+00:00","dateModified":"2020-05-19T09:14:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg","keywords":["amministratore","Ciociaria","Frosinone","guardia di finanza","reddito cittadinanza"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/","name":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg","datePublished":"2020-05-19T09:07:44+00:00","dateModified":"2020-05-19T09:14:49+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/finanza-frosinone.jpg","width":598,"height":456,"caption":"La sede del Comando provinciale di Frosinone in piazza Risorgimento"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Percepiva il reddito di cittadinanza ma era titolare di 7 societ\u00e0 e amministratore di 9"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/19\/percepiva-il-reddito-di-cittadinanza-ma-era-titolare-di-7-societa-e-amministratore-di-9\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=35805"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35805\/revisions"}],"predecessor-version":[{"id":35809,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35805\/revisions\/35809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/6076"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=35805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=35805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=35805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}