{"id":35536,"date":"2020-05-15T07:29:29","date_gmt":"2020-05-15T05:29:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=35536"},"modified":"2020-05-15T07:29:49","modified_gmt":"2020-05-15T05:29:49","slug":"frosinone-via-libera-alla-rinegoziazione-dei-mutui","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/","title":{"rendered":"Frosinone, via libera alla rinegoziazione dei mutui"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> <strong>Il consiglio comunale di Frosinone ha approvato alla unanimit\u00e0 la delibera, <\/strong>portata in aula dall\u2019assessorato al bilancio e alle finanze, coordinato da Riccardo Mastrangeli, circa la <strong>rinegoziazione per l\u2019anno 2020 di prestiti concessi al Comune di Frosinone <\/strong>dalla Cassa Depositi e Prestiti SpA. L\u2019operazione, infatti, doveva essere autorizzata con una deliberazione dell\u2019assise esecutiva a tutti gli effetti di legge da comunicare alla CDP SpA entro il termine perentorio del 03\/06\/2020.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLa CDP SpA \u2013 ha spiegato Mastrangeli &#8211; si \u00e8 resa disponibile alla rinegoziazione per l\u2019anno 2020<\/strong> dei prestiti in ammortamento al 01\/01\/2020 concessi ai Comuni inclusi quelli gi\u00e0 oggetto di precedenti programmi di rinegoziazione, alle condizioni e nei termini e con le modalit\u00e0 definite dalla Circolare n. 1300 del 23\/04\/2020. La rinegoziazione proposta consente, anche nell\u2019attuale situazione finanziaria determinata dalla contrazione delle entrate e dalla necessit\u00e0 di far fronte ai nuovi impegni finanziari determinati dall\u2019attuale situazione emergenziale causata dalla pandemia da Covid 19, di liberare risorse consistenti per l\u2019amministrazione&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;L\u2019ente \u2013 ha proseguito &#8211; intende selezionare tutti i prestiti originari concessi previsti dall\u2019applicativo informatico gestionale messo a disposizione da CDP Sp<\/strong>A ed aventi le caratteristiche seguenti: prestiti ordinari e flessibili, a tasso fisso o variabile; oneri di ammortamento interamente a carico dell\u2019Ente beneficiario; in ammortamento al 1\u00b0 gennaio 2020, con debito residuo a tale data maggiore o uguale a EUR 10.000,00 e scadenza successiva al 31 dicembre 2020. La durata dei prestiti rinegoziati viene allungata fino al 2043 (tranne che per quelli la cui scadenza originaria \u00e8 uguale o successiva al 31 dicembre 2043, la cui durata resta invariata); al 31 luglio 2020 \u00e8 fissata la corresponsione della quota interessi maturata nel primo semestre 2020, calcolata al tasso di interesse applicabile ai prestiti ante rinegoziazione; al 31 dicembre 2020 \u00e8 fissata quella di una rata comprensiva di una quota capitale, pari allo 0,25% del debito residuo in essere alla data del 1\u00b0 gennaio 2020, e di una quota interessi calcolata in base al nuovo tasso di interesse fisso post rinegoziazione individuato secondo un criterio di equivalenza finanziaria. Dal 30 giugno 2021 fino alla scadenza \u00e8 fissata infine la corresponsione di rate semestrali costanti posticipate (comprensive di quota capitale e di quota interessi), calcolate al tasso di interesse fisso post rinegoziazione (piano di ammortamento \u201cfrancese\u201d)\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Il tasso di interesse per l\u2019operazione proposta \u00e8 determinato per ciascun prestito originario in condizioni di equivalenza finanziari<\/strong>a adeguando i flussi finanziari dei prestiti originari alle condizioni di tasso di interesse dei nuovi prestiti concessi da CDP tenendo conto della nuova data di scadenza dei prestiti rinegoziati. \u201cLe economie derivanti dal minore esborso annuale in linea capitale, conseguente alla rinegoziazione del debito \u2013 ha concluso l\u2019assessore Mastrangeli &#8211; consentono una pi\u00f9 efficace gestione attiva del debito non avendo particolari vincoli di destinazione.\u00a0La rinegoziazione consente un notevole risparmio di risorse finanziarie per la ridefinizione della quota capitale dei prestiti rinegoziati. Un\u2019operazione, questa, ad equivalenza finanziaria, che non comporta cio\u00e8 nuovi oneri: anzi, la ridistribuzione delle rate su periodi pi\u00f9 lunghi determina un consistente risparmio di spesa per interessi negli esercizi futuri e per quest\u2019anno ci consente il risparmio della quota capitale da versare al 30\/06\/2020 ed al 31\/12\/2020 liberando risorse finanziarie da destinare, come detto, al finanziamento\u00a0del bilancio senza vincoli di destinazione&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Anche questo risultato evidenzia l\u2019enorme lavoro di squadra e di razionalizzazione compiuto<\/strong>,\u00a0 negli ultimi anni, dal Comune di Frosinone,\u00a0seguendo le linee di indirizzo del sindaco, Nicola Ottaviani: il\u00a0nostro capoluogo, evitando il dissesto finanziario ma continuando in una politica oculata degli investimenti, \u00e8 tra le migliori posizioni nella classifica delle citt\u00e0 italiane pi\u00f9 virtuose, come certificato dalla sezione autonomie della Corte dei Conti. Ci\u00f2 \u00e8 accaduto nonostante le difficolt\u00e0 di manovra dell\u2019Ente, sottoposto a un oneroso piano di rientro dal debito dal 2013, oltre che colpito dai sensibili tagli operati sulle casse da Regione e Governo centrale. L\u2019obiettivo dell\u2019amministrazione \u00e8 proseguire su questa direzione per raggiungere traguardi ancora pi\u00f9 importanti, continuando a garantire l\u2019alta qualit\u00e0 dei servizi e mettendo in atto tutti gli accorgimenti normativi che possano venire incontro alle esigenze dei cittadini di Frosinone&#8221;. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consiglio comunale di Frosinone ha approvato alla unanimit\u00e0 la delibera, portata in aula dall\u2019assessorato al bilancio e alle finanze,<\/p>\n","protected":false},"author":18,"featured_media":35537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[94,721,93,639,2033],"class_list":["post-35536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-ciociaria","tag-consiglio-comunale","tag-frosinone","tag-nicola-ottaviani","tag-riccardo-mastrangeli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, via libera alla rinegoziazione dei mutui - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, via libera alla rinegoziazione dei mutui\" \/>\n<meta property=\"og:description\" content=\"Il consiglio comunale di Frosinone ha approvato alla unanimit\u00e0 la delibera, portata in aula dall\u2019assessorato al bilancio e alle finanze,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-15T05:29:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-15T05:29:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"877\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Frosinone, via libera alla rinegoziazione dei mutui\",\"datePublished\":\"2020-05-15T05:29:29+00:00\",\"dateModified\":\"2020-05-15T05:29:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/\"},\"wordCount\":663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/consiglio-comunale-mascherine.jpg\",\"keywords\":[\"Ciociaria\",\"consiglio comunale\",\"Frosinone\",\"nicola ottaviani\",\"riccardo mastrangeli\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/\",\"name\":\"Frosinone, via libera alla rinegoziazione dei mutui - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/consiglio-comunale-mascherine.jpg\",\"datePublished\":\"2020-05-15T05:29:29+00:00\",\"dateModified\":\"2020-05-15T05:29:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/consiglio-comunale-mascherine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/consiglio-comunale-mascherine.jpg\",\"width\":1024,\"height\":877},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, via libera alla rinegoziazione dei mutui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/15\\\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, via libera alla rinegoziazione dei mutui - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, via libera alla rinegoziazione dei mutui","og_description":"Il consiglio comunale di Frosinone ha approvato alla unanimit\u00e0 la delibera, portata in aula dall\u2019assessorato al bilancio e alle finanze,","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-05-15T05:29:29+00:00","article_modified_time":"2020-05-15T05:29:49+00:00","og_image":[{"width":1024,"height":877,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Frosinone, via libera alla rinegoziazione dei mutui","datePublished":"2020-05-15T05:29:29+00:00","dateModified":"2020-05-15T05:29:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/"},"wordCount":663,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg","keywords":["Ciociaria","consiglio comunale","Frosinone","nicola ottaviani","riccardo mastrangeli"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/","name":"Frosinone, via libera alla rinegoziazione dei mutui - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg","datePublished":"2020-05-15T05:29:29+00:00","dateModified":"2020-05-15T05:29:49+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/consiglio-comunale-mascherine.jpg","width":1024,"height":877},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, via libera alla rinegoziazione dei mutui"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/15\/frosinone-via-libera-alla-rinegoziazione-dei-mutui\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=35536"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35536\/revisions"}],"predecessor-version":[{"id":35538,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35536\/revisions\/35538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/35537"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=35536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=35536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=35536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}