{"id":35520,"date":"2020-05-14T18:26:07","date_gmt":"2020-05-14T16:26:07","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=35520"},"modified":"2020-05-14T18:26:10","modified_gmt":"2020-05-14T16:26:10","slug":"pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/","title":{"rendered":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa&#8230; con le birre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si erano radunati <strong>nel centro di Pescosolido,<\/strong> forse convinti che l\u00ec non li avrebbero notati. Invece i carabinieri, durante un giro di perlustrazione del paese, <strong>si sono imbattuti in un gruppo di ragazzi che, alla vista dell&#8217;auto, sono fuggiti, sparpagliandosi,<\/strong> e lasciando sul posto del party improvvisato due casse di birra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Immediatamente sono scattate le indagini dei carabinieri della Compagnia di Sora che, analizzando le immagini delle telecamere di videosorveglianza, installate vicino al luogo dove i giovani si erano dati appuntamento la sera dell&#8217;8 maggio scorso, sono riusciti a identificare tutti i partecipanti alla &#8216;festa&#8217;.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec<strong> sono scattate sanzioni amministrative nei confronti di 16 persone<\/strong> (14 uomini e due donne di et\u00e0 compresa tra i 20 ed i 40 anni). Ma non \u00e8 tutto: alcuni di loro si sono presentati in caserma per ammettere la loro responsabilit\u00e0 e hanno raccontato quanto accaduto ai carabinieri. I quali, a quel punto, hanno restituito loro le casse di birra recuperate.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>I carabinieri della Compagnia di Sora hanno multato 16 ragazzi che stavano facendo un party a base di birra nel centro di Pescosolido<\/p>\n","protected":false},"author":18,"featured_media":35521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[9076,9846,90,430,94,8722,9845,4617,161,641,1943],"class_list":["post-35520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-assembramento","tag-birra","tag-carabinieri","tag-centro-storico","tag-ciociaria","tag-covid-19","tag-party","tag-sanzioni","tag-sora","tag-telecamere","tag-videosorveglianza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre\" \/>\n<meta property=\"og:description\" content=\"I carabinieri della Compagnia di Sora hanno multato 16 ragazzi che stavano facendo un party a base di birra nel centro di Pescosolido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T16:26:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T16:26:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"731\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa&#8230; con le birre\",\"datePublished\":\"2020-05-14T16:26:07+00:00\",\"dateModified\":\"2020-05-14T16:26:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/\"},\"wordCount\":167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/controlli-carabinieri-1.jpg\",\"keywords\":[\"assembramento\",\"birra\",\"carabinieri\",\"centro storico\",\"Ciociaria\",\"covid 19\",\"party\",\"sanzioni\",\"sora\",\"telecamere\",\"videosorveglianza\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/\",\"name\":\"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/controlli-carabinieri-1.jpg\",\"datePublished\":\"2020-05-14T16:26:07+00:00\",\"dateModified\":\"2020-05-14T16:26:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/controlli-carabinieri-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/controlli-carabinieri-1.jpg\",\"width\":731,\"height\":454,\"caption\":\"Controlli carabinieri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa&#8230; con le birre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/14\\\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/","og_locale":"it_IT","og_type":"article","og_title":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre","og_description":"I carabinieri della Compagnia di Sora hanno multato 16 ragazzi che stavano facendo un party a base di birra nel centro di Pescosolido","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-05-14T16:26:07+00:00","article_modified_time":"2020-05-14T16:26:10+00:00","og_image":[{"width":731,"height":454,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa&#8230; con le birre","datePublished":"2020-05-14T16:26:07+00:00","dateModified":"2020-05-14T16:26:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/"},"wordCount":167,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg","keywords":["assembramento","birra","carabinieri","centro storico","Ciociaria","covid 19","party","sanzioni","sora","telecamere","videosorveglianza"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/","name":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa... con le birre - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg","datePublished":"2020-05-14T16:26:07+00:00","dateModified":"2020-05-14T16:26:10+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/controlli-carabinieri-1.jpg","width":731,"height":454,"caption":"Controlli carabinieri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pescosolido, party con assembramento: multati 16 giovani. Confessano e tornano a casa&#8230; con le birre"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/14\/pescosolido-party-con-assembramento-multati-16-giovani-confessano-e-tornano-a-casa-con-le-birre\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=35520"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35520\/revisions"}],"predecessor-version":[{"id":35522,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35520\/revisions\/35522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/35521"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=35520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=35520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=35520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}