{"id":35205,"date":"2020-05-10T09:15:43","date_gmt":"2020-05-10T07:15:43","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=35205"},"modified":"2020-05-10T15:26:52","modified_gmt":"2020-05-10T13:26:52","slug":"bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/","title":{"rendered":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>La Camera di Commercio di Frosinone ha stanziato 2 milioni e 650mila euro a favore di cittadini e famiglie, lavoratori e\u00a0 imprese<\/strong>\u00a0 della Ciociaria colpiti dall\u2019emergenza Covid-19 . Si tratta di tre bandi e varie modalit\u00e0 di sostegno volte a favorire la ripresa del nostro territorio . In questa fase emergenziale lo stanziamento deliberato dalla CCIAA\u00a0 di Frosinone rappresenta una risposta importante in termini di attenzione e sensibilit\u00e0 \u2018\u2019 . <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/marcello-pigliacelli.jpg\" alt=\"\" class=\"wp-image-34105\" width=\"590\" height=\"330\" \/><figcaption>Marcello Pigliacelli<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cos\u00ec il direttore di Coldiretti Frosinone Carlo Picchi plaude al Presidente della CCIAA Marcello Pigliacelli<\/strong> che,\u00a0 unitamente alla giunta camerale , ha dimostrato ancora una volta quel pragmatismo necessario a\u00a0 donare e ri-donare dignit\u00e0 al nostro territorio e a tutti coloro che nonostante tutto continuano a credere nel proprio lavoro .\u00a0 <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u2018\u2019<strong>Si tratta di un gesto concreto \u2013 ha detto Picchi \u2013 volto a risollevare il tessuto economico , imprenditoriale e sociale<\/strong>\u00a0 del nostro territorio e Coldiretti Frosinone , da sempre al fianco delle imprese e delle persone , non pu\u00f2 che segnalare positivamente una un\u2019 iniziativa di tale portata \u2018\u2019 .\u00a0 L\u2019attivismo , la voglia di fare e non di dire\u00a0 , l\u2019agire contemporaneamente su pi\u00f9 fronti e farlo nella maniera pi\u00f9 efficace possibile :\u00a0 in questo e di pi\u00f9 la\u00a0 Camera di Commercio\u00a0 si mostra sulla stessa lunghezza d\u2019onda di Coldiretti . <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlo Picchi ha poi continuato :<\/strong> \u2018\u2019 Siamo orgogliosi , a nome nostro e di tutte le imprese\u00a0 che con orgoglio rappresentiamo ,\u00a0 in particolare dei 250 mila euro stanziati dalla CCIAA per l\u2019acquisto di generi alimentari prodotti da aziende rigorosamente locali\u00a0 e del\u00a0 bando di 400mila euro di contributi a\u00a0 fondo perduto in favore degli operatori turistici , uno dei settori pi\u00f9 gravemente colpiti dall\u2019emergenza coronavirus .\u00a0 Concludendo ha detto\u00a0 : \u2018\u2019Quello che stiamo vivendo \u00e8 un momento che proprio per le difficolt\u00e0 che porta con s\u00e9 deve vederci lavorare tutti insieme nella convinzione che lo sforzo congiunto di enti ed organismi preposti , ognuno nel rispetto delle proprie prerogative , possa lenire gli effetti della crisi in atto e contribuire all\u2019obiettivo comune di ripartire e farlo proprio ponendo il focus sul nostro territorio \u2018\u2019.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La Camera di Commercio di Frosinone ha stanziato 2 milioni e 650mila euro a favore di cittadini e famiglie, lavoratori<\/p>\n","protected":false},"author":18,"featured_media":26545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[1013,2027,94,1375,93,2126],"class_list":["post-35205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-camera-di-commercio","tag-carlo-picchi","tag-ciociaria","tag-coldiretti","tag-frosinone","tag-marcello-pigliacelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli\" \/>\n<meta property=\"og:description\" content=\"&#8220;La Camera di Commercio di Frosinone ha stanziato 2 milioni e 650mila euro a favore di cittadini e famiglie, lavoratori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-10T07:15:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-10T13:26:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli\",\"datePublished\":\"2020-05-10T07:15:43+00:00\",\"dateModified\":\"2020-05-10T13:26:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carlo-picchi-coldiretti.jpg\",\"keywords\":[\"Camera di Commercio\",\"carlo picchi\",\"Ciociaria\",\"coldiretti\",\"Frosinone\",\"marcello pigliacelli\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/\",\"name\":\"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carlo-picchi-coldiretti.jpg\",\"datePublished\":\"2020-05-10T07:15:43+00:00\",\"dateModified\":\"2020-05-10T13:26:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carlo-picchi-coldiretti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/carlo-picchi-coldiretti.jpg\",\"width\":620,\"height\":340,\"caption\":\"Il direttore di Coldiretti Frosinone Carlo Picchi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/05\\\/10\\\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/","og_locale":"it_IT","og_type":"article","og_title":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli","og_description":"&#8220;La Camera di Commercio di Frosinone ha stanziato 2 milioni e 650mila euro a favore di cittadini e famiglie, lavoratori","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-05-10T07:15:43+00:00","article_modified_time":"2020-05-10T13:26:52+00:00","og_image":[{"width":620,"height":340,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli","datePublished":"2020-05-10T07:15:43+00:00","dateModified":"2020-05-10T13:26:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg","keywords":["Camera di Commercio","carlo picchi","Ciociaria","coldiretti","Frosinone","marcello pigliacelli"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/","name":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg","datePublished":"2020-05-10T07:15:43+00:00","dateModified":"2020-05-10T13:26:52+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/carlo-picchi-coldiretti.jpg","width":620,"height":340,"caption":"Il direttore di Coldiretti Frosinone Carlo Picchi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Bandi a fondo perduto per emergenza coronavirus, il plauso di Coldiretti a Pigliacelli"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/05\/10\/bandi-a-fondo-perduto-per-emergenza-coronavirus-il-plauso-di-coldiretti-a-pigliacelli\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=35205"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35205\/revisions"}],"predecessor-version":[{"id":35208,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/35205\/revisions\/35208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/26545"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=35205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=35205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=35205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}