{"id":34542,"date":"2020-04-30T18:21:09","date_gmt":"2020-04-30T16:21:09","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=34542"},"modified":"2020-05-01T09:10:16","modified_gmt":"2020-05-01T07:10:16","slug":"modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/","title":{"rendered":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#8217;analisi di Martufi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>presidente dei Consulenti del Lavoro di Frosinone, Carlo Martufi<\/strong>, sui nuovi modelli organizzativi e sui costi da sostenere per la ripresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dalla &#8216;Fase 2&#8217;, che prevede la riapertura a partire da luned\u00ec 4 maggio solo di alcune attivit\u00e0 produttive, <strong>restano fuori commercianti, ristoratori e tutte le professioni &#8216;di prossimit\u00e0&#8217; <\/strong>&#8211; come parrucchieri, estetiste, colf e badanti, una platea di circa 6 milioni 145 mila di lavoratori.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 la fotografia scattata dalla <strong>Fondazione Studi Consulenti del Lavoro nell\u2019indagine &#8216;Come cambieranno le professioni di prossimit\u00e0&#8217; <\/strong>contenente una classifica dei lavoratori maggiormente esposti al contagio e pi\u00f9 bisognosi di tutele per la Fase 2.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Martufi: come cambia il lavoro che deve\nriadattarsi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;L\u2019uscita dal lockdown imporr\u00e0 a molti di questi lavoratori un cambiamento non facile della proprie modalit\u00e0 di lavoro &#8211; spiega Carlo Martufi, vicepresidente della Fondazione Studi e presidente del Consiglio provinciale dell\u2019Ordine dei Consulenti del Lavoro di Frosinone &#8211; <strong>Bisogner\u00e0 creare nuovi modelli organizzativi, rivedere l\u2019organizzazione dei luoghi di lavoro<\/strong>, assicurare il contingentamento degli accessi, fornire protezioni individuali e garantire una maggiore attenzione all&#8217;igiene e alla cura dei locali&#8221;.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Questo riadattamento risulter\u00e0 pi\u00f9 difficile da attuare soprattutto alle micro e piccole imprese<\/strong>, che dopo 2 mesi ferme dovranno scegliere se riaprire oppure no, in considerazione dei costi fissi che dovranno sostenere anche nei prossimi mesi per pagare affitti, stipendi, utenze e tributi. E se molte attivit\u00e0 produttive decidessero di non riaprire quando sar\u00e0 consentito farlo, perch\u00e9 ne trarrebbero pi\u00f9 vantaggio dal restare chiuse, il danno ricadr\u00e0 anche sui loro dipendenti, per i quali il rischio di rimanere senza lavoro sar\u00e0 concreto&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ammortizzatori sociali&#8230;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una triste prospettiva che si somma a\nquella dei lavoratori dipendenti gi\u00e0 in cassa integrazione. \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Il Lazio &#8211; precisa Martufi &#8211; \u00e8 la prima regione per numero di domande presentate per la cassa integrazione in deroga (30 mila al 23 aprile) <\/strong>ma sono <strong>solo 6 mila circa quelle autorizzate e poco pi\u00f9 di 600 quelle pagate<\/strong>. In molti casi non \u00e8 stato rispettato l\u2019ordine cronologico di invio delle domande e, di conseguenza, migliaia di lavoratori non riceveranno il sussidio neanche questo mese&#8221;.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&#8230;e incognita finanziamenti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ci sono tanti imprenditori che non hanno percepito alcun prestito dalle banche per un eccesso di burocrazia e adempimenti formali &#8211; sottolinea ancora Martufi &#8211; <strong>La procedura da seguire per richiedere un finanziamento fino a 25 mila euro garantito al 100% dallo Stato \u00e8 molto complessa<\/strong> e non \u00e8 la stessa per tutte le banche. In questo modo si finisce per rendere sempre pi\u00f9 lontana la possibilit\u00e0 di rispondere in modo concreto e adeguato al bisogno di liquidit\u00e0 degli imprenditori italiani&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente dei Consulenti del Lavoro di Frosinone, Carlo Martufi, interviene sulla riorganizzazione delle imprese nella Fase 2 e spiega i nuovi modelli da adottare<\/p>\n","protected":false},"author":18,"featured_media":24118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,17],"tags":[9147,9260,3293,94,7563,9582,93,1529,9628,6262,9629,9627,116],"class_list":["post-34542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","category-lavoro","tag-attivita-produttive","tag-carlo-martufi","tag-cassa-integrazione","tag-ciociaria","tag-consulenti-del-lavoro","tag-fase-2","tag-frosinone","tag-lavoratori","tag-modelli","tag-organizzazione","tag-prestiti","tag-professioni","tag-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#039;analisi di Martufi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#039;analisi di Martufi\" \/>\n<meta property=\"og:description\" content=\"Il presidente dei Consulenti del Lavoro di Frosinone, Carlo Martufi, interviene sulla riorganizzazione delle imprese nella Fase 2 e spiega i nuovi modelli da adottare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-30T16:21:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-01T07:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#8217;analisi di Martufi\",\"datePublished\":\"2020-04-30T16:21:09+00:00\",\"dateModified\":\"2020-05-01T07:10:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/martufi-consulenti-e1575722641489.jpg\",\"keywords\":[\"attivit\u00e0 produttive\",\"carlo martufi\",\"Cassa integrazione\",\"Ciociaria\",\"consulenti del lavoro\",\"fase 2\",\"Frosinone\",\"lavoratori\",\"modelli\",\"organizzazione\",\"prestiti\",\"professioni\",\"sicurezza\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/\",\"name\":\"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L'analisi di Martufi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/martufi-consulenti-e1575722641489.jpg\",\"datePublished\":\"2020-04-30T16:21:09+00:00\",\"dateModified\":\"2020-05-01T07:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/martufi-consulenti-e1575722641489.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/martufi-consulenti-e1575722641489.jpg\",\"width\":632,\"height\":420,\"caption\":\"Carlo Martufi presidente, della Consulta regionale del Lazio dei Consulenti del lavoro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#8217;analisi di Martufi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/30\\\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L'analisi di Martufi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/","og_locale":"it_IT","og_type":"article","og_title":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L'analisi di Martufi","og_description":"Il presidente dei Consulenti del Lavoro di Frosinone, Carlo Martufi, interviene sulla riorganizzazione delle imprese nella Fase 2 e spiega i nuovi modelli da adottare","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-30T16:21:09+00:00","article_modified_time":"2020-05-01T07:10:16+00:00","og_image":[{"width":632,"height":420,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#8217;analisi di Martufi","datePublished":"2020-04-30T16:21:09+00:00","dateModified":"2020-05-01T07:10:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg","keywords":["attivit\u00e0 produttive","carlo martufi","Cassa integrazione","Ciociaria","consulenti del lavoro","fase 2","Frosinone","lavoratori","modelli","organizzazione","prestiti","professioni","sicurezza"],"articleSection":["*PRIMO PIANO*","Economia e Finanza","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/","name":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L'analisi di Martufi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg","datePublished":"2020-04-30T16:21:09+00:00","dateModified":"2020-05-01T07:10:16+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/martufi-consulenti-e1575722641489.jpg","width":632,"height":420,"caption":"Carlo Martufi presidente, della Consulta regionale del Lazio dei Consulenti del lavoro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Modelli organizzativi e costi della Fase 2: il lavoro che cambia. L&#8217;analisi di Martufi"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/30\/modelli-organizzativi-e-costi-della-fase-2-il-lavoro-che-cambia-lanalisi-di-martufi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=34542"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34542\/revisions"}],"predecessor-version":[{"id":34545,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34542\/revisions\/34545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/24118"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=34542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=34542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=34542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}