{"id":3430,"date":"2018-12-18T14:08:36","date_gmt":"2018-12-18T13:08:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=3430"},"modified":"2018-12-18T14:08:36","modified_gmt":"2018-12-18T13:08:36","slug":"libera-rappresentanza-guardia-alta-sui-diritti-dei-militari","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/","title":{"rendered":"Libera Rappresentanza: guardia alta sui diritti dei militari"},"content":{"rendered":"<p>Un grande successo di pubblico quello che ha riscosso il <strong>IV congresso nazionale<\/strong> dell&#8217;associazione culturale<strong> &#8216;Libera Rappresentanza&#8217;<\/strong>, svoltosi all&#8217;auditorium <strong>&#8216;Vittorio De Sica&#8217;<\/strong> di <strong>Sora<\/strong> lo scorso sabato. Tema dell&#8217;incontro &#8216;la svolta dei diritti sindacali per i militari&#8217;.<\/p>\n<p>In una sala gremitissima si sono riuniti tutti gli associati e non solo, provenienti da ogni parte d&#8217;Italia, dalla Sicilia fino al Veneto, per ritrovarsi in questo importante momento di confronto ad ascoltare interventi di relatori d&#8217;eccezione.<\/p>\n<p>Al tavolo dell&#8217;assemblea erano seduti il presidente di Libera Rappresentanza, <strong>Girolamo Foti<\/strong>, con a suo fianco il segretario nazionale <strong>Marco Votano<\/strong> e il segretario regionale per il Lazio, <strong>Mario Di Stefano<\/strong>, che si \u00e8 occupato, insieme ad altri soci, di organizzare l&#8217;evento. Al quale hanno preso parte anche associazioni storiche, come quella degli <strong>Alpini Italiani<\/strong> presenti con la sezione di Sora.<\/p>\n<figure id=\"attachment_3431\" aria-describedby=\"caption-attachment-3431\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3431 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/libera-rappresentanza-sora-e1545137857564.jpg\" alt=\"libera rappresentanza militari sora frosinone ciociaria\" width=\"632\" height=\"339\" \/><figcaption id=\"caption-attachment-3431\" class=\"wp-caption-text\">Relatori e personalit\u00e0 presenti al IV congresso di Libera Rappresentanza<\/figcaption><\/figure>\n<p>Ad aprire i lavori un mini concerto dell&#8217;orchestra scolastica dell&#8217;istituto comprensivo terzo di Sora Edoardo Facchini e i saluti dell&#8217;amministrazione comunale rappresentata dal presidente del consiglio <strong>Antonio Lecce<\/strong> a cui \u00e8 stato consegnato un quadro raffigurante il maestro del cinema De Sica, illustra concittadino, realizzato dall&#8217;artista <strong>Giovanna Lettieri<\/strong>.<\/p>\n<h2>I temi trattati nel convegno<\/h2>\n<p>A seguire il discorso del presidente di Euromil, organizzazione europea delle associazioni militari di 22 paesi, <strong>Emmanuel Jacob<\/strong> che, con la collaborazione della traduttrice Francesca Milone, ha illustrato il lavoro della propria associazione, confidando che anche l&#8217;Italia possa arrivare a Bruxelles con un sindacato che rappresenti i diritti dei propri militari .<\/p>\n<p>A seguire le parole del capo dipartimento del team legal di Libera Rappresentanza, l&#8217;avvocato <strong>Francesco Pandolfi<\/strong>, che ha ricordato che tutti gli associati possono rivolgersi a loro per le difficolt\u00e0 che dovessero incontrare.<\/p>\n<p>Il segretario nazionale <strong>Marco Votano<\/strong> ha ricordato come il ministro Elisabetta Trenta abbia mostrato disponibilit\u00e0 e apertura per ufficializzare l\u2019associazionismo sindacale nelle forze armate.<\/p>\n<p>Parole di sostegno anche dal presidente dell&#8217;Unsi, unione nazionale sottufficiali italiani, <strong>Roberto Congedi<\/strong> e dai rappresentanti dell&#8217;associazione CGS, Cum Grano Salis, <strong>Eliseo Taverna<\/strong> e <strong>Daniele Tisci<\/strong>. Presente pure il delegato nazionale di LR, <strong>Pasquale D&#8217;Alterio<\/strong> che, coadiuvato da altri membri dell&#8217;associazione, si \u00e8 occupato di accogliere le adesioni.<\/p>\n<p>Intervento molto sentito anche quello della dottoressa <strong>Danila D&#8217;Amico<\/strong> che ha parlato del disturbo da stress post traumatico a cui l\u2019associazione Libera Rappresentanza dedicher\u00e0 un convegno specifico. L&#8217;associato <strong>Salvo Ricco<\/strong>, segretario regionale per la Sicilia, ha ribadito l&#8217;importanza di essere uniti e mostrare solidariet\u00e0 a tutti i colleghi che ne avessero bisogno.<\/p>\n<figure id=\"attachment_3433\" aria-describedby=\"caption-attachment-3433\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3433 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/platea-convegno-militari-e1545138127643.jpg\" alt=\"militari auditorium sora libera rappresentanza frosinone ciociaria\" width=\"632\" height=\"423\" \/><figcaption id=\"caption-attachment-3433\" class=\"wp-caption-text\">La platea all&#8217;auditorium &#8216;Vittorio De Sica&#8217; di Sora<\/figcaption><\/figure>\n<p>A concludere i lavori l&#8217;intervento davvero sentito del presidente <strong>Girolamo Foti<\/strong> che ha ricevuto con un grande applauso il sostegno di tutti gli associati. Il vicepresidente di LR, <strong>Sandro Frattalemi<\/strong>, che ha messo in risalto le problematiche del personale vittima del dovere, ha consegnato il premio cittadino modello con le stellette 2018 al cavalier <strong>Nicola Passarelli<\/strong>, vittima del dovere premiato da Francesco Damasco, e al cavalier e primo luogotenente Pasquale Fico, veterano dell&#8217;Esercito Italiano, persona stimata non solo dagli associati di Libera Rappresentanza ma da tutti i militari per la sua dedizione alle problematiche del personale.<\/p>\n<p>Soddisfatto il promotore dell\u2019evento <strong>Mario Di Stefano<\/strong> per aver centrato il suo obiettivo in termini di partecipazione all\u2019evento. L&#8217;evento \u00e8 stato trasmesso via web e ha raccolto migliaia di visualizzazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grande successo di pubblico quello che ha riscosso il IV congresso nazionale dell&#8217;associazione culturale &#8216;Libera Rappresentanza&#8217;, svoltosi all&#8217;auditorium &#8216;Vittorio<\/p>\n","protected":false},"author":7,"featured_media":3432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17],"tags":[846,94,507,1025,1027,93,1149,1024,161],"class_list":["post-3430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-lavoro","tag-auditorium","tag-ciociaria","tag-congresso","tag-diritti-sindacali","tag-esercito-italiano","tag-frosinone","tag-libera-rappresentanza","tag-militari","tag-sora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Libera Rappresentanza: guardia alta sui diritti dei militari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Una gremita platea quella che ha partecipato al IV congresso di &#039;Libera Rappresentanza&#039; sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libera Rappresentanza: guardia alta sui diritti dei militari\" \/>\n<meta property=\"og:description\" content=\"Una gremita platea quella che ha partecipato al IV congresso di &#039;Libera Rappresentanza&#039; sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T13:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Abbruzzese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Abbruzzese\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/\"},\"author\":{\"name\":\"Giulia Abbruzzese\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\"},\"headline\":\"Libera Rappresentanza: guardia alta sui diritti dei militari\",\"datePublished\":\"2018-12-18T13:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/\"},\"wordCount\":584,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/relatori-convegno-sora-e1545138344633.jpg\",\"keywords\":[\"auditorium\",\"Ciociaria\",\"congresso\",\"diritti sindacali\",\"esercito italiano\",\"Frosinone\",\"libera rappresentanza\",\"militari\",\"sora\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/\",\"name\":\"Libera Rappresentanza: guardia alta sui diritti dei militari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/relatori-convegno-sora-e1545138344633.jpg\",\"datePublished\":\"2018-12-18T13:08:36+00:00\",\"description\":\"Una gremita platea quella che ha partecipato al IV congresso di 'Libera Rappresentanza' sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/relatori-convegno-sora-e1545138344633.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/relatori-convegno-sora-e1545138344633.jpg\",\"width\":632,\"height\":423,\"caption\":\"I relatori del convegno di Libera Rappresentanza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libera Rappresentanza: guardia alta sui diritti dei militari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/58bf90a6d70d54d2f0db83bc3d580351\",\"name\":\"Giulia Abbruzzese\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g\",\"caption\":\"Giulia Abbruzzese\"},\"description\":\"Giornalista dei quotidiani online \\\"Il Corriere della Provincia\\\" e \\\"TuNews24.it\\\" e del settimanale \\\"Tu News\\\", ha collaborato anche con il mensile \\\"Qui Magazine\\\" oltre che con il settimanale \\\"Qui Sette\\\"; \u00e8 stata inoltre Caposervizio del quotidiano \\\"\u2018Ciociaria Oggi\\\" e Caporedattore de \\\"Il quotidiano della Ciociaria\\\". Collabora con la rivista \\\"Chic Style\\\".\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/giulia-abbruzzese\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/18\\\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Libera Rappresentanza: guardia alta sui diritti dei militari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Una gremita platea quella che ha partecipato al IV congresso di 'Libera Rappresentanza' sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/","og_locale":"it_IT","og_type":"article","og_title":"Libera Rappresentanza: guardia alta sui diritti dei militari","og_description":"Una gremita platea quella che ha partecipato al IV congresso di 'Libera Rappresentanza' sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/tunews24","article_published_time":"2018-12-18T13:08:36+00:00","og_image":[{"width":632,"height":423,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg","type":"image\/jpeg"}],"author":"Giulia Abbruzzese","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Abbruzzese","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/"},"author":{"name":"Giulia Abbruzzese","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351"},"headline":"Libera Rappresentanza: guardia alta sui diritti dei militari","datePublished":"2018-12-18T13:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/"},"wordCount":584,"commentCount":1,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg","keywords":["auditorium","Ciociaria","congresso","diritti sindacali","esercito italiano","Frosinone","libera rappresentanza","militari","sora"],"articleSection":["*PRIMO PIANO*","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/","name":"Libera Rappresentanza: guardia alta sui diritti dei militari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg","datePublished":"2018-12-18T13:08:36+00:00","description":"Una gremita platea quella che ha partecipato al IV congresso di 'Libera Rappresentanza' sui diritti sindacali dei militari che si \u00e8 svolto sabato a Sora.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/relatori-convegno-sora-e1545138344633.jpg","width":632,"height":423,"caption":"I relatori del convegno di Libera Rappresentanza"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Libera Rappresentanza: guardia alta sui diritti dei militari"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/58bf90a6d70d54d2f0db83bc3d580351","name":"Giulia Abbruzzese","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff9b2f7c2c6d1751e3de0056e95b7af4a6c366bf539cdd639aac86cd1908507f?s=96&d=mm&r=g","caption":"Giulia Abbruzzese"},"description":"Giornalista dei quotidiani online \"Il Corriere della Provincia\" e \"TuNews24.it\" e del settimanale \"Tu News\", ha collaborato anche con il mensile \"Qui Magazine\" oltre che con il settimanale \"Qui Sette\"; \u00e8 stata inoltre Caposervizio del quotidiano \"\u2018Ciociaria Oggi\" e Caporedattore de \"Il quotidiano della Ciociaria\". Collabora con la rivista \"Chic Style\".","sameAs":["http:\/\/www.tunews24.it","http:\/\/www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/giulia-abbruzzese\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/18\/libera-rappresentanza-guardia-alta-sui-diritti-dei-militari\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=3430"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3430\/revisions"}],"predecessor-version":[{"id":3435,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3430\/revisions\/3435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3432"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=3430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=3430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=3430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}