{"id":34214,"date":"2020-04-27T15:42:12","date_gmt":"2020-04-27T13:42:12","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=34214"},"modified":"2020-04-28T14:56:56","modified_gmt":"2020-04-28T12:56:56","slug":"tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/","title":{"rendered":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&#8217;emergenza Covid-19 sta mettendo in crisi interi territori. In una prima fase soprattutto sotto il profilo sanitario, ora anche dal punto di vista economico e occupazionale<\/strong>. Ma l&#8217;1-2 dei giorni scorsi, ovvero il progetto di realizzazione della fermata TAV e le opere infrastrutturali di Regione e Asi, potrebbero essere davvero il trampolino di lancio per la ripartenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Due volte sindaco di Ferentino, due volte presidente della Provincia di Frosinone nonch\u00e9 al vertice di Upi Lazio, Antonio Pompeo<\/strong> sta dimostrando concretezza e lungimiranza al di l\u00e0 degli steccati politici. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non esita, infatti, a trovare accordi anche con l&#8217;opposizione perch\u00e9 ritiene che l&#8217;Ente di Palazzo Jacobucci possa e debba essere quella &#8216;Casa dei Comuni&#8217; priva di etichette politiche.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"637\" height=\"350\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/tav-stazione-ferentino-bis.jpg\" alt=\"\" class=\"wp-image-33925\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/tav-stazione-ferentino-bis.jpg 637w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/tav-stazione-ferentino-bis-300x165.jpg 300w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervista <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Presidente Pompeo, la realizzazione della stazione TAV a Ferentino, al netto delle sterili polemiche politiche, potrebbe essere la vera occasione di rilancio dell&#8217;intera provincia e non solo dell&#8217;area Nord. Poco importa il comune in cui sar\u00e0 realizzata: l&#8217;effettiva portata di questa infrastruttura dovrebbe essere interpretata da mezzo milione di cittadini come una vittoria del territorio. Non le pare?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;Alta Velocit\u00e0 in provincia di Frosinone \u00e8 una delle\ninfrastrutture pi\u00f9 strategiche e importanti per l&#8217;intero territorio,\nche andr\u00e0 a beneficiarne non soltanto dal punto di vista della\nmobilit\u00e0 e dei trasporti ma in un&#8217;ottica integrata di sviluppo\neconomico, turistico e urbanistico. La fermata della Tav, un progetto\natteso da anni, completa uno snodo viario nevralgico, tra la\nsuperstrada che collega l&#8217;area Est al nord della provincia, il\ncasello autostradale e la nuova stazione ferroviaria di Ferentino,\nfresca di un progetto di riqualificazione da 7 milioni di euro, oltre\nalla rotatoria e al parcheggio, che a breve sar\u00e0 inaugurato. In\ntutto questo il ruolo della politica deve essere quello di studiare\nopere e interventi intorno al progetto Tav, lavorare affinch\u00e9 il\nnostro territorio possa avere pi\u00f9 infrastrutture come questa e non\ncerto correre per tenerla a battesimo o spostarla da un lembo\nall\u2019altro del territorio. Piuttosto ringraziamo e guardiamo avanti.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A proposito di questo, dal Protocollo di Intesa tra Asi e Regione risulta evidente che le opere saranno realizzate anche in comuni di diverso colore politico rispetto a quello del presidente Zingaretti, a cominciare dal capoluogo. Ma a suo avviso, nell&#8217;era coronavirus, alla gente interessa la politica della polemica?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assolutamente no. E spiace dire che proprio un&#8217;emergenza terribile\ne logorante, come quella che stiamo attraversando, ci sta ricordando,\nseppure in modo brutale, il valore di essere comunit\u00e0. Un&#8217;unica,\ngrande comunit\u00e0. Non \u00e8 concepibile non sentirsi parte di un tutto\nsolo a pochi chilometri di distanza. Dalla politica oggi la gente si\naspetta un valore aggiunto, strumenti concreti che aiutino la\nripresa, sostegni economici per non soccombere. Bene, quindi, gli\ninterventi di Asi e Regione, ai quali, come Provincia e Comune, non\nfaremo mancare supporto e disponibilit\u00e0 per creare tutte le\ncondizioni necessarie allo sviluppo del territorio. Non \u00e8 tempo di\ncampanilismi ma di rimboccarsi le maniche e riaccendere la speranza\nnel futuro.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"748\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/cartina-turistica-ciociaria-1024x748.jpg\" alt=\"\" class=\"wp-image-34215\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/cartina-turistica-ciociaria-1024x748.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/cartina-turistica-ciociaria-300x219.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/cartina-turistica-ciociaria-768x561.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/cartina-turistica-ciociaria.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Uno dei settori pi\u00f9 in crisi anche in provincia di Frosinone sar\u00e0 quello del turismo. E non riguarder\u00e0 solamente Fiuggi, secondo polo alberghiero del Lazio sul quale va assolutamente tenuta alta l&#8217;attenzione. Ma interesser\u00e0 anche tutte le citt\u00e0 d&#8217;arte della Ciociaria: in ginocchio potrebbero finire hotel, agriturismi, strutture ricettive, personale e trasporti del comparto turistico. Insomma, un intero indotto che offre posti di lavoro pi\u00f9 dello stabilimento Fca. Quali sono secondo lei le mosse da mettere in campo per evitare la catastrofe?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Coronavirus ha esasperato una situazione che era gi\u00e0 difficile\nper quanto attiene a settori come quello turistico, nonostante la\nnostra terra sia interprete di tutte le declinazioni che il comparto\npu\u00f2 assumere: dal turismo religioso a quello culturale,\ndall&#8217;enogastronomico al termale passando per quello naturale che\ntanti ci invidiano. Il passo in pi\u00f9 che si deve fare \u00e8 quello di\npromuovere il &#8216;turismo lento&#8217; a dispetto di quello mordi e fuggi: la\nnostra provincia \u00e8 ricca di paesaggi, borghi, centri e citt\u00e0\nsuggestive in cui trascorrere pi\u00f9 di una giornata o di un weekend. E\nsar\u00e0 anche grazie a un&#8217;opera come la Tav che, nonostante le\nlimitazioni imposte dalle misure di sicurezza a cui purtroppo dovremo\nattenerci ancora per un bel po&#8217;, che potremo giocare un ruolo\nimportante. Una vera e propria &#8216;cerniera&#8217; che ci render\u00e0 territorio\nstrategico di connessione tra nord e sud del Paese.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/edilizia-scolastica-1024x683.jpg\" alt=\"edilizia scolastica interventi paliano il corriere della provincia\" class=\"wp-image-14609\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ormai \u00e8 certo che l&#8217;anno scolastico terminer\u00e0 in modalit\u00e0 on-line. Alla ripresa per\u00f2 ci sar\u00e0 bisogno di istituti non soltanto sicuri dal punto di vista strutturale ma anche adeguati a fronteggiare il rischio di contagi. Qual \u00e8 il piano?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;edilizia scolastica e la sicurezza del patrimonio strutturale di\nnostra competenza sono da sempre prioritarie nell&#8217;agenda\ndell&#8217;Amministrazione provinciale. Abbiamo ottenuto circa trenta\nmilioni di euro di finanziamenti dal Miur per interventi di\nadeguamento sismico e opere strutturali che in parte abbiamo avviato\ne alle quali nelle prossime settimane daremo seguito. Quella di\nFrosinone \u00e8 stata la prima Provincia d&#8217;Italia a sottoscrivere un\nprotocollo d&#8217;intesa con Cassa Depositi e Prestiti che, attraverso la\npropria unit\u00e0 di Sviluppo Infrastrutture, ci sta affiancando in\ntutto l\u2019iter progettuale, procedurale e amministrativo degli\ninterventi. Ora, per\u00f2, dobbiamo anche adeguare aule, laboratori e\nspazi degli istituti a quelle che saranno le misure del Governo: per\ni prossimi giorni ho convocato l&#8217;Ufficio scolastico provinciale, le\nsigle sindacali, i consiglieri provinciali delegati e tutti i\nsoggetti interessati, intorno a un tavolo che avr\u00e0 proprio questo\nobiettivo. Tra i banchi ormai \u00e8 certo si torner\u00e0 non prima di\nsettembre e per allora tutto dovr\u00e0 essere pronto ad accogliere\nstudenti e docenti in assoluta sicurezza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Restando in tema, le Province pi\u00f9 delle Regioni sono il vero &#8216;sportello&#8217; per il cittadino. Lei da tempo si batte affinch\u00e9 riconquistino la centralit\u00e0 affermata anche nella nostra Costituzione. E questa emergenza ha dimostrato quanto la gente abbia bisogno di risposte dagli enti di prossimit\u00e0, quali Comuni e Province, appunto. \u00c8 anche da qui che si deve ripartire?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Che la Provincia sia l&#8217;anello di congiunzione fondamentale tra i\nterritori e gli Enti sovraordinati \u00e8 una realt\u00e0 non solo\n&#8216;costituzionale&#8217; ma concretamente evidente. Un Ente che ha\ndimostrato, come nel caso della gestione delle emergenze, la sua\ncentralit\u00e0, nonostante la riforma della legge 56. Abbiamo un ruolo\nfondamentale nei tavoli con il Governo. \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con l&#8217;Amministrazione provinciale di Frosinone, che ha giocato una\nparte importante, da presidente di Upi Lazio, componente del\ndirettivo nazionale di Upi e membro Conferenza Stato-Citt\u00e0 e della\nConferenza unificata, ho potuto seguire personalmente e da vicino le\nvarie fasi di confronto con Governo, enti locali e parti sociali.\nBattaglie che mi appassionano soprattutto perch\u00e9, anche nel mio\nruolo di sindaco, vivo quotidianamente le difficolt\u00e0 degli\namministratori. Ecco perch\u00e9 continuer\u00f2 a portare su tutti i tavoli\nle emergenze del nostro territorio, le frustrazioni amministrative di\nchi, in prima linea, deve dare risposte, garantire servizi, avviare\ncantieri, dare impulso agli investimenti e, di contro, si trova\ntroppo spesso a combattere da solo e con le casse vuote. \u00c8 questo il\ncompito principale che le Province devono assolvere: riunire le\nsingole voci di un territorio e trasformarle in un&#8217;unica, forte e\nchiara richiesta di attenzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;emergenza Covid-19 sta mettendo in crisi interi territori. In una prima fase soprattutto sotto il profilo sanitario, ora anche dal<\/p>\n","protected":false},"author":3,"featured_media":33849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[842,94,92,83,367,2115,1351],"class_list":["post-34214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-antonio-pompeo","tag-ciociaria","tag-ferentino","tag-provincia","tag-scuola","tag-tav","tag-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart\" \/>\n<meta property=\"og:description\" content=\"L&#8217;emergenza Covid-19 sta mettendo in crisi interi territori. In una prima fase soprattutto sotto il profilo sanitario, ora anche dal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T13:42:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-28T12:56:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"825\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart\",\"datePublished\":\"2020-04-27T13:42:12+00:00\",\"dateModified\":\"2020-04-28T12:56:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/\"},\"wordCount\":1204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/pompeo-palazzo-provincia.jpg\",\"keywords\":[\"antonio pompeo\",\"Ciociaria\",\"ferentino\",\"provincia\",\"scuola\",\"tav\",\"Turismo\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/\",\"name\":\"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/pompeo-palazzo-provincia.jpg\",\"datePublished\":\"2020-04-27T13:42:12+00:00\",\"dateModified\":\"2020-04-28T12:56:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/pompeo-palazzo-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/pompeo-palazzo-provincia.jpg\",\"width\":825,\"height\":543,\"caption\":\"Il presidente della Provincia di Frosinone Antonio Pompeo e Palazzo Jacobucci\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/27\\\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/","og_locale":"it_IT","og_type":"article","og_title":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart","og_description":"L&#8217;emergenza Covid-19 sta mettendo in crisi interi territori. In una prima fase soprattutto sotto il profilo sanitario, ora anche dal","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2020-04-27T13:42:12+00:00","article_modified_time":"2020-04-28T12:56:56+00:00","og_image":[{"width":825,"height":543,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart","datePublished":"2020-04-27T13:42:12+00:00","dateModified":"2020-04-28T12:56:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/"},"wordCount":1204,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg","keywords":["antonio pompeo","Ciociaria","ferentino","provincia","scuola","tav","Turismo"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/","name":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg","datePublished":"2020-04-27T13:42:12+00:00","dateModified":"2020-04-28T12:56:56+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/pompeo-palazzo-provincia.jpg","width":825,"height":543,"caption":"Il presidente della Provincia di Frosinone Antonio Pompeo e Palazzo Jacobucci"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Tav, Asi, turismo, scuole e Province, Pompeo: basta campanilismi. \u00c8 ora del restart"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/27\/tav-asi-turismo-scuole-e-province-pompeo-basta-campanilismi-e-ora-del-restart\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=34214"}],"version-history":[{"count":7,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34214\/revisions"}],"predecessor-version":[{"id":34305,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34214\/revisions\/34305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/33849"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=34214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=34214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=34214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}