{"id":34055,"date":"2020-04-24T16:16:49","date_gmt":"2020-04-24T14:16:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=34055"},"modified":"2020-04-24T16:18:26","modified_gmt":"2020-04-24T14:18:26","slug":"convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/","title":{"rendered":"Accordo tra Asi e Regione per le infrastrutture, Battisti:  passo in avanti per il rilancio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201c<strong>Ancora un annuncio importante, ancora un risultato incredibile per il nostro territorio dopo la grande svolta dell\u2019Alta Velocit\u00e0 in Provincia di Frosinone.<\/strong> La Ciociaria dell\u2019era Post Covid-19 sar\u00e0 una terra di ripartenza e un volano per tutta la Regione Lazio: gli investimenti che stiamo annunciando ne sono l\u2019emblema&#8221;- Cos\u00ec Sara Battisti, consigliere regionale del Pd. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La Convenzione tra Regione Lazio a guida Zingaretti, l\u2019Astral e il Consorzio Asi, presieduto da Francesco De Angelis, grazie al coordinamento del Capo di Gabinetto della Regione, Albino Ruberti, Assessori Orneli e Alessandri, rappresenta un ulteriore passo di ammodernamento del nostro territorio, che porter\u00e0 a lavori di rifacimento, completamento e messa in sicurezza di tratti stradali strategici al fine favorire, nella Provincia di Frosinone, lo sviluppo industriale e\u00a0 un\u2019industrializzazione sostenibile&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Sono stati stimati in 12.8 mln di euro i lavori che interesseranno, in particolare, <\/strong>i Comuni di Ferentino, Sora, Frosinone, Arpino, Anagni, Ceccano, Ceprano. Un investimento molto importante che \u00e8 simbolo della volont\u00e0 reciproca di Asi, Arsial e Regione Lazio, di rendere la Provincia di Frosinone pi\u00f9 attrattiva per gli investimenti esogeni e foriera di nuove proposte endogene dalle imprese del territorio. Strade migliorate, completate, ampliate e pi\u00f9 sicure per i lavoratori oltre, alla scelta di rilanciare il territorio con un investimento che permetter\u00e0 nuove assunzioni e all\u2019economia di tornare a mettersi in movimento. Questa \u00e8 la grande risposta che stiamo dando alla nostra Provincia: il Covid-19 rappresenta una delle pi\u00f9 grandi crisi mai affrontate, ma la Regione Lazio non si tira indietro e rilancia l\u2019economia Ciociara\u201d.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAncora un annuncio importante, ancora un risultato incredibile per il nostro territorio dopo la grande svolta dell\u2019Alta Velocit\u00e0 in Provincia<\/p>\n","protected":false},"author":18,"featured_media":29990,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[289,94,93,98,1721],"class_list":["post-34055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-asi","tag-ciociaria","tag-frosinone","tag-pd","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio\" \/>\n<meta property=\"og:description\" content=\"\u201cAncora un annuncio importante, ancora un risultato incredibile per il nostro territorio dopo la grande svolta dell\u2019Alta Velocit\u00e0 in Provincia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-24T14:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-24T14:18:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio\",\"datePublished\":\"2020-04-24T14:16:49+00:00\",\"dateModified\":\"2020-04-24T14:18:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"keywords\":[\"asi\",\"Ciociaria\",\"Frosinone\",\"Pd\",\"Sara Battisti\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/\",\"name\":\"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"datePublished\":\"2020-04-24T14:16:49+00:00\",\"dateModified\":\"2020-04-24T14:18:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/sara-battisti.png\",\"width\":512,\"height\":328,\"caption\":\"Sara Battisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/24\\\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/","og_locale":"it_IT","og_type":"article","og_title":"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio","og_description":"\u201cAncora un annuncio importante, ancora un risultato incredibile per il nostro territorio dopo la grande svolta dell\u2019Alta Velocit\u00e0 in Provincia","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-24T14:16:49+00:00","article_modified_time":"2020-04-24T14:18:26+00:00","og_image":[{"width":512,"height":328,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio","datePublished":"2020-04-24T14:16:49+00:00","dateModified":"2020-04-24T14:18:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","keywords":["asi","Ciociaria","Frosinone","Pd","Sara Battisti"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/","name":"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","datePublished":"2020-04-24T14:16:49+00:00","dateModified":"2020-04-24T14:18:26+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/sara-battisti.png","width":512,"height":328,"caption":"Sara Battisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Accordo tra Asi e Regione per le infrastrutture, Battisti: passo in avanti per il rilancio"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/24\/convenzionetra-asi-e-regione-per-le-infrastrutture-battisti-passo-in-avanti-per-rilanciare-leconomia\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=34055"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34055\/revisions"}],"predecessor-version":[{"id":34059,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/34055\/revisions\/34059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/29990"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=34055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=34055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=34055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}