{"id":33800,"date":"2020-04-21T17:05:26","date_gmt":"2020-04-21T15:05:26","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=33800"},"modified":"2020-04-21T17:15:25","modified_gmt":"2020-04-21T15:15:25","slug":"coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/","title":{"rendered":"Coronavirus, cinque nuovi casi e un decesso ad Arpino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sono ottanta i nuovi casi di Coronavirus registrati in tutta la regione Lazio nelle ultime 24 ore. <strong>In provincia di Frosinone i nuovi contagi ammontano a cinque.<\/strong> Purtroppo di registra il decesso di un uomo di Arpino, come annunciato dal sindaco Renato Rea. Venti persone sono uscite dall\u2019isolamento domiciliare e intanto  continuano i controlli nelle RSA e case di riposo del territorio.  <strong>A Latina e Rieti nessun caso. <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1-1024x576.jpg\" alt=\"\" class=\"wp-image-977\" width=\"591\" height=\"332\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1-1024x576.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1-500x281.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/alessio-damato-1.jpg 1280w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><figcaption>L&#8217;assessore regionale Alessio D&#8217;Amato<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento di d&#8217;Amato<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Oggi registriamo un dato di 80 casi di positivit\u00e0 per il terzo giorno consecutivo sotto i 100 casi <\/strong>e un trend al 1,3%. Dobbiamo proseguire e stabilizzare questa discesa. Aumentano i controlli sulle RSA e le strutture socio-assistenziali private accreditate. Sono ad oggi 472 le strutture per anziani ispezionate su tutto il territorio. Sono giunti i primi pazienti nei nuovi 20 posti di terapia intensiva della struttura di Alto Bio-Contenimento dell\u2019Istituto nazionale di malattie infettive Lazzaro Spallanzani. L\u2019Istituto ha avuto a disposizione i locali dalla Protezione Civile Nazionale meno di un mese fa e siamo riusciti ad allestirli con tutte le dotazioni tecnologiche in meno di 3 settimane&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Un ringraziamento particolare va alla Banca D\u2019Italia per il contributo messo a disposizione di tutte le Regioni italiane <\/strong>e che noi abbiamo voluto destinare a questa iniziativa. Con questi ulteriori 20 posti di terapia intensiva rafforziamo la risposta nella Capitale, nella ricorrenza del Natale di Roma, e lo Spallanzani diventa sempre di pi\u00f9 il centro di riferimento nazionale.&nbsp; <strong>Per quanto riguarda i guariti salgono di 29 unit\u00e0 nelle ultime 24h <\/strong>per un totale di 1.130, e 14 i decessi nelle ultime 24h ed \u00e8 stata superata la soglia dei 100 mila tamponi e di questi oltre 9 su 10 negativi&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La nuova app della Regione \u2018LazioDrCovid<\/strong>\u2019 realizzata in collaborazione con i medici di medicina generale e i pediatri di libera scelta, ha registrato oltre 89 mila utenti che hanno scaricato l\u2019applicazione e 2.300 medici di famiglia e 320 pediatri di libera scelta collegati. Per quanto riguarda infine i dispositivi di protezione individuale oggi sono in distribuzione presso le strutture sanitarie: 225.300 mascherine chirurgiche, 28.000 maschere FFP2, 23.300 camici impermeabili, 7.400 calzari, 7.600 guanti, 28.500 cuffie&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le altre asl<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Asl Roma 1<\/strong>:&nbsp;<strong>12 nuovi casi positivi<\/strong>. 47 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli sulle RSA e case di riposo del territorio.<\/li><li><strong>Asl Roma 2:<\/strong>&nbsp;<strong>14 nuovi casi positivi<\/strong>. Deceduto un uomo di 93 anni con precedenti patologie. 18 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli sulle RSA e case di riposo del territorio.<\/li><li><strong>Asl Roma 3<\/strong>:&nbsp;<strong>20 nuovi casi positivi<\/strong>&nbsp;di cui 7 in isolamento domiciliare. 2 decessi: donna 75 anni e un uomo di 81 anni. 22 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli nelle RSA e case di riposo del territorio: attenzionata 1 casa di riposo e 1 Istituto religioso.<\/li><li><strong>Asl Roma 4<\/strong>:&nbsp;&nbsp;<strong>1 nuovo caso positivo<\/strong>. 128 persone sono uscite dall\u2019isolamento domiciliare. Operative le Uscar alla RSA di Santa Marinella e a Campagnano per controlli nelle case di riposo del territorio.<\/li><li><strong>Asl Roma 5<\/strong>:&nbsp;&nbsp;<strong>10 nuovi casi positivi<\/strong>. 3 decessi: una donna di 98 anni, un uomo di 87 anni e una donna di 75 anni, tutti con patologie pregresse. 11 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli sulle RSA e case di riposo del territorio.<\/li><li><strong>Asl Roma 6: 15 nuovi casi positivi.&nbsp;<\/strong>3 decessi: una donna 94, una donna di 91 anni e un uomo di 82 anni, tutti con precedenti patologie. 75 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli nelle case di riposo e RSA del territorio. <\/li><li><strong>Asl Latina<\/strong>: &nbsp;<strong>0 nuovi casi positivi.<\/strong>&nbsp;Deceduto un uomo di 57 anni con precedenti patologie. 170 persone sono uscite dall\u2019isolamento domiciliare. Si sta attivando il laboratorio per il test sierologico<\/li><li><strong>Asl Rieti:<\/strong>&nbsp;&nbsp;<strong>0 nuovi casi positivi.<\/strong>&nbsp;3 decessi: un uomo di 57 anni, un uomo di 54 e un uomo di 84 anni. 26 persone sono uscite dall\u2019isolamento domiciliare. Si sta attivando il laboratorio per il test sierologico.<\/li><li><strong>Asl Viterbo:<\/strong>&nbsp;<strong>3 nuovi casi positivi<\/strong>. 32 persone sono uscite dall\u2019isolamento domiciliare. Continuano i controlli sulle RSA e case di riposo del territorio.<\/li><li><strong>Azienda Ospedaliera Sant\u2019Andrea<\/strong>: 7 pazienti guariti. Nessun nuovo caso positivo in accesso al Pronto Soccorso negli ultimi 7 giorni.<\/li><li><strong>Azienda Ospedaliera San Camillo<\/strong>: 2 pazienti guariti. 4 pazienti ricoverati in terapia intensiva. Non si registrano nuovi casi positivi in accesso al pronto soccorso negli ultimi 3 giorni.<\/li><li><strong>Azienda Ospedaliera San Giovanni<\/strong>:&nbsp; Non si registrano nuovi casi positivi in accesso al pronto soccorso negli ultimi 9 giorni. Nessun caso di positivit\u00e0 tra il personale sanitario.<\/li><li><strong>Policlinico Umberto I<\/strong>:&nbsp; Deceduta una donna di 69 anni con precedenti patologie. 164 pazienti ricoverati di cui 17 in terapia intensiva. 2 pazienti guariti.<\/li><li><strong>Policlinico Tor Vergata:<\/strong>&nbsp;17 pazienti ricoverati in terapia intensiva. 3 pazienti guariti.<\/li><li><strong>Policlinico Gemelli:<\/strong>&nbsp;143 pazienti ricoverati al Covid Hospital Columbus di cui 27 in terapia intensiva. 6 pazienti guariti.<\/li><li><strong>Policlinico Campus Biomedico di Roma:<\/strong>&nbsp;7 pazienti guariti. 28 pazienti ricoverati al Covid Center Campus Biomedico di cui 11 in terapia intensiva. Il 55% degli operatori sanitari sono stati sottoposti a sorveglianza sanitaria: 0 positivi.<\/li><li><strong>Ospedale Pediatrico Bambino Ges\u00f9<\/strong>: &nbsp;18 ricoveri Covid di cui 11 bambini e 7 genitori. In giornata, secondo trasferimento precauzionale in terapia intensiva per monitoraggio stato infiammatorio di una bambina di 11 anni. Prevista dimissione di 2 bambini guariti.<\/li><li><strong>Ares 118<\/strong>: Operativo al numero verde 800.118.800 il servizio di assistenza psicologica per i cittadini<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sono ottanta i nuovi casi di Coronavirus registrati in tutta la regione Lazio nelle ultime 24 ore. In provincia di<\/p>\n","protected":false},"author":18,"featured_media":29866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[254,94,8896,8337,93,102],"class_list":["post-33800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-arpino","tag-ciociaria","tag-contagi","tag-coronavirus","tag-frosinone","tag-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coronavirus, cinque nuovi casi e un decesso ad Arpino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, cinque nuovi casi e un decesso ad Arpino\" \/>\n<meta property=\"og:description\" content=\"Sono ottanta i nuovi casi di Coronavirus registrati in tutta la regione Lazio nelle ultime 24 ore. In provincia di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T15:05:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-21T15:15:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"548\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Coronavirus, cinque nuovi casi e un decesso ad Arpino\",\"datePublished\":\"2020-04-21T15:05:26+00:00\",\"dateModified\":\"2020-04-21T15:15:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/\"},\"wordCount\":852,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus.jpg\",\"keywords\":[\"arpino\",\"Ciociaria\",\"contagi\",\"coronavirus\",\"Frosinone\",\"Lazio\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/\",\"name\":\"Coronavirus, cinque nuovi casi e un decesso ad Arpino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus.jpg\",\"datePublished\":\"2020-04-21T15:05:26+00:00\",\"dateModified\":\"2020-04-21T15:15:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus.jpg\",\"width\":548,\"height\":387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, cinque nuovi casi e un decesso ad Arpino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/21\\\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coronavirus, cinque nuovi casi e un decesso ad Arpino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, cinque nuovi casi e un decesso ad Arpino","og_description":"Sono ottanta i nuovi casi di Coronavirus registrati in tutta la regione Lazio nelle ultime 24 ore. In provincia di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-21T15:05:26+00:00","article_modified_time":"2020-04-21T15:15:25+00:00","og_image":[{"width":548,"height":387,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Coronavirus, cinque nuovi casi e un decesso ad Arpino","datePublished":"2020-04-21T15:05:26+00:00","dateModified":"2020-04-21T15:15:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/"},"wordCount":852,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg","keywords":["arpino","Ciociaria","contagi","coronavirus","Frosinone","Lazio"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/","name":"Coronavirus, cinque nuovi casi e un decesso ad Arpino - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg","datePublished":"2020-04-21T15:05:26+00:00","dateModified":"2020-04-21T15:15:25+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus.jpg","width":548,"height":387},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, cinque nuovi casi e un decesso ad Arpino"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/21\/coronavirus-cinque-nuovi-casi-e-un-decesso-ad-arpino\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=33800"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33800\/revisions"}],"predecessor-version":[{"id":33810,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33800\/revisions\/33810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/29866"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=33800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=33800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=33800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}