{"id":33466,"date":"2020-04-16T01:58:05","date_gmt":"2020-04-15T23:58:05","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=33466"},"modified":"2020-04-16T10:14:58","modified_gmt":"2020-04-16T08:14:58","slug":"spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/","title":{"rendered":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Il presidente della Regione Lazio Nicola Zingaretti ha firmato l&#8217;ordinanza regionale <\/strong>a favore degli spostamenti degli agricoltori hobbisti con la quale si concedono tutti gli spostamenti, all&#8217;interno del proprio comune o nei pressi dei comuni limitrofi, volti allo svolgimento amatoriale di attivit\u00e0 agricole e\/o di allevamenti di animali da cortile, ritenute essenziali e di assoluta urgenza e necessit\u00e0. Gli spostamenti sono concessi per pi\u00f9 di una volta al giorno, ma dovranno essere effettuati da un unico componente del nucleo familiare. Sono escluse dall\u2019applicazione dell\u2019ordinanza le zone rosse regionali<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;A seguito anche di nostre reiterate richieste come gruppo di Forza Italia di Frosinone \u00e8 stata firmata l&#8217;ordinanza regionale a favore degli spostamenti degli agricoltori e degli hobbisti.-<strong>dichiarano i consiglieri provinciali di FI Gianluca Quadrini presidente del gruppo azzurro e Gioacchino Ferdinandi, <\/strong>sindaco di Piedimonte San Germano-. Ringraziamo il presidente regionale Nicola Zingaretti e l\u2019assessore all\u2019Agricoltura Enrica Onorati per la sensibilit\u00e0 avuta nel firmare l\u2019ordinanza che permette agli agricoltori di spostarsi per coltivare i terreni. Un appello da noi prontamente lanciato a favore dei tanti agricoltori e hobbisti della nostra provincia, che da mesi si vedono costretti a non poter raggiungere i propri terreni con danni irreparabili ed ora finalmente accolto\u201d.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente della Regione Lazio Nicola Zingaretti ha firmato l&#8217;ordinanza regionale a favore degli spostamenti degli agricoltori hobbisti con la<\/p>\n","protected":false},"author":18,"featured_media":28361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[669,94,1251,4725,918,9443],"class_list":["post-33466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-agricoltura","tag-ciociaria","tag-gianluca-quadrini","tag-gioacchino-ferdinandi","tag-nicola-zingaretti","tag-spostamenti-in-agricoltura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti\" \/>\n<meta property=\"og:description\" content=\"Il presidente della Regione Lazio Nicola Zingaretti ha firmato l&#8217;ordinanza regionale a favore degli spostamenti degli agricoltori hobbisti con la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T23:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T08:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti\",\"datePublished\":\"2020-04-15T23:58:05+00:00\",\"dateModified\":\"2020-04-16T08:14:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ferdinandi-quadrini.jpg\",\"keywords\":[\"agricoltura\",\"Ciociaria\",\"Gianluca Quadrini\",\"Gioacchino Ferdinandi\",\"nicola zingaretti\",\"spostamenti in agricoltura\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/\",\"name\":\"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ferdinandi-quadrini.jpg\",\"datePublished\":\"2020-04-15T23:58:05+00:00\",\"dateModified\":\"2020-04-16T08:14:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ferdinandi-quadrini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/ferdinandi-quadrini.jpg\",\"width\":1600,\"height\":760,\"caption\":\"Ferdinandi e Quadrini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/16\\\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/","og_locale":"it_IT","og_type":"article","og_title":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti","og_description":"Il presidente della Regione Lazio Nicola Zingaretti ha firmato l&#8217;ordinanza regionale a favore degli spostamenti degli agricoltori hobbisti con la","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-15T23:58:05+00:00","article_modified_time":"2020-04-16T08:14:58+00:00","og_image":[{"width":1600,"height":760,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti","datePublished":"2020-04-15T23:58:05+00:00","dateModified":"2020-04-16T08:14:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg","keywords":["agricoltura","Ciociaria","Gianluca Quadrini","Gioacchino Ferdinandi","nicola zingaretti","spostamenti in agricoltura"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/","name":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg","datePublished":"2020-04-15T23:58:05+00:00","dateModified":"2020-04-16T08:14:58+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/ferdinandi-quadrini.jpg","width":1600,"height":760,"caption":"Ferdinandi e Quadrini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Spostamenti agricoltori hobbisti. Quadrini e Ferdinandi ringraziano Zingaretti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/16\/spostamenti-agricoltori-hobbisti-quadrini-e-ferdinadi-ringraziano-zingaretti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=33466"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33466\/revisions"}],"predecessor-version":[{"id":33486,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33466\/revisions\/33486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/28361"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=33466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=33466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=33466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}