{"id":33385,"date":"2020-04-15T09:55:45","date_gmt":"2020-04-15T07:55:45","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=33385"},"modified":"2020-04-15T09:55:51","modified_gmt":"2020-04-15T07:55:51","slug":"covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/","title":{"rendered":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Casa del Maestro di Fiuggi \u00e8 una <strong>struttura ricettiva di propriet\u00e0 dell&#8217;Inps <\/strong>affidata temporaneamente all\u2019Agenzia Regionale di Protezione Civile <strong>per assicurare ospitalit\u00e0 a persone che<\/strong>, su richiesta della Asl, <strong>devono essere poste in via d\u2019urgenza in isolamento fiduciario<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di coloro che hanno necessit\u00e0 di essere messi  in isolamento al di fuori della propria residenza o del proprio domicilio perch\u00e9 non dispongono di altra o diversa soluzione alloggiativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ieri, dunque, sono arrivati nella struttura i primi pazienti che trascorreranno l\u00ec <\/strong>il periodo di tempo necessario per guarire dal virus. Sono pazienti sintomatici, senza necessit\u00e0 di ricovero, appena positivizzati a tampone e\/o dimessi dall&#8217;ospedale in condizioni stabili ma ancora positivi oppure di coloro che, negativi al tampone, devono osservare un periodo di quarantena.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La struttura e le professionalit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lo stabile pu\u00f2 ospitare da subito dieci persone, con possibilit\u00e0 di arrivare in seguito fino a 40 ospiti. Possono essere inviati dal Servizio Igiene Pubblica diretto dal <strong>dottor Giuseppe Di Luzio <\/strong>(se si trovano a domicilio) o dal Referente del Reparto ospedaliero (se sono in uscita dall&#8217;ospedale), attraverso il Bed Manager aziendale,<strong> dottor Giampiero Fabi<\/strong> mentre il Coordinamento dell\u2019attivit\u00e0 della struttura alberghiera \u2013 articolato con le diverse professionalit\u00e0 coinvolte \u2013 \u00e8 affidato al <strong>dottor  Marcello Russo<\/strong>, Direttore del Dipartimento Assistenza Cure Primarie ed al <strong>dottor Ciro D\u2019Ambrosio<\/strong> in quanto direttore del Reparto Medicina Covid di Frosinone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"455\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro1.jpg\" alt=\"casa maestro fiuggi il corriere della provincia\" class=\"wp-image-33389\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro1.jpg 737w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro1-300x185.jpg 300w\" sizes=\"auto, (max-width: 737px) 100vw, 737px\" \/><figcaption>Uno degli spazi interni della Casa del Maestro<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alla struttura si accede nelle fasce orarie 8,30-10,30  e  15,30-17,30 e il trasferimento dei pazienti avviene tramite il 118. Una decisione importante che ha visto coinvolti Enti ai diversi livelli istituzionali e che, per la Asl di Frosinone, \u00e8 stata seguita direttamente dal Direttore Amministrativo Pierpaola D\u2019Alessandro, oggi dg facente funzioni.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le dichiarazioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Possiamo ufficializzare \u2013  ha spiegato ieri il dg facente funzioni Pierpaola D\u2019Alessandro \u2013 di aver inviato i primi due pazienti presso la struttura alberghiera Casa del Maestro di Fiuggi&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"458\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-interno.jpg\" alt=\"casa maestro fiuggi interno il corriere della provincia\" class=\"wp-image-33392\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-interno.jpg 687w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-interno-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-interno-272x182.jpg 272w\" sizes=\"auto, (max-width: 687px) 100vw, 687px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dottoressa ha fatto sapere che gi\u00e0 da oggi potranno accedere altri 3-4 pazienti. &#8220;L\u2019iniziativa &#8211; ha continuato &#8211; \u00e8 stata fortemente voluta dalla Regione Lazio che ha sottoscritto apposita Convenzione con Inps e ha visto il fattivo concorso sinergico, un grosso lavoro di squadra, di Protezione Civile, Prefettura, Asl e Croce Rossa che, fra l\u2019altro, garantisce la consegna dei pasti ed il servizio di guardiania&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"776\" height=\"498\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/lorusso-dottoressa.jpg\" alt=\"d'alessandro asl lorusso il corriere della provincia\" class=\"wp-image-27824\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/lorusso-dottoressa.jpg 776w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/lorusso-dottoressa-300x193.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/lorusso-dottoressa-768x493.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/lorusso-dottoressa-500x321.jpg 500w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><figcaption>Il direttore amministrativo Pierpaola D&#8217;Alessandro con il dg Stefano Lorusso <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Desidero ringraziare tutti loro \u2013 ha concluso il dg facente funzioni &#8211; e le nostre Aree interne che ne assicureranno il funzionamento ed il monitoraggio con un impegnativo lavoro clinico-sanitario-operativo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da ieri sono stati trasferiti i primi pazienti risultati positivi al Covid-19 nella struttura Inps &#8216;La Casa del Maestro&#8217; di Fiuggi dove passeranno il periodo di isolamento<\/p>\n","protected":false},"author":18,"featured_media":33390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,11],"tags":[108,9298,94,5775,1902,217,93,2139,894,2597,8720],"class_list":["post-33385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-salute","tag-asl","tag-casa-del-maestro","tag-ciociaria","tag-dg","tag-direttore-generale","tag-fiuggi","tag-frosinone","tag-inps","tag-pazienti","tag-struttura","tag-virus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi\" \/>\n<meta property=\"og:description\" content=\"Da ieri sono stati trasferiti i primi pazienti risultati positivi al Covid-19 nella struttura Inps &#039;La Casa del Maestro&#039; di Fiuggi dove passeranno il periodo di isolamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T07:55:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-15T07:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"692\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi\",\"datePublished\":\"2020-04-15T07:55:45+00:00\",\"dateModified\":\"2020-04-15T07:55:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/\"},\"wordCount\":437,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/casa-maestro-esterna.jpg\",\"keywords\":[\"Asl\",\"casa del maestro\",\"Ciociaria\",\"dg\",\"direttore generale\",\"Fiuggi\",\"Frosinone\",\"inps\",\"pazienti\",\"struttura\",\"virus\"],\"articleSection\":[\"*SLIDE*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/\",\"name\":\"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/casa-maestro-esterna.jpg\",\"datePublished\":\"2020-04-15T07:55:45+00:00\",\"dateModified\":\"2020-04-15T07:55:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/casa-maestro-esterna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/casa-maestro-esterna.jpg\",\"width\":692,\"height\":476,\"caption\":\"La Casa del Maestro a Fiuggi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/15\\\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/","og_locale":"it_IT","og_type":"article","og_title":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi","og_description":"Da ieri sono stati trasferiti i primi pazienti risultati positivi al Covid-19 nella struttura Inps 'La Casa del Maestro' di Fiuggi dove passeranno il periodo di isolamento","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-15T07:55:45+00:00","article_modified_time":"2020-04-15T07:55:51+00:00","og_image":[{"width":692,"height":476,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi","datePublished":"2020-04-15T07:55:45+00:00","dateModified":"2020-04-15T07:55:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/"},"wordCount":437,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg","keywords":["Asl","casa del maestro","Ciociaria","dg","direttore generale","Fiuggi","Frosinone","inps","pazienti","struttura","virus"],"articleSection":["*SLIDE*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/","name":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg","datePublished":"2020-04-15T07:55:45+00:00","dateModified":"2020-04-15T07:55:51+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/casa-maestro-esterna.jpg","width":692,"height":476,"caption":"La Casa del Maestro a Fiuggi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Covid-19: da ieri i primi pazienti in isolamento nella Casa del Maestro di Fiuggi"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/15\/covid-19-da-ieri-i-primi-pazienti-in-isolamento-nella-casa-del-maestro-di-fiuggi\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=33385"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33385\/revisions"}],"predecessor-version":[{"id":33396,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33385\/revisions\/33396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/33390"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=33385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=33385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=33385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}