{"id":33105,"date":"2020-04-09T17:22:43","date_gmt":"2020-04-09T15:22:43","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=33105"},"modified":"2020-04-09T17:22:46","modified_gmt":"2020-04-09T15:22:46","slug":"buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/","title":{"rendered":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> \u201c<strong>Come avevamo annunciato,<\/strong> la Regione Lazio ha trovato le risorse per dare una risposta anche sul tema degli affitti\u201d. <strong>Lo dichiara in un video sulla sua pagina Facebook il Presidente del Consiglio regionale del Lazio, Mauro Buschini<\/strong>, in merito allo stanziamento di 43 milioni di euro per il sostegno agli affitti per le persone in difficolt\u00e0 in questo periodo di emergenza.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Sono state infatti approvate<\/strong> \u2013 prosegue &#8211; le delibere per il sostegno agli affitti per cittadini e famiglie che vivono una situazione di disagio. \u00c8 la prima risposta e ne seguiranno altre che interesseranno le attivit\u00e0 commerciali. La Regione continua ad affrontare questa crisi stando dalla parte delle persone\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCome avevamo annunciato, la Regione Lazio ha trovato le risorse per dare una risposta anche sul tema degli affitti\u201d. Lo<\/p>\n","protected":false},"author":18,"featured_media":1785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236],"tags":[7550,94,8337,1388,562,926],"class_list":["post-33105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","tag-affitti","tag-ciociaria","tag-coronavirus","tag-mauro-buschini","tag-regione-lazio","tag-sostegno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0\" \/>\n<meta property=\"og:description\" content=\"\u201cCome avevamo annunciato, la Regione Lazio ha trovato le risorse per dare una risposta anche sul tema degli affitti\u201d. Lo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T15:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T15:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0\",\"datePublished\":\"2020-04-09T15:22:43+00:00\",\"dateModified\":\"2020-04-09T15:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/\"},\"wordCount\":122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/buschini-3.jpg\",\"keywords\":[\"affitti\",\"Ciociaria\",\"coronavirus\",\"mauro buschini\",\"regione lazio\",\"sostegno\"],\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/\",\"name\":\"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/buschini-3.jpg\",\"datePublished\":\"2020-04-09T15:22:43+00:00\",\"dateModified\":\"2020-04-09T15:22:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/buschini-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/buschini-3.jpg\",\"width\":512,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/09\\\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/","og_locale":"it_IT","og_type":"article","og_title":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0","og_description":"\u201cCome avevamo annunciato, la Regione Lazio ha trovato le risorse per dare una risposta anche sul tema degli affitti\u201d. Lo","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-09T15:22:43+00:00","article_modified_time":"2020-04-09T15:22:46+00:00","og_image":[{"width":512,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0","datePublished":"2020-04-09T15:22:43+00:00","dateModified":"2020-04-09T15:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/"},"wordCount":122,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg","keywords":["affitti","Ciociaria","coronavirus","mauro buschini","regione lazio","sostegno"],"articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/","name":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg","datePublished":"2020-04-09T15:22:43+00:00","dateModified":"2020-04-09T15:22:46+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/buschini-3.jpg","width":512,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Buschini: dalla Regione 43 milioni di euro per sostegno affitti a famiglie e cittadini in difficolt\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/09\/buschini-dalla-regione-43-milioni-di-euro-per-sostegno-affitti-a-famiglie-e-cittadini-in-difficolta\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=33105"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33105\/revisions"}],"predecessor-version":[{"id":33106,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/33105\/revisions\/33106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/1785"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=33105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=33105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=33105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}