{"id":32857,"date":"2020-04-05T15:39:28","date_gmt":"2020-04-05T13:39:28","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=32857"},"modified":"2020-04-05T15:53:55","modified_gmt":"2020-04-05T13:53:55","slug":"coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/","title":{"rendered":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Si \u00e8 appena conclusa<\/strong>, alla presenza dell&#8217;assessore alla Sanit\u00e0 e l\u2019Integrazione Sociosanitaria della Regione Lazio, Alessio D\u2019Amato, l\u2019odierna videoconferenza della task-force regionale per il COVID-19 con i direttori generali delle Asl, Aziende ospedaliere e Policlinici universitari e ospedale Pediatrico Bambino Ges\u00f9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"712\" height=\"449\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/sanificazione-ospedale-alatri3.jpg\" alt=\"ospedale alatri san benedetto il corriere della provincia\" class=\"wp-image-32809\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/sanificazione-ospedale-alatri3.jpg 712w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/sanificazione-ospedale-alatri3-300x189.jpg 300w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/><figcaption>I Vigili  del fuoco all&#8217;ospedale di Alatri<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">La situazione in Ciociaria<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diciotto  nuovi casi positivi, tre morti<\/strong> e due pazienti guariti.  Questi i dati per  quel che concerne la provincia di Frosinone. Le persone uscite dall\u2019isolamento domiciliare ammontano a 301. <strong>Completate le operazioni di sanificazione del Pronto Soccorso di Alatri <\/strong>da parte dei Vigili del Fuoco.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/damato-1024x576.jpg\" alt=\"\" class=\"wp-image-32858\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/damato-1024x576.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/damato-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/damato-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/04\/damato.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento dell&#8217;assessore<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nel Lazio <strong>oggi registriamo un dato di 123 casi di positivit\u00e0<\/strong>, continua la frenata del trend che per la prima volta \u00e8 al 3%. Ora \u00e8 il momento di non mollare e mantenere alta l\u2019attenzione anche in vista delle festivit\u00e0 di Pasqua e Pasquetta. Da luned\u00ec partono le prime RSA COVID con i primi 100 posti a disposizione sul territorio.  Sono in continua crescita i guariti che salgono di 36 unit\u00e0 nelle ultime 24 ore arrivando a 475 totali. Sono usciti dalla sorveglianza domiciliare in 9.921 e i decessi nelle ultime 24 ore sono stati 7&#8243;. <strong>Ha affermato D&#8217;Amato<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La nuova app della Regione <\/strong>\u2018LazioDrCovid\u2019 in collaborazione con i medici di medicina generale e i pediatri di libera scelta, ha gi\u00e0 registrato oltre 80 mila utenti che hanno scaricato l\u2019applicazione e 2.200 medici di famiglia e 300 pediatri di libera scelta collegati. <strong>Per quanto riguarda infine i dispositivi di protezione individuale<\/strong>  &#8211; ha concluso &#8211; oggi sono in distribuzione presso le strutture sanitarie: 65.000 mascherine chirurgiche, 33.000 maschere FFP2, 3.500 maschere FFP3, 6.100 camici impermeabili, 29.200 calzari, 69.000 guanti, 22.000 cuffie. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le altre asl<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 1 <\/strong>\u2013 18 nuovi casi positivi. 1.416 le persone che sono uscite dall\u2019isolamento domiciliare;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 2 <\/strong>\u2013 7 nuovi casi positivi. 36 le persone che sono uscite dall\u2019isolamento domiciliare. Continuano i controlli nelle case di cura e RSA del territorio. Attivato accordo con albergo Urban per i pazienti positivi in isolamento domiciliare;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 3 <\/strong>\u2013 11 nuovi casi positivi. 3 i pazienti che sono guariti. 1.457 le persone che sono uscite dall\u2019isolamento domiciliare. Domani verranno attivati 4 posti di terapia intensiva all\u2019Ospedale Grassi;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 4 <\/strong>\u2013 15 nuovi casi positivi. 1.469 le persone che sono uscite dall\u2019isolamento domiciliare;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 5 <\/strong>\u2013 24 nuovi casi positivi. 4 i pazienti che sono guariti. Deceduto un uomo di 90 anni con precedenti patologie. 1.517 le persone che sono uscite dall\u2019isolamento domiciliare. Al COVID Hospital Palestrina ricoverati 38 pazienti. Avviati i tamponi alla casa di riposo abusiva di Fonte Nuova;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 6 <\/strong>\u2013 3 nuovi casi positivi. 10 pazienti sono guariti. 79 le persone che sono uscite dall\u2019isolamento domiciliare. A Genzano da oggi operativo il laboratorio per il test COVID. Continuano i controlli nelle case di riposo e RSA del territorio;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Latina<\/strong> \u2013 18 nuovi casi positivi. 2 i pazienti che sono guariti;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Viterbo<\/strong> &#8211; 7 nuovi casi positivi. 2 i pazienti che sono guariti. 2.170 le persone che sono uscite dall\u2019isolamento domiciliare. Continuano le verifiche nelle case di riposo del territorio, a Villa Immacolata tutti i tamponi sono negativi. Celleno: intera famiglia positiva dopo una cena nonostante l\u2019obbligo di quarantena, saranno segnalati;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Rieti <\/strong>\u2013 2 nuovi casi positivi. 2 i pazienti che sono guariti. Decedute 3 donne ultraottantenni con patologie preesistenti. 31 le persone che sono uscite dall\u2019isolamento domiciliare. Continuano i controlli sulle 77 case di riposo e RSA del territorio;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Umberto I<\/strong> \u2013 5 i pazienti guariti;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera San Giovanni<\/strong> &#8211; Dal 7 Aprile sar\u00e0 attivato il laboratorio per il test COVID h24;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera Sant\u2019Andrea<\/strong> &#8211; Attivo servizio psicologico per cittadini e operatori h24;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Gemelli<\/strong> &#8211; Sono stati dimessi 7 pazienti;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Spallanzani <\/strong>&#8211; Per la prima volta i pazienti dimessi sono superiori ai ricoverati. Domani saranno attivati ulteriori 10 posti letto di terapia intensiva;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Tor Vergata<\/strong> \u2013 5 i pazienti che sono guariti. il 7 aprile saranno attivati ulteriori 16 posti letto dedicati;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera San Camill<\/strong>o &#8211; Attivato il laboratorio per il test COVID;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ospedale Pediatrico Bambino Ges\u00f9 <\/strong>&#8211; Nelle ultime 24 ore, 1 paziente dimesso ed 1 nuovo ricovero: ragazza di 15 anni trasferita da Frosinone. I 4 neonati e le mamme provenienti da Civitavecchia stanno bene, condizioni stabili;<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>IFO<\/strong> &#8211; Domani sar\u00e0 operativo il laboratorio per il test COVID;<br>Universit\u00e0 Campus Bio-Medico \u2013 arrivato al COVID Center il primo paziente trasferito in elicottero da Bergamo per essere curato in terapia intensiva. Attualmente ricoverati 8 pazienti in terapia intensiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 appena conclusa, alla presenza dell&#8217;assessore alla Sanit\u00e0 e l\u2019Integrazione Sociosanitaria della Regione Lazio, Alessio D\u2019Amato, l\u2019odierna videoconferenza della<\/p>\n","protected":false},"author":18,"featured_media":31177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[368,3968,94,8337,93,1703],"class_list":["post-32857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-alatri","tag-alessio-damato","tag-ciociaria","tag-coronavirus","tag-frosinone","tag-morti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 appena conclusa, alla presenza dell&#8217;assessore alla Sanit\u00e0 e l\u2019Integrazione Sociosanitaria della Regione Lazio, Alessio D\u2019Amato, l\u2019odierna videoconferenza della\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-05T13:39:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-05T13:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute\",\"datePublished\":\"2020-04-05T13:39:28+00:00\",\"dateModified\":\"2020-04-05T13:53:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/\"},\"wordCount\":713,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-3.jpg\",\"keywords\":[\"alatri\",\"alessio d'amato\",\"Ciociaria\",\"coronavirus\",\"Frosinone\",\"morti\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/\",\"name\":\"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-3.jpg\",\"datePublished\":\"2020-04-05T13:39:28+00:00\",\"dateModified\":\"2020-04-05T13:53:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-3.jpg\",\"width\":654,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/04\\\/05\\\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute","og_description":"Si \u00e8 appena conclusa, alla presenza dell&#8217;assessore alla Sanit\u00e0 e l\u2019Integrazione Sociosanitaria della Regione Lazio, Alessio D\u2019Amato, l\u2019odierna videoconferenza della","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-04-05T13:39:28+00:00","article_modified_time":"2020-04-05T13:53:55+00:00","og_image":[{"width":654,"height":368,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute","datePublished":"2020-04-05T13:39:28+00:00","dateModified":"2020-04-05T13:53:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/"},"wordCount":713,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg","keywords":["alatri","alessio d'amato","Ciociaria","coronavirus","Frosinone","morti"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/","name":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg","datePublished":"2020-04-05T13:39:28+00:00","dateModified":"2020-04-05T13:53:55+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-3.jpg","width":654,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, in provincia di Frosinone diciotto nuovi casi e tre persone decedute"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/04\/05\/coronavirus-in-provincia-di-frosinone-diciotto-nuovi-casi-e-tre-persone-decedute\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=32857"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32857\/revisions"}],"predecessor-version":[{"id":32862,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32857\/revisions\/32862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/31177"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=32857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=32857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=32857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}