{"id":3233,"date":"2018-12-14T14:52:53","date_gmt":"2018-12-14T13:52:53","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=3233"},"modified":"2018-12-14T15:00:40","modified_gmt":"2018-12-14T14:00:40","slug":"rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/","title":{"rendered":"Rifiuti da Roma: &#8220;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&#8221;"},"content":{"rendered":"<div dir=\"ltr\">\n<p class=\"m_-629964673734266284gmail-yiv8314638912ydp7e978b6cmsonormal\">\u201cPurtroppo \u00e8 una situazione gi\u00e0 vissuta, che chiama in causa direttamente le mancanze dell\u2019Amministrazione comunale di Roma. La Capitale d\u2019Italia, simbolo del nostro Paese, non pu\u00f2 non essere in\u00a0 grado di gestire un servizio fondamentale per i cittadini come la raccolta e lo smaltimento dei rifiuti. Non \u00e8 pi\u00f9 concepibile che si continui a rinviare una soluzione e si faccia sempre affidamento alle capacit\u00e0 altrui\u201d.<\/p>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3228 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Antonio-Pompeo-e1544794993808.jpg\" alt=\"pompeo provincia fca ilva vertenza frosinone il corriere della provincia ciociaria\" width=\"570\" height=\"380\" \/><\/p>\n<div dir=\"ltr\">\n<p class=\"m_-629964673734266284gmail-yiv8314638912ydp7e978b6cmsonormal\">Questo \u00e8 quanto fa notare il Presidente della Provincia di Frosinone Antonio Pompeo, che aggiunge: \u201cRoma sta dimostrando di non avere nessuna strategia sullo smaltimento dei rifiuti, appoggiandosi sempre agli impianti di altri territori. Una strada che non pu\u00f2 essere percorsa all\u2019infinito e che, come gi\u00e0 annunciato dalla sindaca, produrr\u00e0 anche degli aumenti sulla Tari per i contribuenti capitolini\u201d.<\/p>\n<h3>Una situazione che crea difficolt\u00e0<\/h3>\n<p class=\"m_-629964673734266284gmail-yiv8314638912ydp7e978b6cmsonormal\">\u201cTra l\u2019altro la Provincia di Frosinone \u00e8 fortemente impegnata sul potenziamento della raccolta differenziata, sia con risorse per i servizi e le strutture ai Comuni, sia con una campagna di sensibilizzazione rivolta ai cittadini,<strong> \u201cSave Ciociaria\u201d<\/strong>. Stiamo lavorando da tempo e per tempo per non soffrire quello che sta vivendo Roma e questa situazione pu\u00f2 mettere in difficolt\u00e0 anche chi comunque ha un sistema che funziona. In sede di confronto con la Regione Lazio, per l\u2019aggiornamento del Piano dei Rifiuti, chiederemo espressamente e con forza il rispetto del principio dell\u2019autosufficienza dei territori, non solo a tutela dei nostri cittadini, ma anche perch\u00e9 Il tempo degli slogan \u00e8 finito. Roma faccia il suo dovere, come lo stanno facendo le Province del Lazio\u201d.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPurtroppo \u00e8 una situazione gi\u00e0 vissuta, che chiama in causa direttamente le mancanze dell\u2019Amministrazione comunale di Roma. La Capitale d\u2019Italia,<\/p>\n","protected":false},"author":18,"featured_media":3240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1166,85,83],"class_list":["post-3233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-emergenza-rifiuti","tag-pompeo","tag-provincia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rifiuti da Roma: &quot;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&quot; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifiuti da Roma: &quot;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&quot;\" \/>\n<meta property=\"og:description\" content=\"\u201cPurtroppo \u00e8 una situazione gi\u00e0 vissuta, che chiama in causa direttamente le mancanze dell\u2019Amministrazione comunale di Roma. La Capitale d\u2019Italia,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-14T13:52:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-14T14:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Rifiuti da Roma: &#8220;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&#8221;\",\"datePublished\":\"2018-12-14T13:52:53+00:00\",\"dateModified\":\"2018-12-14T14:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/rifiuti-nuova.jpg\",\"keywords\":[\"Emergenza rifiuti\",\"pompeo\",\"provincia\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/\",\"name\":\"Rifiuti da Roma: \\\"la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita\\\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/rifiuti-nuova.jpg\",\"datePublished\":\"2018-12-14T13:52:53+00:00\",\"dateModified\":\"2018-12-14T14:00:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/rifiuti-nuova.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/rifiuti-nuova.jpg\",\"width\":696,\"height\":348,\"caption\":\"rifiuti roma pompeo il corriere della provincia virgina raggi ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifiuti da Roma: &#8220;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/12\\\/14\\\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rifiuti da Roma: \"la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/","og_locale":"it_IT","og_type":"article","og_title":"Rifiuti da Roma: \"la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita\"","og_description":"\u201cPurtroppo \u00e8 una situazione gi\u00e0 vissuta, che chiama in causa direttamente le mancanze dell\u2019Amministrazione comunale di Roma. La Capitale d\u2019Italia,","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2018-12-14T13:52:53+00:00","article_modified_time":"2018-12-14T14:00:40+00:00","og_image":[{"width":696,"height":348,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Rifiuti da Roma: &#8220;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&#8221;","datePublished":"2018-12-14T13:52:53+00:00","dateModified":"2018-12-14T14:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg","keywords":["Emergenza rifiuti","pompeo","provincia"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/","name":"Rifiuti da Roma: \"la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg","datePublished":"2018-12-14T13:52:53+00:00","dateModified":"2018-12-14T14:00:40+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/rifiuti-nuova.jpg","width":696,"height":348,"caption":"rifiuti roma pompeo il corriere della provincia virgina raggi ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Rifiuti da Roma: &#8220;la reponsabilit\u00e0 dei territori non pu\u00f2 essere infinita&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/12\/14\/rifiuti-da-roma-pompeo-la-reponsabilita-dei-territori-non-puo-essere-infinita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=3233"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3233\/revisions"}],"predecessor-version":[{"id":3242,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/3233\/revisions\/3242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3240"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=3233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=3233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=3233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}