{"id":32021,"date":"2020-03-26T14:22:19","date_gmt":"2020-03-26T13:22:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=32021"},"modified":"2020-03-27T10:05:34","modified_gmt":"2020-03-27T09:05:34","slug":"controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/","title":{"rendered":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diciannove unit\u00e0, due turni\ngiornalieri da sei ore ciascuno e sei pattuglie dislocate sul\nterritorio per monitorare gli spostamenti e accertare il rispetto\ndelle regole, anche in base al recente decreto dei ministri Speranza\ne Lamorgese, che vieta di lasciare il comune o la citt\u00e0 in cui ci si\ntrovi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli uomini del corpo di Polizia provinciale, agli ordini del comandante Pietro D&#8217;Aguanno, sono impegnati gi\u00e0 da una settimana nei servizi di controllo delle strade <\/strong>al fine di verificare il rispetto delle norme sugli spostamenti e segnalare eventuali anomalie. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non solo: da qualche giorno hanno iniziato anche il controllo all&#8217;esterno di supermercati e attivit\u00e0 commerciali per garantire l&#8217;osservanza delle misure di sicurezza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le parole del comandante D&#8217;Aguanno<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dal primo giorno in cui siamo\nstati incaricati di effettuare pattugliamenti sulle strade del\nterritorio \u2013 fa sapere il comandante D&#8217;Aguanno \u2013 abbiamo\ncontrollato 555 veicoli \u2013 il dato \u00e8 riferito alla giornata di\nieri, 25 marzo &#8211; ed elevato quattro denunce per inosservanza dei\nprovvedimenti dell&#8217;autorit\u00e0 (ex art.650 c.p.) che ora, in virt\u00f9\ndelle nuove disposizioni governative, si trasformeranno in sanzioni\npecuniarie amministrative. Abbiamo anche provveduto a verificare il\ncorretto comportamento dei cittadini davanti agli ingressi di\nsupermercati e attivit\u00e0 commerciali, dove inevitabilmente si formano\nle file e va, quindi, assicurato il rispetto delle misure di\nsicurezza&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il ringraziamento di Pompeo e Caperna<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il presidente della Provincia, Antonio Pompeo, insieme al consigliere delegato alla Polizia provinciale, Germano Caperna, ringraziano il corpo della polizia provinciale &#8220;per il prezioso lavoro che sta portando avanti in un momento in cui il pieno e totale rispetto dei provvedimenti emanati dal Governo e dalla Regione \u00e8 l&#8217;unico modo di frenare i contagi e uscire, nel minor tempo possibile, da questa situazione&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/pompeo-e-Caperna.jpg\" alt=\"\" class=\"wp-image-28833\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/pompeo-e-Caperna.jpg 720w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/pompeo-e-Caperna-300x200.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/pompeo-e-Caperna-500x333.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/pompeo-e-Caperna-272x182.jpg 272w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption>Il presidente della Provincia Antonio Pompeo e il consigliere Germano Caperna<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Cogliamo l&#8217;occasione &#8211; concludono &#8211; per rinnovare a tutti i cittadini l&#8217;appello a restare in casa, a muoversi solo ed eslcusivamente per esigenze necessarie e consentite ma, soprattutto, a collaborare con tutte le autorit\u00e0 che si stanno occupando di questa emergenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polizia provinciale sta effettuando controlli sulle strade del territorio per l&#8217;emergenza Covid-19: fermati 555 veicoli ed elevate quattro denunce<\/p>\n","protected":false},"author":18,"featured_media":32025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[842,94,209,8337,8722,2552,93,1293,439,83],"class_list":["post-32021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-antonio-pompeo","tag-ciociaria","tag-controlli","tag-coronavirus","tag-covid-19","tag-emergenza","tag-frosinone","tag-germano-caperna","tag-polizia-provinciale","tag-provincia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce\" \/>\n<meta property=\"og:description\" content=\"La polizia provinciale sta effettuando controlli sulle strade del territorio per l&#039;emergenza Covid-19: fermati 555 veicoli ed elevate quattro denunce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T13:22:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-27T09:05:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"708\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce\",\"datePublished\":\"2020-03-26T13:22:19+00:00\",\"dateModified\":\"2020-03-27T09:05:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/controlli-polizia-provinciale-1.jpg\",\"keywords\":[\"antonio pompeo\",\"Ciociaria\",\"controlli\",\"coronavirus\",\"covid 19\",\"emergenza\",\"Frosinone\",\"germano caperna\",\"polizia provinciale\",\"provincia\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/\",\"name\":\"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/controlli-polizia-provinciale-1.jpg\",\"datePublished\":\"2020-03-26T13:22:19+00:00\",\"dateModified\":\"2020-03-27T09:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/controlli-polizia-provinciale-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/controlli-polizia-provinciale-1.jpg\",\"width\":708,\"height\":425,\"caption\":\"Controlli della polizia provinciale sulle strade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/26\\\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/","og_locale":"it_IT","og_type":"article","og_title":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce","og_description":"La polizia provinciale sta effettuando controlli sulle strade del territorio per l'emergenza Covid-19: fermati 555 veicoli ed elevate quattro denunce","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-26T13:22:19+00:00","article_modified_time":"2020-03-27T09:05:34+00:00","og_image":[{"width":708,"height":425,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce","datePublished":"2020-03-26T13:22:19+00:00","dateModified":"2020-03-27T09:05:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg","keywords":["antonio pompeo","Ciociaria","controlli","coronavirus","covid 19","emergenza","Frosinone","germano caperna","polizia provinciale","provincia"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/","name":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg","datePublished":"2020-03-26T13:22:19+00:00","dateModified":"2020-03-27T09:05:34+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/controlli-polizia-provinciale-1.jpg","width":708,"height":425,"caption":"Controlli della polizia provinciale sulle strade"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Controlli della polizia provinciale: 555 veicoli fermati e 4 denunce"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/26\/controlli-della-polizia-provinciale-555-veicoli-fermati-e-4-denunce\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=32021"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32021\/revisions"}],"predecessor-version":[{"id":32026,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/32021\/revisions\/32026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/32025"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=32021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=32021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=32021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}