{"id":31364,"date":"2020-03-20T09:27:52","date_gmt":"2020-03-20T08:27:52","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=31364"},"modified":"2020-03-20T09:56:48","modified_gmt":"2020-03-20T08:56:48","slug":"controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/","title":{"rendered":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dall\u2019inizio dell\u2019emergenza coronavirus <strong>sono state controllate in provincia di Frosinone 2.903 persone ed effettuate 1.126 verifiche negli esercizi pubblici<\/strong>. Denunciate dai carabinieri <strong>ben 191 persone, di cui 9 gestori di esercizi commerciali<\/strong>.\u00a0Inoltre, nella\u00a0giornata di gioved\u00ec, sono\u00a0state\u00a0<strong>deferite  altre 49 persone<\/strong>.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Casi particolari<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A  <strong>Ripi <\/strong> un ragazzo, per giustificarsi, ha affermato che stava andando dalla fidanzata per consegnarle una mascherina.  Una\u00a0<em>50<\/em>enne\u00a0di <strong>Ceccano<\/strong>, invece, venditrice di autovetture, ha riferito falsamente che avrebbe dovuto ritirare un veicolo, nonostante  la sua attivit\u00e0\u00a0risulti attualmente chiusa. Mentre a <strong>Guarcino<\/strong> \u00e8 stato denunciato  un 67enne, il quale,  fermato a bordo della propria auto con i suoi cani, ha dichiarato di voler andare in montagna per una fare passeggiata. Tutte scuse che i carabinieri hanno ritenuto non attendibili. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tutti le operazioni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>A Ferentino <\/strong>\u00e8 stato deferito un giovane di Supino; ad <strong>Anagni<\/strong> un uomo di Colleferro; a <strong>Frosinone<\/strong> tre giovani e una 72enne; a <strong>Supino<\/strong> tre ragazzi di Patrica; a <strong>Pofi <\/strong>un giovane di Amaseno; a <strong>Ripi <\/strong>6 persone; a <strong>Cassino <\/strong>due giovani del posto, a <strong>Sant\u2019Elia Fiumerapido<\/strong> 2 persone; a<strong> Cervaro<\/strong> due uomini; a <strong>Sant\u2019Ambrogio sul Garigliano<\/strong> quattro persone del posto; ad <strong>Alatri <\/strong>4 giovani della citt\u00e0, una 50enne di Ceccano nonch\u00e9 un 52enne e una 48enne entrambi di Boville Ernica; a<strong> Fiuggi<\/strong> sono stati denunciati un pakistano e un albanese residenti in citt\u00e0; a <strong>Trevi nel Lazio <\/strong>un 54enne di Fiuggi; <strong>a Guarcino<\/strong> un 67enne; a <strong>Veroli<\/strong> due uomini di Frosinone; ad <strong>Arce, Pontecorvo, Aquino e San Giorgio a Liri<\/strong> sono state denunciate 8 persone. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dall\u2019inizio dell\u2019emergenza coronavirus sono state controllate in provincia di Frosinone 2.903 persone ed effettuate 1.126 verifiche negli esercizi pubblici. Denunciate<\/p>\n","protected":false},"author":18,"featured_media":31365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[441,90,8896,8337,91,92,93,981,982],"class_list":["post-31364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-anagni","tag-carabinieri","tag-contagi","tag-coronavirus","tag-denunce","tag-ferentino","tag-frosinone","tag-supino","tag-veroli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Controlli per il coronavirus, ancora una raffica di denunce per scuse banali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali\" \/>\n<meta property=\"og:description\" content=\"Dall\u2019inizio dell\u2019emergenza coronavirus sono state controllate in provincia di Frosinone 2.903 persone ed effettuate 1.126 verifiche negli esercizi pubblici. Denunciate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T08:27:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-20T08:56:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1180\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali\",\"datePublished\":\"2020-03-20T08:27:52+00:00\",\"dateModified\":\"2020-03-20T08:56:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-carabinieri.jpg\",\"keywords\":[\"anagni\",\"carabinieri\",\"contagi\",\"coronavirus\",\"denunce\",\"ferentino\",\"Frosinone\",\"Supino\",\"Veroli\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/\",\"name\":\"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-carabinieri.jpg\",\"datePublished\":\"2020-03-20T08:27:52+00:00\",\"dateModified\":\"2020-03-20T08:56:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/coronavirus-carabinieri.jpg\",\"width\":1180,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/20\\\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/","og_locale":"it_IT","og_type":"article","og_title":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali","og_description":"Dall\u2019inizio dell\u2019emergenza coronavirus sono state controllate in provincia di Frosinone 2.903 persone ed effettuate 1.126 verifiche negli esercizi pubblici. Denunciate","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-20T08:27:52+00:00","article_modified_time":"2020-03-20T08:56:48+00:00","og_image":[{"width":1180,"height":900,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali","datePublished":"2020-03-20T08:27:52+00:00","dateModified":"2020-03-20T08:56:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg","keywords":["anagni","carabinieri","contagi","coronavirus","denunce","ferentino","Frosinone","Supino","Veroli"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/","name":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg","datePublished":"2020-03-20T08:27:52+00:00","dateModified":"2020-03-20T08:56:48+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/coronavirus-carabinieri.jpg","width":1180,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Controlli per il coronavirus, ancora una raffica di denunce per scuse banali"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/20\/controlli-per-il-coronavirus-ancora-una-raffica-di-denunce-per-scuse-banali\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=31364"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31364\/revisions"}],"predecessor-version":[{"id":31367,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31364\/revisions\/31367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/31365"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=31364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=31364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=31364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}