{"id":31020,"date":"2020-03-17T08:23:45","date_gmt":"2020-03-17T07:23:45","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=31020"},"modified":"2020-03-17T08:27:22","modified_gmt":"2020-03-17T07:27:22","slug":"coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/","title":{"rendered":"Coronavirus, Massaro: &#8220;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&#8221;."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>Le Autorit\u00e0 anzich\u00e9 darci indicazion<\/strong>i pratiche e chiarire le soluzioni che le nostre aziende devono adottare, oggi che si trovano sull\u2019orlo del baratro, con il recente Protocollo non hanno fatto altro che ricalcare in maniera generica e demagogica i principi del DPCM 12 marzo e quelli diramati dal sistema sanitario, sbilanciando ancora di pi\u00f9 in capo alle aziende la responsabilit\u00e0 di garantire condizioni di sicurezza nei luoghi di lavoro, attraverso prescrizioni inapplicabili, almeno in questo momento&#8221;. <strong>Cos\u00ec il cavalier Angelo Libero Massaro, presidente di Ance Frosinone. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"673\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance-1024x673.jpg\" alt=\"Massaro Ance Frosinone ciociaria infrastrutture il corriere della provincia\" class=\"wp-image-2754\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance-1024x673.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance-300x197.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance-768x505.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance-500x329.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/Massaro-Ance.jpg 1028w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Il cavalier Angelo Libero Massaro<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>E\u2019 emblematico in tal senso<\/strong> il richiamo del Protocollo sottoscritto dalle Parti Sociali nazionali, alla necessit\u00e0 di utilizzare le mascherine conformi, dispositivi che, come sanno tutti, oggi sono introvabili su mercato. Voglio evidenziare in particolare la problematica collegata al reperimento delle mascherine FFP2 poich\u00e9 trovo che sia rappresentativa della assurdit\u00e0 dei provvedimenti in commento&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Pare che le forniture di mascherine destinate all\u2019Italia siano state addirittura requisite<\/strong> <strong>da Paesi esteri <\/strong>e nessuno sa quando avremo una disponibilit\u00e0 adeguata di dispositivi di protezione individuale. E intanto le Parti Sociali nazionali, ribadisco, ci chiedono di garantire la sicurezza dei lavoratori, che lavorano a meno di un metro di distanza, come spesso avviene in cantiere, attraverso l\u2019utilizzo delle mascherine e degli altri dispositivi di protezione individuale classificati conformi&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;appello<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Non riusciamo ad acquistare mascherine per i nostri lavoratori <\/strong>e riusciamo a reperire soltanto dispositivi non conformi a prezzi che andrebbero denunciati alla Guardia di Finanza Il cantiere \u00e8 una unit\u00e0 produttiva complessa. Il lavoro \u00e8 una cosa seria. Quanto tempo ancora dobbiamo essere presi in giro? <strong>Qualcuno \u00e8 in grado di spiegarci<\/strong>, per esempio, come si applica il divieto di trasferta previsto dal Protocollo alle nostre aziende che stanno eseguendo appalti pubblici o privati in altre Regioni ovvero all\u2019interno delle zone rosse?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Assai problematica, sotto questo profilo, \u00e8 anche la gestione del trasporto dei lavoratori<\/strong> dalla sede aziendale all\u2019unit\u00e0 operativa di cantiere, considerando il fortissimo pendolarismo che caratterizza il nostro settore attraverso tutta Italia. Intanto i nostri committenti ci mettono in mora, furbescamente. Dobbiamo fare fronte agli impegni presi, ai mutui, al pagamento dei fornitori. Cosa accade alle nostre aziende se, nonostante le nostre segnalazioni, i committenti non dispongono la sospensione dei cantieri? Dovremmo diventare responsabili penalmente per la salute dei lavoratori, ovvero inadempimenti rispetto all\u2019obbligazione contrattuale originariamente assunta nei confronti della committenza?&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La problematica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Inoltre, a fronte della sospensione degli obblighi contributivi<\/strong> in scadenza \u00e8 necessario gestire i Documenti Unici di Regolarit\u00e0 Contributiva D.U.R.C., per evitare che, per effetto delle stesse agevolazioni, si ricevano DURC negativi. Personalmente propongo la proroga della validit\u00e0 dei DURC in scadenza per ulteriori quattro mesi. I nostri lavoratori, anche per tutelare se stessi e le proprie famiglie, in molti casi non sono pi\u00f9 disponibili a lavorare in queste condizioni e le aziende si fermano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Noi vogliamo tutelare i lavoratori e le nostre aziende<\/strong> ma non siamo disposti a diventare, per l\u2019ennesima volta, le vittime sacrificali.\u00a0 L\u2019edilizia non pagher\u00e0 il prezzo pi\u00f9 alto anche stavolta. Stiamo richiedendo dei pareri legali per fronteggiare le pretese di quei Committenti pubblici e privati pi\u00f9 attenti alle loro finanze che alla salute delle persone e del bene primario del Paese. Siamo pronti, se necessario, a chiudere tutto e procedere con ammortizzatori sociali e licenziamenti&#8221;.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Le Autorit\u00e0 anzich\u00e9 darci indicazioni pratiche e chiarire le soluzioni che le nostre aziende devono adottare, oggi che si trovano<\/p>\n","protected":false},"author":18,"featured_media":27447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[1003,2601,94,8337,788,93],"class_list":["post-31020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-ance","tag-angelo-libero-massaro","tag-ciociaria","tag-coronavirus","tag-edilizia","tag-frosinone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coronavirus, Massaro: &quot;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&quot;. - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, Massaro: &quot;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&quot;.\" \/>\n<meta property=\"og:description\" content=\"&#8220;Le Autorit\u00e0 anzich\u00e9 darci indicazioni pratiche e chiarire le soluzioni che le nostre aziende devono adottare, oggi che si trovano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T07:23:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T07:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"778\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Coronavirus, Massaro: &#8220;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&#8221;.\",\"datePublished\":\"2020-03-17T07:23:45+00:00\",\"dateModified\":\"2020-03-17T07:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/\"},\"wordCount\":561,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Cav.-Angelo-Libero-Massaro-1.jpg\",\"keywords\":[\"Ance\",\"angelo libero massaro\",\"Ciociaria\",\"coronavirus\",\"edilizia\",\"Frosinone\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/\",\"name\":\"Coronavirus, Massaro: \\\"Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata\\\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Cav.-Angelo-Libero-Massaro-1.jpg\",\"datePublished\":\"2020-03-17T07:23:45+00:00\",\"dateModified\":\"2020-03-17T07:27:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Cav.-Angelo-Libero-Massaro-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/01\\\/Cav.-Angelo-Libero-Massaro-1.jpg\",\"width\":778,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, Massaro: &#8220;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/17\\\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coronavirus, Massaro: \"Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, Massaro: \"Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata\".","og_description":"&#8220;Le Autorit\u00e0 anzich\u00e9 darci indicazioni pratiche e chiarire le soluzioni che le nostre aziende devono adottare, oggi che si trovano","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-17T07:23:45+00:00","article_modified_time":"2020-03-17T07:27:22+00:00","og_image":[{"width":778,"height":560,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Coronavirus, Massaro: &#8220;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&#8221;.","datePublished":"2020-03-17T07:23:45+00:00","dateModified":"2020-03-17T07:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/"},"wordCount":561,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg","keywords":["Ance","angelo libero massaro","Ciociaria","coronavirus","edilizia","Frosinone"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/","name":"Coronavirus, Massaro: \"Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata\". - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg","datePublished":"2020-03-17T07:23:45+00:00","dateModified":"2020-03-17T07:27:22+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/01\/Cav.-Angelo-Libero-Massaro-1.jpg","width":778,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, Massaro: &#8220;Normativa e protocollo delle parti sociali inaccettabili. Edilizia dimenticata&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/17\/coronavirus-massaro-normativa-e-protocollo-delle-parti-sociali-inaccettabili-edilizia-dimenticata\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=31020"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31020\/revisions"}],"predecessor-version":[{"id":31024,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/31020\/revisions\/31024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/27447"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=31020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=31020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=31020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}