{"id":30697,"date":"2020-03-13T16:42:48","date_gmt":"2020-03-13T15:42:48","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=30697"},"modified":"2020-03-14T16:03:21","modified_gmt":"2020-03-14T15:03:21","slug":"covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/","title":{"rendered":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Si \u00e8 tenuta la quotidiana videoconferenz<\/strong>a della task-force regionale per il COVID-19 con i direttori generali delle Asl, delle Aziende ospedaliere e dell\u2019ospedale pediatrico Bambino Ges\u00f9.   <strong>In provincia di Frosinone si registra anche il decesso di un 52enne<\/strong>  <\/p>\n\n\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento di D&#8217;Amato<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> \u201c <em>Ad oggi, come da ultimo&nbsp; bollettino, sono 200 i casi positivi al Covid-19. Abbiamo iniziato la&nbsp; settimana con 102, quindi c\u2019\u00e8 stato un progressivo incremento e ci&nbsp; aspettiamo un aumento nella giornata di ogg<\/em>i\u201d.  <em>Rispetto a ieri registriamo un aumento di 77 casi di positivit\u00e0, ma c\u2019\u00e8 anche un incremento delle persone guarite dal COVID-19 che sono 24. Escono dalla sorveglianza in 597, ovvero hanno terminato la quarantena. Ad oggi sono stati effettuati circa 6.500 tamponi per il COVID-19<\/em>\u201d ha commentato D\u2019Amato. <strong>In provincia di Frosinone si registra anche il decesso di un 52enne<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ad oggi, venerd\u00ec 13 marzo, la situazione<\/strong>&nbsp;nelle Asl e negli Ospedali del Lazio la situazione \u00e8 la seguente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>Asl di Frosinone<\/strong>&nbsp;\u2013 6 nuovi casi positivi, 4 legati alla RSA di Cassino che raggiungono cos\u00ec quota 7. Blocco delle accettazioni presso la RSA e indagine epidemiologica in collaborazione tra Asl Frosinone e SERESMI Spallanzani. 1 paziente \u00e8 guarito. Deceduto 1 paziente di 52 anni con grave patologia oncologica preesistente. 18 le persone che sono uscite dalla sorveglianza domiciliare. Possibilit\u00e0 di implementare la disponibilit\u00e0 di 2 posti di terapia intensiva; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 1<\/strong>&nbsp;\u2013 4 nuovi casi positivi. 104 le persone che sono uscite dalla sorveglianza domiciliare. Dal 17 marzo disponibili ulteriori 8 posti di pneumologia. Da marted\u00ec 17 marzo sar\u00e0 attivato il laboratorio per test COVID-19;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 2<\/strong>&nbsp;\u2013 20 nuovi casi positivi. 55 le persone che sono uscite dalla sorveglianza domiciliare. Deceduta una donna di 88 anni al Policlinico Casilino per shock settico e polmonite. Attivati 2 posti di terapia intensiva all\u2019Ospedale Pertini. Da mercoled\u00ec 18 marzo sar\u00e0 attivato il laboratorio per test COVID-19;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 3<\/strong>&nbsp;\u201316 nuovi casi positivi. 57 le persone che sono uscite dalla sorveglianza domiciliare;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 4<\/strong>&nbsp;\u2013 3 nuovi casi positivi. 80 le persone che sono uscite dalla sorveglianza domiciliare;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 5<\/strong>&nbsp;\u2013 3 nuovi casi positivi. 62 le persone che sono uscite dalla sorveglianza domiciliare. Dal 28 marzo disponibili ulteriori 10 posti di terapia intensiva;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl Roma 6<\/strong>&nbsp;\u2013 9 nuovi casi positivi. 92 le persone che sono uscite dalla sorveglianza domiciliare;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Latina<\/strong>&nbsp;\u2013 10 nuovi casi positivi. 49 le persone che sono uscite dalla sorveglianza domiciliare. Dal 23 marzo disponibili ulteriori 12 posti di terapia intensiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Viterbo<\/strong>&nbsp;\u2013 4 nuovi casi positivi. 64 le persone che sono uscite dalla sorveglianza domiciliare<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asl di Rieti<\/strong>&nbsp;\u2013 2 nuovi casi positivi. 16 le persone che sono uscite dalla sorveglianza domiciliare. Il 16 marzo saranno attivati ulteriori 11 posti di terapia intensiva per COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Umberto I<\/strong>&nbsp;\u2013 da luned\u00ec 16 marzo saranno disponibili ulteriori 26 posti di malattie infettive e ulteriori 8 di terapia intensiva;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera San Giovanni<\/strong>&nbsp;\u2013 da luned\u00ec 16 marzo saranno disponibili ulteriori 8 posti di terapia intensiva;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera Sant\u2019Andrea<\/strong>&nbsp;\u2013 possibilit\u00e0 di implementare 10 posti di terapia intensiva;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Gemelli<\/strong>&nbsp;\u2013 da luned\u00ec 16 marzo ulteriori 28 posti di malattie infettive e ulteriori 21 posti di terapia intensiva al COVID-19 2 Hospital Columbus;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ares 118<\/strong>&nbsp;\u2013 da questa mattina raddoppiate le postazioni del numero verde 800.118.800 dedicato al COVID-19. Attivato un settore dedicato al trasferimento dei pazienti COVID-19 tra i diversi presidi della rete ospedaliera regionale;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Policlinico Tor Vergata<\/strong>&nbsp;\u2013 da domani disponibili ulteriori 4 posti di terapia intensiva. Dal 16 marzo saranno disponibili ulteriori 16 posti di malattie infettive;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Azienda Ospedaliera San Camillo<\/strong>: luned\u00ec 16 marzo saranno attivati 3 posti di terapia intensiva;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ospedale Pediatrico Bambino Ges\u00f9<\/strong>: disponibili 16 posti di malattie infettive<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuta la quotidiana videoconferenza della task-force regionale per il COVID-19 con i direttori generali delle Asl, delle Aziende<\/p>\n","protected":false},"author":18,"featured_media":30702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[9004,94,8337,93,945,8885],"class_list":["post-30697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-52enne","tag-ciociaria","tag-coronavirus","tag-frosinone","tag-morto","tag-positivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 tenuta la quotidiana videoconferenza della task-force regionale per il COVID-19 con i direttori generali delle Asl, delle Aziende\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-13T15:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-14T15:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"591\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne\",\"datePublished\":\"2020-03-13T15:42:48+00:00\",\"dateModified\":\"2020-03-14T15:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/damato.jpg\",\"keywords\":[\"52enne\",\"Ciociaria\",\"coronavirus\",\"Frosinone\",\"Morto\",\"positivo\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/\",\"name\":\"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/damato.jpg\",\"datePublished\":\"2020-03-13T15:42:48+00:00\",\"dateModified\":\"2020-03-14T15:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/damato.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/damato.jpg\",\"width\":591,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/13\\\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/","og_locale":"it_IT","og_type":"article","og_title":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne","og_description":"Si \u00e8 tenuta la quotidiana videoconferenza della task-force regionale per il COVID-19 con i direttori generali delle Asl, delle Aziende","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-13T15:42:48+00:00","article_modified_time":"2020-03-14T15:03:21+00:00","og_image":[{"width":591,"height":394,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne","datePublished":"2020-03-13T15:42:48+00:00","dateModified":"2020-03-14T15:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg","keywords":["52enne","Ciociaria","coronavirus","Frosinone","Morto","positivo"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/","name":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg","datePublished":"2020-03-13T15:42:48+00:00","dateModified":"2020-03-14T15:03:21+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/03\/damato.jpg","width":591,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Covid 19, nel Lazio sono 200 i casi positivi: in Ciociaria morto un 52nne"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/13\/covid-19-nel-lazio-sono-200-i-casi-positivi-in-ciociaria-morto-un-52nne\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=30697"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30697\/revisions"}],"predecessor-version":[{"id":30703,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30697\/revisions\/30703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/30702"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=30697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=30697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=30697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}