{"id":30454,"date":"2020-03-11T11:15:19","date_gmt":"2020-03-11T10:15:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=30454"},"modified":"2020-03-11T15:52:08","modified_gmt":"2020-03-11T14:52:08","slug":"ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/","title":{"rendered":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La coalizione a sostegno della futura candidatura a Sindaco di Marco Corsi <\/strong>annuncia che la propria campagna elettorale, nello specifico ogni occasione di incontro e confronto con la cittadinanza, \u00e8 di fatto sospesa sino al termine dell\u2019emergenza epidemiologica da COVID-19.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La decisione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u2019ora in avanti, <\/strong>auspicando che la fase emergenziale rientri nel pi\u00f9 breve tempo possibile, gli esponenti della medesima coalizione contribuiranno principalmente alla divulgazione delle disposizioni e delle note informative che sono state e saranno emesse dal Governo, dalla Regione Lazio, dalla Asl e della Provincia di Frosinone, e dal Comune di Ceccano. Resta immutato, ovviamente, il nostro impegno civico nell\u2019esclusivo interesse della popolazione, promuovendo e sostenendo convintamente tutte le iniziative che possano aiutare a rendere meno complicato il periodo che noi tutti stiamo vivendo e vivremo nei prossimi giorni. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La richiesta <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In tal senso, con la forte condivisione di tutti gli esponenti della coalizione, <strong>Marco Corsi ha gi\u00e0 formalmente richiesto nella mattinata di ieri un incontro con il Commissario Straordinario del Comune<\/strong>, il Dott. Giuseppe Ranieri, e con il Sub Commissario Prefettizio, la Dott.ssa Stefania Galella, per poter discutere con loro la potenziale<strong> attivazione sul territorio comunale di un servizio di \u201cSpesa a domicilio\u201d<\/strong> (beni di prima necessit\u00e0, viveri e medicinali) a favore delle persone anziane che vivono da sole o hanno problemi di deambulazione, e delle persone affette da malattie croniche invalidanti o immunodepresse adeguatamente certificate. Vista la tematica della proposta, qualora tale servizio non sia stato gi\u00e0 previsto, tale riunione preliminare si terr\u00e0 possibilmente alla presenza dei Responsabili dei Settori comunali \u201cServizi Sociali\u201d e \u201cFinanziario\u201d. In attesa di un riscontro dal Palazzo Municipale, rivolgiamo alla collettivit\u00e0 un messaggio di incoraggiamento e sensibilizzazione all\u2019importanza delle misure da rispettare a fronte dell\u2019emergenza Coronavirus. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La coalizione a sostegno della futura candidatura a Sindaco di Marco Corsi annuncia che la propria campagna elettorale, nello specifico<\/p>\n","protected":false},"author":18,"featured_media":20505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[3447,524,80,93,6658,253,117],"class_list":["post-30454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-campagna-elettorale","tag-ceccano","tag-elezioni","tag-frosinone","tag-marco-corsi","tag-politica","tag-sindaco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale\" \/>\n<meta property=\"og:description\" content=\"La coalizione a sostegno della futura candidatura a Sindaco di Marco Corsi annuncia che la propria campagna elettorale, nello specifico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-11T10:15:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-11T14:52:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale\",\"datePublished\":\"2020-03-11T10:15:19+00:00\",\"dateModified\":\"2020-03-11T14:52:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/\"},\"wordCount\":302,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Marco-Corsi-1200x720.jpg\",\"keywords\":[\"campagna elettorale\",\"ceccano\",\"Elezioni\",\"Frosinone\",\"Marco Corsi\",\"politica\",\"Sindaco\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/\",\"name\":\"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Marco-Corsi-1200x720.jpg\",\"datePublished\":\"2020-03-11T10:15:19+00:00\",\"dateModified\":\"2020-03-11T14:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Marco-Corsi-1200x720.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Marco-Corsi-1200x720.jpg\",\"width\":1200,\"height\":720,\"caption\":\"Marco Corsi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/11\\\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/","og_locale":"it_IT","og_type":"article","og_title":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale","og_description":"La coalizione a sostegno della futura candidatura a Sindaco di Marco Corsi annuncia che la propria campagna elettorale, nello specifico","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-11T10:15:19+00:00","article_modified_time":"2020-03-11T14:52:08+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale","datePublished":"2020-03-11T10:15:19+00:00","dateModified":"2020-03-11T14:52:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/"},"wordCount":302,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg","keywords":["campagna elettorale","ceccano","Elezioni","Frosinone","Marco Corsi","politica","Sindaco"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/","name":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg","datePublished":"2020-03-11T10:15:19+00:00","dateModified":"2020-03-11T14:52:08+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/Marco-Corsi-1200x720.jpg","width":1200,"height":720,"caption":"Marco Corsi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ceccano, Covid19: la coalizione a sostegno di Corsi sospende la campagna elettorale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/11\/ceccano-covid19-la-coalizione-a-sostegno-di-corsi-sospende-la-campagna-elettorale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=30454"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30454\/revisions"}],"predecessor-version":[{"id":30456,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30454\/revisions\/30456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20505"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=30454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=30454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=30454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}