{"id":30229,"date":"2020-03-08T13:58:16","date_gmt":"2020-03-08T12:58:16","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=30229"},"modified":"2020-03-08T14:34:04","modified_gmt":"2020-03-08T13:34:04","slug":"covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/","title":{"rendered":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primo decesso in provincia di Frosinone per Covid-19. L&#8217;ufficialit\u00e0 \u00e8 arrivata pochi minuti fa dalla Asl di Frosinone: si tratta di un <strong>pazienze che era ricoverato all&#8217;ospedale Santa Scolastica di Cassino <\/strong>perch\u00e9 affetto da coronavirus. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;uomo, che <strong>aveva 75 anni<\/strong> e viveva in un paese del sud della provincia, era risultato positivo al tampone ed era stato ricoverato in ospedale dove <strong>gli era stata diagnosticata la polmonite<\/strong>. Questa notte \u00e8 deceduto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La nota della Asl<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Immmediatamente \u2013 fanno sapere dalla Asl &#8211; tutte le procedure e le precauzioni sono state messe in atto secondo le disposizioni regionali e della stessa Azienda Sanitaria ed \u00e8 stata attivata la sorveglianza epidemiologica&#8221;.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inoltre la Asl fa sapere che <strong>presso l\u2019ospedale Fabrizio Spaziani<\/strong> di Frosinone risultano sottoposti a terapia intensiva <strong>due pazienti risultati positivi al Covid 19.  <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primo decesso per coronavirus in Ciociaria: \u00e8 un 75enne ricorverato al Santa Scolastica di Cassino<\/p>\n","protected":false},"author":18,"featured_media":3709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2],"tags":[108,216,94,8722,8904,1481,93,8905,1334,8898],"class_list":["post-30229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-cronaca","tag-asl","tag-cassino","tag-ciociaria","tag-covid-19","tag-decesso","tag-fabrizio-spaziani","tag-frosinone","tag-polmonite","tag-santa-scolastica","tag-tampone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani\" \/>\n<meta property=\"og:description\" content=\"Primo decesso per coronavirus in Ciociaria: \u00e8 un 75enne ricorverato al Santa Scolastica di Cassino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-08T12:58:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-08T13:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani\",\"datePublished\":\"2020-03-08T12:58:16+00:00\",\"dateModified\":\"2020-03-08T13:34:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/\"},\"wordCount\":143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"keywords\":[\"Asl\",\"Cassino\",\"Ciociaria\",\"covid 19\",\"decesso\",\"fabrizio spaziani\",\"Frosinone\",\"polmonite\",\"santa scolastica\",\"tampone\"],\"articleSection\":[\"*SLIDE*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/\",\"name\":\"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"datePublished\":\"2020-03-08T12:58:16+00:00\",\"dateModified\":\"2020-03-08T13:34:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/ospedale-cassino-e1545410069802.jpg\",\"width\":632,\"height\":352,\"caption\":\"L'ospedale Santa Scolastica di Cassino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/03\\\/08\\\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/","og_locale":"it_IT","og_type":"article","og_title":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani","og_description":"Primo decesso per coronavirus in Ciociaria: \u00e8 un 75enne ricorverato al Santa Scolastica di Cassino","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-03-08T12:58:16+00:00","article_modified_time":"2020-03-08T13:34:04+00:00","og_image":[{"width":632,"height":352,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani","datePublished":"2020-03-08T12:58:16+00:00","dateModified":"2020-03-08T13:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/"},"wordCount":143,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","keywords":["Asl","Cassino","Ciociaria","covid 19","decesso","fabrizio spaziani","Frosinone","polmonite","santa scolastica","tampone"],"articleSection":["*SLIDE*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/","name":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","datePublished":"2020-03-08T12:58:16+00:00","dateModified":"2020-03-08T13:34:04+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/ospedale-cassino-e1545410069802.jpg","width":632,"height":352,"caption":"L'ospedale Santa Scolastica di Cassino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Covid-19, \u00e8 ufficiale: primo decesso a Cassino. Due in terapia intensiva allo Spaziani"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/03\/08\/covid-19-e-ufficiale-primo-decesso-a-cassino-due-in-terapia-intensiva-allo-spaziani\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=30229"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30229\/revisions"}],"predecessor-version":[{"id":30235,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/30229\/revisions\/30235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3709"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=30229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=30229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=30229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}