{"id":29656,"date":"2020-02-29T14:29:55","date_gmt":"2020-02-29T13:29:55","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=29656"},"modified":"2020-02-29T14:29:58","modified_gmt":"2020-02-29T13:29:58","slug":"truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/","title":{"rendered":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#8217;Elia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nell\u2019ambito delle iniziative intraprese dal <strong>Comando Provinciale dei Carabinieri di Frosinone <\/strong>connesse al fenomeno dei reati predatori, e in particolare delle truffe a danno di anziani, il <strong>comandante della Compagnia di Cassino, capitano Ivan Mastromanno<\/strong>, insieme al comandante della stazione carabinieri, ha tenuto un incontro al circolo pensionati di via Pietro Bembo. Erano presenti <strong>un&#8217;ottantina di anziani<\/strong> e il presidente del circolo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tappa\nanche a Sant&#8217;Elia Fiumerapido<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Analogo incontro si \u00e8 tenuto presso la<strong> sala polifunzionale del Comune di Sant\u2019Elia Fiumerapido<\/strong>, alla presenza di circa 40 persone tra giovani e anziani, del <strong>sindaco Roberto Angelosanto<\/strong>, parte dell\u2019amministrazione comunale, una <strong>rappresentanza della locale Associazione Nazionale Carabinieri <\/strong>e della <strong>Protezione Civile.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il\ntema degli incontri<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;ufficiale ha illustrato ai presenti le numerose tipologie di truffe che pi\u00f9 frequentemente vengono perpetrate a danno degli anziani, in particolare quella del <strong>falso avvocato<\/strong>; dei carabinieri che hanno arrestato qualche familiare a seguito di sinistro stradale; dei <strong>falsi funzionari pubblici o rappresentanti di societ\u00e0 erogatrici di energia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A tutti i presenti \u00e8 stato raccomandato di diffidare da telefonante ricevute da persone che rappresentano le situazioni sopra descritte, di evitare di farli accedere in casa propria non consegnando mai danaro, oro e\/o gioielli e di contattare immediatamente il numero di emergenza 112, raccontando all\u2019operatore quanto accaduto.  Al termine dell\u2019incontro diverse sono state le domande rivolte al capitano da parte della folta platea.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono svolti nei giorni scorsi due incontri a Cassino e a Sant&#8217;Elia Fiumerapido tenuti dai carabinieri sulle truffe ai danni degli anziani<\/p>\n","protected":false},"author":18,"featured_media":29659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[322,1408,8769,90,216,2553,93,2254,8770,5767,1074,8298],"class_list":["post-29656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-amministrazione","tag-anziani","tag-capitano","tag-carabinieri","tag-cassino","tag-centro","tag-frosinone","tag-incontri","tag-ivan-mastromanno","tag-roberto-angelosanto","tag-santelia","tag-truffe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#039;Elia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#039;Elia\" \/>\n<meta property=\"og:description\" content=\"Si sono svolti nei giorni scorsi due incontri a Cassino e a Sant&#039;Elia Fiumerapido tenuti dai carabinieri sulle truffe ai danni degli anziani\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-29T13:29:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-29T13:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"713\" \/>\n\t<meta property=\"og:image:height\" content=\"374\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#8217;Elia\",\"datePublished\":\"2020-02-29T13:29:55+00:00\",\"dateModified\":\"2020-02-29T13:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/incontro-cc-santelia.jpg\",\"keywords\":[\"amministrazione\",\"anziani\",\"capitano\",\"carabinieri\",\"Cassino\",\"centro\",\"Frosinone\",\"incontri\",\"ivan mastromanno\",\"Roberto Angelosanto\",\"sant'elia\",\"truffe\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/\",\"name\":\"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant'Elia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/incontro-cc-santelia.jpg\",\"datePublished\":\"2020-02-29T13:29:55+00:00\",\"dateModified\":\"2020-02-29T13:29:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/incontro-cc-santelia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/incontro-cc-santelia.jpg\",\"width\":713,\"height\":374,\"caption\":\"Un momento dell'incontro con i carabinieri a Sant'Elia Fiumerapido\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#8217;Elia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/29\\\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant'Elia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/","og_locale":"it_IT","og_type":"article","og_title":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant'Elia","og_description":"Si sono svolti nei giorni scorsi due incontri a Cassino e a Sant'Elia Fiumerapido tenuti dai carabinieri sulle truffe ai danni degli anziani","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-02-29T13:29:55+00:00","article_modified_time":"2020-02-29T13:29:58+00:00","og_image":[{"width":713,"height":374,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#8217;Elia","datePublished":"2020-02-29T13:29:55+00:00","dateModified":"2020-02-29T13:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg","keywords":["amministrazione","anziani","capitano","carabinieri","Cassino","centro","Frosinone","incontri","ivan mastromanno","Roberto Angelosanto","sant'elia","truffe"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/","name":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant'Elia - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg","datePublished":"2020-02-29T13:29:55+00:00","dateModified":"2020-02-29T13:29:58+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/incontro-cc-santelia.jpg","width":713,"height":374,"caption":"Un momento dell'incontro con i carabinieri a Sant'Elia Fiumerapido"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Truffe agli anziani: incontri dei carabinieri a Cassino e a Sant&#8217;Elia"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/29\/truffe-agli-anziani-incontri-dei-carabinieri-a-cassino-e-a-santelia\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=29656"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29656\/revisions"}],"predecessor-version":[{"id":29660,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29656\/revisions\/29660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/29659"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=29656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=29656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=29656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}