{"id":29413,"date":"2020-02-26T12:29:55","date_gmt":"2020-02-26T11:29:55","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=29413"},"modified":"2020-02-26T12:29:59","modified_gmt":"2020-02-26T11:29:59","slug":"concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/","title":{"rendered":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il fascino di una vettura d\u2019epoca \u00e8 esclusivo e ineguagliabile. Per preservarne il valore storico, sociale e culturale e diffonderlo alle nuove generazioni, il presidente dell\u2019<strong>Associazione Culturale Motorismo Storico e della Federazione Veicoli d\u2019Epoca<\/strong>, dottor <strong>Corrado Collalti<\/strong>, insieme all\u2019Arneo Veicoli Storici e con il <strong>patrocinio dell\u2019Amministrazione Provinciale<\/strong>, ha messo in campo un\u2019iniziativa riservata agli studenti dell\u2019<strong>Accademia di Belle Arti di Frosinone<\/strong>, istituzione con cui si \u00e8 avviato un rapporto di collaborazione. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"668\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Marignani-Collalti-Rea.jpg\" alt=\"marignani collalti rea il corriere della provincia\" class=\"wp-image-29417\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Marignani-Collalti-Rea.jpg 717w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Marignani-Collalti-Rea-300x279.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Marignani-Collalti-Rea-500x466.jpg 500w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><figcaption>Da sinistra Marignani, Collalti e Rea<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In attesa di esaminare le opere, diversi ragazzi dell\u2019Accademia hanno avuto modo di visitare, nei giorni scorsi, la Collezione Marignani, che raccoglie straordinarie vetture d\u2019epoca. Accompagnati dalla <strong>direttrice dell\u2019Accademia Loredana Rea<\/strong> e dal presidente dell\u2019Associazione Culturale Motorismo Storico e della Federazione Veicoli d\u2019Epoca, Corrado Collalti, gli studenti sono stati ricevuti dalla signora Marignani e hanno avuto la possibilit\u00e0 di osservare da vicino le bellissime automobili.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il concorso<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 stata bandita la prima edizione di un concorso che prevede l\u2019assegnazione di <strong>6 borse di studio da 500\u00a0euro ciascuna<\/strong>, con l\u2019intento di coinvolgere i pi\u00f9 giovani nella realizzazione di un progetto creativo che, utilizzando i linguaggi della pittura, della scultura e del design, possa stimolare una riflessione sull&#8217;importanza di indirizzare l\u2019attenzione delle nuove generazioni su particolari e rari veicoli d\u2019epoca progettati e costruiti in Italia, intesi come espressione di una creativit\u00e0 e di una cifra stilistica riconosciuta nel mondo intero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"674\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-3.jpg\" alt=\"marignani studenti accademia il corriere della provincia\" class=\"wp-image-29416\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-3.jpg 646w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-3-288x300.jpg 288w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-3-500x522.jpg 500w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><figcaption>Gli studenti dell&#8217;Accademia in visita alla Collezione Marignani<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La commissione esaminatrice \u00e8 cos\u00ec composta: presidente professoressa <strong>Loredana Rea<\/strong>, architetto <strong>Corrado Lopresto<\/strong>, avvocato <strong>Giuseppe Dell\u2019Aversano<\/strong>, dottor <strong>Luigi Marignani<\/strong>, professoressa<strong> Eleonora Pusceddu<\/strong>, dottor <strong>Antonio Italo Pisan\u00f2<\/strong>, dottor <strong>Corrado Collalti<\/strong>, dottor <strong>Luca Gastaldi<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alla <strong>cerimonia di premiazione<\/strong>, in programma il <strong>prossimo 19 di aprile alle ore 10,<\/strong> presso il <strong>Salone di Rappresentanza del Palazzo dell\u2019Amministrazione Provinciale di Frosinone<\/strong>, sar\u00e0 presente l\u2019architetto Corrado Lopresto, collezionista di veicoli storici e d\u2019epoca pi\u00f9 importante ed apprezzato sia a livello nazionale che internazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli studenti dell&#8217;Accademia di Belle Arti di Frosinone hanno visitato la collezione di auto storiche Marignani in vista del concorso<\/p>\n","protected":false},"author":18,"featured_media":29414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[340,5459,94,8731,143,93,4156,379],"class_list":["post-29413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-accademia","tag-belle-arti","tag-ciociaria","tag-collezione-marignani","tag-concorso","tag-frosinone","tag-loredana-rea","tag-studenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani\" \/>\n<meta property=\"og:description\" content=\"Gli studenti dell&#039;Accademia di Belle Arti di Frosinone hanno visitato la collezione di auto storiche Marignani in vista del concorso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T11:29:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T11:29:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"861\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani\",\"datePublished\":\"2020-02-26T11:29:55+00:00\",\"dateModified\":\"2020-02-26T11:29:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/\"},\"wordCount\":337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Collezione-Marignani-1.jpg\",\"keywords\":[\"accademia\",\"belle arti\",\"Ciociaria\",\"collezione marignani\",\"concorso\",\"Frosinone\",\"Loredana Rea\",\"studenti\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/\",\"name\":\"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Collezione-Marignani-1.jpg\",\"datePublished\":\"2020-02-26T11:29:55+00:00\",\"dateModified\":\"2020-02-26T11:29:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Collezione-Marignani-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Collezione-Marignani-1.jpg\",\"width\":861,\"height\":600,\"caption\":\"Studenti dell'Accademia di Belle Arti in visita alla Collezione Marignani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/26\\\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/","og_locale":"it_IT","og_type":"article","og_title":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani","og_description":"Gli studenti dell'Accademia di Belle Arti di Frosinone hanno visitato la collezione di auto storiche Marignani in vista del concorso","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-02-26T11:29:55+00:00","article_modified_time":"2020-02-26T11:29:59+00:00","og_image":[{"width":861,"height":600,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani","datePublished":"2020-02-26T11:29:55+00:00","dateModified":"2020-02-26T11:29:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/"},"wordCount":337,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg","keywords":["accademia","belle arti","Ciociaria","collezione marignani","concorso","Frosinone","Loredana Rea","studenti"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/","name":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg","datePublished":"2020-02-26T11:29:55+00:00","dateModified":"2020-02-26T11:29:59+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Collezione-Marignani-1.jpg","width":861,"height":600,"caption":"Studenti dell'Accademia di Belle Arti in visita alla Collezione Marignani"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Concorso auto storiche: studenti dell\u2019Accademia in visita alla Collezione Marignani"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/26\/concorso-auto-storiche-studenti-dellaccademia-in-visita-alla-collezione-marignani\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=29413"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29413\/revisions"}],"predecessor-version":[{"id":29418,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/29413\/revisions\/29418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/29414"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=29413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=29413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=29413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}