{"id":28310,"date":"2020-02-07T16:09:20","date_gmt":"2020-02-07T15:09:20","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=28310"},"modified":"2020-02-07T16:16:13","modified_gmt":"2020-02-07T15:16:13","slug":"venturi-il-grande-capoluogo-e-unopportunita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/","title":{"rendered":"Venturi: &#8220;il grande capoluogo \u00e8 un&#8217;opportunit\u00e0. Ottaviani non sia timido&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> \u201cIl progetto del Grande Capoluogo \u00e8 un\u2019opportunit\u00e0 da non perdere, il sindaco Nicola  Ottaviani non sia \u201ctimido\u201d. Ci sarebbero vantaggi enormi, per esempio nel contrasto all\u2019inquinamento\u201d. <strong>Lo evidenzia Norbero Venturi, consigliere comunale di Frosinone. <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"403\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/nicola-ottaviani-roma-e1554740208411.jpg\" alt=\"nicola ottaviani sindaco frosinone il corriere della provincia\" class=\"wp-image-9550\" \/><figcaption>Il sindaco di Frosinone Nicola Ottaviani<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;intervento<br> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Meno timidezza sul progetto del Grande Capoluogo,  che pu\u00f2 davvero rappresentare una possibilit\u00e0  concreta di rilancio, <\/strong>perfino culturale, del territorio. Il  31 luglio 2019 il consiglio comunale di Frosinone ha  approvato una manifestazione di interesse per un  progetto, quello dell\u2019Unione dei Comuni, che  costituisce una piattaforma importante di dibattito e di organizzazione. Perch\u00e9 ha un\u2019impostazione solidaristica e \u201ccooperativistica\u201d che non snatura  l\u2019identit\u00e0 storica e territoriale dei singoli Comuni. Da  luglio per\u00f2 non \u00e8 stato compiuto nessun altro atto pratico. Oggi si fatica a capire quali Comuni sono interessati davvero. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bene ha fatto il presidente di  Unindustria Frosinone Giovanni Turriziani a chiedere  ai Comuni di prendere l\u2019iniziativa.<\/strong> Se vogliono naturalmente. E visto che il Comune capoluogo \u00e8 \u201cnaturalmente\u201d il  capofila, dovrebbe a mio avviso passare dalla manifestazione di interesse generale ad un  coinvolgimento specifico e particolare. Utilizzando i vantaggi che questo tipo di aggregazione assicura.  Invece ho riscontrato da parte del sindaco Nicola  Ottaviani una sorta di timidezza politica ed amministrativa che peraltro non fa parte del modo con il quale interpreta il ruolo&#8221;. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"356\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/12\/Giovanni-Turriziani-Unindustria-e1578657823805.jpg\" alt=\"unindustria presidente giovanni turriziani il corriere della provincia\" class=\"wp-image-24969\" \/><figcaption>Il presidente di Unindustria Giovanni Turriziani<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;appello<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Per me dovrebbe  accelerare il processo. Il progetto del Grande Capoluogo avrebbe dei <strong>vantaggi enormi e decisivi  nelle politiche di contrasto all\u2019inquinamento,<\/strong> a cominciare da quello determinato dalle polveri sottili. Per questo motivo mi permetto di invitare il sindaco  Ottaviani ad essere pi\u00f9 dinamico su questa iniziativa. Indipendentemente da chi l\u2019ha promossa. Se poi invece ha dubbi e remore, che il mio  ottimismo non riesce a vedere, con il coraggio che  non gli ha mai difettato, apra al pi\u00f9 presto un  confronto in consiglio comunale&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;opportunit\u00e0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> &#8220;Sinceramente penso che su un progetto del genere<strong>  l\u2019intero consiglio comunale avrebbe il sostegno della cittadinanza ma anche di enti<\/strong> e associazioni che a vario titolo sarebbero interessati ad avere un bacino pi\u00f9 ampio sul quale ragionare e confrontarsi. Un\u2019iniziativa del genere rafforzerebbe e rilancerebbe un territorio altrimenti destinato alla marginalizzazione.  Qui non si tratta affatto di annullare individualit\u00e0 e competenze dei singoli Comuni. Nello studio di Unindustria non c\u2019\u00e8 neppure una virgola che lascia intravedere questo. Non c\u2019\u00e8 chi non vede invece i vantaggio di una gestione condivisa su temi come la mobilit\u00e0, la lotta all\u2019inquinamento,il trasporto pubblico locale. Intanto per le misure adottate che sarebbero pi\u00f9 efficaci. Ma anche per il risparmio dei costi, considerando che oggi tutti i Comuni sono alle prese con problemi derivanti dalla mancanza di  risorse e di personale&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;appello<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Lo studio elaborato disegna  una citt\u00e0 metropolitana di 150.000 abitanti <\/strong>su una superficie di 487 chilometri quadrati.. Il territorio ne beneficerebbe in termini di maggiore competitivit\u00e0, di accesso ai fondi europei, di aumento della rappresentativit\u00e0 ad ogni livello. Si pu\u00f2 fare. Il sindaco Nicola Ottaviani vinca l\u2019inusuale  timidezza politica e amministrativa&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il consigliere comunale invita il primo cittadino a dare vita al progetto<\/p>\n","protected":false},"author":18,"featured_media":15488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[94,93,4495,639,8500],"class_list":["post-28310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-ciociaria","tag-frosinone","tag-grande-capoluogo","tag-nicola-ottaviani","tag-venturi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Venturi: &quot;il grande capoluogo \u00e8 un&#039;opportunit\u00e0. Ottaviani non sia timido&quot; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venturi: &quot;il grande capoluogo \u00e8 un&#039;opportunit\u00e0. Ottaviani non sia timido&quot;\" \/>\n<meta property=\"og:description\" content=\"Il consigliere comunale invita il primo cittadino a dare vita al progetto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-07T15:09:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-07T15:16:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"345\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Venturi: &#8220;il grande capoluogo \u00e8 un&#8217;opportunit\u00e0. Ottaviani non sia timido&#8221;\",\"datePublished\":\"2020-02-07T15:09:20+00:00\",\"dateModified\":\"2020-02-07T15:16:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/norberto-venturi-e1563886169465.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"Grande capoluogo\",\"nicola ottaviani\",\"venturi\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/\",\"name\":\"Venturi: \\\"il grande capoluogo \u00e8 un'opportunit\u00e0. Ottaviani non sia timido\\\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/norberto-venturi-e1563886169465.jpg\",\"datePublished\":\"2020-02-07T15:09:20+00:00\",\"dateModified\":\"2020-02-07T15:16:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/norberto-venturi-e1563886169465.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/07\\\/norberto-venturi-e1563886169465.jpg\",\"width\":632,\"height\":345,\"caption\":\"Il consigliere comunale del Pd Norberto Venturi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venturi: &#8220;il grande capoluogo \u00e8 un&#8217;opportunit\u00e0. Ottaviani non sia timido&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2020\\\/02\\\/07\\\/venturi-il-grande-capoluogo-e-unopportunita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Venturi: \"il grande capoluogo \u00e8 un'opportunit\u00e0. Ottaviani non sia timido\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/","og_locale":"it_IT","og_type":"article","og_title":"Venturi: \"il grande capoluogo \u00e8 un'opportunit\u00e0. Ottaviani non sia timido\"","og_description":"Il consigliere comunale invita il primo cittadino a dare vita al progetto","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2020-02-07T15:09:20+00:00","article_modified_time":"2020-02-07T15:16:13+00:00","og_image":[{"width":632,"height":345,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Venturi: &#8220;il grande capoluogo \u00e8 un&#8217;opportunit\u00e0. Ottaviani non sia timido&#8221;","datePublished":"2020-02-07T15:09:20+00:00","dateModified":"2020-02-07T15:16:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg","keywords":["Ciociaria","Frosinone","Grande capoluogo","nicola ottaviani","venturi"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/","name":"Venturi: \"il grande capoluogo \u00e8 un'opportunit\u00e0. Ottaviani non sia timido\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg","datePublished":"2020-02-07T15:09:20+00:00","dateModified":"2020-02-07T15:16:13+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/07\/norberto-venturi-e1563886169465.jpg","width":632,"height":345,"caption":"Il consigliere comunale del Pd Norberto Venturi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Venturi: &#8220;il grande capoluogo \u00e8 un&#8217;opportunit\u00e0. Ottaviani non sia timido&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2020\/02\/07\/venturi-il-grande-capoluogo-e-unopportunita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/28310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=28310"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/28310\/revisions"}],"predecessor-version":[{"id":28315,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/28310\/revisions\/28315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/15488"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=28310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=28310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=28310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}